{"id":16545,"date":"2013-10-01T00:00:00","date_gmt":"2013-10-01T04:00:00","guid":{"rendered":"https:\/\/frenchdistrict.com\/boston\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/"},"modified":"2020-08-17T14:46:43","modified_gmt":"2020-08-17T18:46:43","slug":"cadres-chef-entreprise-solitude-coaching-professionnel-conseil","status":"publish","type":"post","link":"https:\/\/frenchdistrict.com\/boston\/articles\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil\/","title":{"rendered":"\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?"},"content":{"rendered":"<h2>Comparaison avec le golf, sport individuel par excellence :<\/h2>\n<ol>\n<li><strong>La responsabilit\u00e9 du caddie\u00a0:<\/strong> fournir au golfeur toutes les informations indispensables pour effectuer le meilleur coup : les distances, la condition des greens, l\u2019environnement, le club. Remettre en question les id\u00e9es sans imposer les choix.<\/li>\n<li><strong>La responsabilit\u00e9 du golfeur :<\/strong>\u00a0d\u00e9cider du choix ultime du club et effectuer le swing final.<\/li>\n<\/ol>\n<p>Dans cet esprit, voici 3 conseils pratiques :<\/p>\n<ul>\n<li>Accepter la contradiction sans jugement<\/li>\n<li>Valoriser la remont\u00e9e d\u2019information<\/li>\n<li>S\u2019appuyer sur une personne de confiance non impliqu\u00e9e dans la marche des affaires.<\/li>\n<\/ul>\n<p>Vous pouvez <a href=\"https:\/\/frenchdistrict.com\/annuaire-pro\/coach-professionnel-personnel\/\">faire appel \u00e0 un coach<\/a>, dont le r\u00f4le est d\u2019\u00eatre ce partenaire d\u2019exp\u00e9rience, de toute confiance, objectif, honn\u00eate et impartial qui vous remet en question et vous challenge en toute confidentialit\u00e9, et qui reste en contact avec vous, o\u00f9 que vous soyez, dans le monde entier.<\/p>\n<h2>Vous n\u2019\u00eates plus seul, vous allez par cons\u00e9quent :<\/h2>\n<ul>\n<li>Prendre vos d\u00e9cisions plus rapidement sans l\u2019ombre d\u2019un doute ;<\/li>\n<li>Augmenter votre niveau de confiance ;<\/li>\n<li>R\u00e9duire votre niveau de stress ;<\/li>\n<li>Am\u00e9liorer le niveau d\u2019engagement de vos <a href=\"https:\/\/frenchdistrict.com\/articles\/travailler-etats-unis-trouver-emploi-usa-visa-travail\/\">employ\u00e9s<\/a> ;<\/li>\n<li>Vous d\u00e9velopper professionnellement gr\u00e2ce \u00e0 de meilleures d\u00e9cisions.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Comparaison avec le golf, sport individuel par excellence : La responsabilit\u00e9 du caddie\u00a0: fournir au golfeur toutes les informations indispensables pour effectuer le meilleur coup : les distances, la condition des greens, l\u2019environnement, le club. Remettre en question les id\u00e9es sans imposer les choix. La responsabilit\u00e9 du golfeur :\u00a0d\u00e9cider du choix ultime du club et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":70408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[487,1587,273],"tags":[1161,1162],"class_list":["post-16545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entreprendre","category-sante-etats-unis","category-conseils-de-pros","tag-bernard-foure","tag-bgf-coaching"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?<\/title>\n<meta name=\"description\" content=\"Bien qu\u2019ils soient entour\u00e9s d\u2019amis, de partenaires, il s\u2019av\u00e8re que les chefs d\u2019entreprises et les cadres sont confront\u00e9s \u00e0 une forme de solitude.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?\" \/>\n<meta property=\"og:description\" content=\"Bien qu\u2019ils soient entour\u00e9s d\u2019amis, de partenaires, il s\u2019av\u00e8re que les chefs d\u2019entreprises et les cadres sont confront\u00e9s \u00e0 une forme de solitude.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/\" \/>\n<meta property=\"og:site_name\" content=\"Boston\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frenchdistrict\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-01T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-17T18:46:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchdistrict.com\/boston\/wp-content\/uploads\/sites\/8\/2020\/08\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1101\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"French District\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:site\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"French District\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/articles\\\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil\\\/\"},\"author\":{\"name\":\"French District\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"headline\":\"\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?\",\"datePublished\":\"2013-10-01T04:00:00+00:00\",\"dateModified\":\"2020-08-17T18:46:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/articles\\\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil\\\/\"},\"wordCount\":211,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2020\\\/08\\\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une.jpg\",\"keywords\":[\"Bernard Four\u00e9\",\"BGF coaching\"],\"articleSection\":[\"Entreprise\",\"Sant\u00e9\",\"Travail\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/articles\\\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil\\\/\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\\\/\",\"name\":\"\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2020\\\/08\\\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une.jpg\",\"datePublished\":\"2013-10-01T04:00:00+00:00\",\"dateModified\":\"2020-08-17T18:46:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"description\":\"Bien qu\u2019ils soient entour\u00e9s d\u2019amis, de partenaires, il s\u2019av\u00e8re que les chefs d\u2019entreprises et les cadres sont confront\u00e9s \u00e0 une forme de solitude.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2020\\\/08\\\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une.jpg\",\"contentUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2020\\\/08\\\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une.jpg\",\"width\":1600,\"height\":1101,\"caption\":\"cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Boston\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"station de ski\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/tag\\\/station-de-ski\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/#website\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/\",\"name\":\"Boston\",\"description\":\"Le meilleur de &lt;span&gt;Boston&lt;\\\/span&gt; par ceux qui y vivent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/boston\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\",\"name\":\"French District\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"caption\":\"French District\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?","description":"Bien qu\u2019ils soient entour\u00e9s d\u2019amis, de partenaires, il s\u2019av\u00e8re que les chefs d\u2019entreprises et les cadres sont confront\u00e9s \u00e0 une forme de solitude.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?","og_description":"Bien qu\u2019ils soient entour\u00e9s d\u2019amis, de partenaires, il s\u2019av\u00e8re que les chefs d\u2019entreprises et les cadres sont confront\u00e9s \u00e0 une forme de solitude.","og_url":"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/","og_site_name":"Boston","article_publisher":"https:\/\/www.facebook.com\/frenchdistrict","article_published_time":"2013-10-01T04:00:00+00:00","article_modified_time":"2020-08-17T18:46:43+00:00","og_image":[{"width":1600,"height":1101,"url":"https:\/\/frenchdistrict.com\/boston\/wp-content\/uploads\/sites\/8\/2020\/08\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une.jpg","type":"image\/jpeg"}],"author":"French District","twitter_card":"summary_large_image","twitter_creator":"@frenchdistrict","twitter_site":"@frenchdistrict","twitter_misc":{"\u00c9crit par":"French District","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/#article","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/boston\/articles\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil\/"},"author":{"name":"French District","@id":"https:\/\/frenchdistrict.com\/boston\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"headline":"\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?","datePublished":"2013-10-01T04:00:00+00:00","dateModified":"2020-08-17T18:46:43+00:00","mainEntityOfPage":{"@id":"https:\/\/frenchdistrict.com\/boston\/articles\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil\/"},"wordCount":211,"commentCount":0,"image":{"@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/boston\/wp-content\/uploads\/sites\/8\/2020\/08\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une.jpg","keywords":["Bernard Four\u00e9","BGF coaching"],"articleSection":["Entreprise","Sant\u00e9","Travail"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/frenchdistrict.com\/boston\/articles\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil\/","url":"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/","name":"\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/boston\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/#primaryimage"},"image":{"@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/boston\/wp-content\/uploads\/sites\/8\/2020\/08\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une.jpg","datePublished":"2013-10-01T04:00:00+00:00","dateModified":"2020-08-17T18:46:43+00:00","author":{"@id":"https:\/\/frenchdistrict.com\/boston\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"description":"Bien qu\u2019ils soient entour\u00e9s d\u2019amis, de partenaires, il s\u2019av\u00e8re que les chefs d\u2019entreprises et les cadres sont confront\u00e9s \u00e0 une forme de solitude.","breadcrumb":{"@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/#primaryimage","url":"https:\/\/frenchdistrict.com\/boston\/wp-content\/uploads\/sites\/8\/2020\/08\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une.jpg","contentUrl":"https:\/\/frenchdistrict.com\/boston\/wp-content\/uploads\/sites\/8\/2020\/08\/cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une.jpg","width":1600,"height":1101,"caption":"cadres-chef-entreprise-solitude-coaching-professionnel-conseil-une"},{"@type":"BreadcrumbList","@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/coach-professionnel-bgf-coaching-aide-cadres-chef-entreprise-conseil-bernard-foure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Boston","item":"https:\/\/frenchdistrict.com\/boston\/"},{"@type":"ListItem","position":2,"name":"station de ski","item":"https:\/\/frenchdistrict.com\/boston\/tag\/station-de-ski\/"},{"@type":"ListItem","position":3,"name":"\u00catre chef d\u2019entreprise et se sentir seul : comment faire face \u00e0 ce d\u00e9fi ?"}]},{"@type":"WebSite","@id":"https:\/\/frenchdistrict.com\/boston\/#website","url":"https:\/\/frenchdistrict.com\/boston\/","name":"Boston","description":"Le meilleur de &lt;span&gt;Boston&lt;\/span&gt; par ceux qui y vivent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchdistrict.com\/boston\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/frenchdistrict.com\/boston\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010","name":"French District","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","caption":"French District"}}]}},"_links":{"self":[{"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/posts\/16545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/comments?post=16545"}],"version-history":[{"count":5,"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/posts\/16545\/revisions"}],"predecessor-version":[{"id":46393,"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/posts\/16545\/revisions\/46393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/media\/70408"}],"wp:attachment":[{"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/media?parent=16545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/categories?post=16545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchdistrict.com\/boston\/wp-json\/wp\/v2\/tags?post=16545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}