{"id":144394,"date":"2020-05-18T16:12:31","date_gmt":"2020-05-18T23:12:31","guid":{"rendered":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/"},"modified":"2021-08-09T05:26:46","modified_gmt":"2021-08-09T12:26:46","slug":"plus-beaux-quartiers-manhattan-new-york","status":"publish","type":"post","link":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/","title":{"rendered":"Les plus beaux quartiers de Manhattan"},"content":{"rendered":"<h2>Upper East Side<\/h2>\n<p>Vivier culturel de <strong>Manhattan<\/strong> avec le Museum Mile et notamment l\u2019<strong><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/visite-metropolitan-museum-art-new-york\/\" target=\"_blank\" rel=\"noopener noreferrer\">incontournable MET<\/a><\/strong>, l\u2019<strong>Upper East Side<\/strong> incarne le luxe discret et les traditions des grandes familles new-yorkaises. Ici, rien ne d\u00e9passe, tout est en ordre, vous dormirez sur vos deux oreilles. Le<strong> quartier<\/strong> est r\u00e9put\u00e9 pour ses superbes Brownstones, ses magasins haut de gamme, ses malls de luxe, ses larges avenues bord\u00e9es d\u2019arbres et ses restaurants chics. Chic justement, vous y d\u00e9m\u00e9nagez !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-89214\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2020\/05\/quartiers-manhattant-article-3.jpg\" alt=\"quartiers-manhattant-article (3)\" width=\"750\" height=\"350\" \/><\/p>\n<h2>Upper West Side<\/h2>\n<p>Au nord ouest de<strong> Manhattan<\/strong>, en bordure de<strong> <a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/sports-jeux-activites-central-park-new-york\/\" target=\"_blank\" rel=\"noopener noreferrer\">Central Park<\/a><\/strong>, et \u00e0 c\u00f4t\u00e9 de la Hudson River, <strong>le quartier d\u2019Upper West Side<\/strong> conjugue verdure et nature dans un cadre de vie calme et opulent. De remarquables Brownstones et des immeubles anciens bordent les larges trottoirs et l\u2019UWS, pour les intimes, jouit d\u2019une excellente r\u00e9putation en mati\u00e8re de s\u00e9curit\u00e9. Sc\u00e8ne de nombreux films comme Ghost Busters ou le l\u00e9gendaire West Side Story, le <strong>quartier<\/strong> abrite le superbe <a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/american-museum-of-natural-history-visite-musee-histoire-naturelle\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>American Museum of Natural History<\/strong><\/a> et bon nombre de th\u00e9\u00e2tres et de mus\u00e9es. C\u2019est \u00e0 l\u2019ouest de <strong>Central Park<\/strong> que la belle pierre y vaut le plus cher avec des immeubles de prestige tels que le Dakota, o\u00f9 vivait John Lennon ou Lauren Bacall. M\u00eame en mati\u00e8re d\u2019\u00e9ducation, <strong>l\u2019Upper West Side<\/strong> se d\u00e9marque, et compte parmi des \u00e9coles et universit\u00e9s de prestige dont Trinity School et <strong>Columbia<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-89213\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2020\/05\/quartiers-manhattant-article-2.jpg\" alt=\"\" width=\"750\" height=\"350\" \/><\/p>\n<h2>Chelsea &#8211; Meatpacking<\/h2>\n<p>Vibrant, \u00e9clectique, contrast\u00e9 et artistique, <strong>Chelsea<\/strong> est vraiment un lieu de vie privil\u00e9gi\u00e9 au c\u0153ur de<strong> Manhattan<\/strong>. Son emplacement est central, tr\u00e8s bien desservi et on croise sur la <strong><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/high-line-visite-promenade-chelsea-nyc\/\" target=\"_blank\" rel=\"noopener noreferrer\">High Line<\/a>,<\/strong> ce parc sur\u00e9lev\u00e9 n\u00e9 sur une ancienne voie ferr\u00e9e, autant de coureurs du dimanche que de familles avec poussettes, qui reviennent du fameux<strong> <a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/chelsea-market-new-york\/\" target=\"_blank\" rel=\"noopener noreferrer\">Chelsea Market<\/a>.<\/strong> Il faut dire que l\u2019environnement est vert, calme et que les <strong>townhouses<\/strong> de briques rouges et les condos parfois luxueux avec vue sur l<strong>\u2019<\/strong><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/empire-state-building-visite-manhattan\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Empire State Building<\/strong><\/a> ou la <strong><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/statue-liberte-liberty-island-monument-visite\/\" target=\"_blank\" rel=\"noopener noreferrer\">Statue de la Libert\u00e9<\/a><\/strong> en rajoutent \u00e0 ce portrait enchanteur. Vous aimez l\u2019art au sens large et inconditionnel ? <strong>Chelsea<\/strong> a ce qu\u2019il vous faut : avec plus de 200 galeries, le<strong> quartier<\/strong> est devenu une r\u00e9f\u00e9rence mondiale en mati\u00e8re d\u2019art contemporain.<\/p>\n<p>Enfin, si vous aimez l\u2019art et que vous \u00eates f\u00eatard, cherchez plut\u00f4t du c\u00f4t\u00e9 de la 27th street (et au-dessus), la rue des bars et des m\u00e9ga-clubs. Vous ne serez plus \u00e0<strong> Chelsea,<\/strong> mais dans le Meatpacking, un des <strong>endroits les plus en vogue de Manhattan<\/strong>. Ancienne zone des abattoirs et des usines de conditionnement, le <strong>quartier<\/strong> s\u2019est affranchi de sa mauvaise r\u00e9putation pour devenir le rendez-vous de la jeunesse chic et branch\u00e9e de <strong>New York<\/strong>. Spas pour chiens, h\u00f4tels de luxe avec rooftops, comme le Gansvoort, showrooms gigantesques et chausseurs chics bordent les jolies rues pav\u00e9es, tout est possible dans le Meatpacking.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-89221\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2020\/05\/QUArtier-manhattant-article-4\u00e8.jpg\" alt=\"QUArtier-manhattant-article-4\u00e8\" width=\"750\" height=\"350\" \/><\/p>\n<h2>West Village<\/h2>\n<p>Si vous avez quelques millions de c\u00f4t\u00e9, le quartier de <strong>West Village<\/strong> reste une valeur s\u00fbre, que ce soit pour y habiter d\u2019abord et peut \u00eatre croiser le chemin de Sarah Jessica Parker ou d\u2019admirer la dentition de Jim Carrey, mais aussi pour<strong> investir dans les superbes maisons de villes,<\/strong> si typiques de ce coin. Ce que vous allez aimer \u00e0 <strong>West village<\/strong>, ce sont les rues o\u00f9 flottent encore un parfum de boh\u00e8me, les trottoirs anim\u00e9s de caf\u00e9s qui sentent bon le Cappucino, sans parler des boutiques intimistes que l\u2019on ne trouve nul par ailleurs. Le quartier accueille une population plut\u00f4t jeune (- 40 ans) qui aime un vrai confort de vie, se balader vers la <strong>Hudson River Park<\/strong> et la High line pour les envies de vert, et vers le <strong><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/whitney-museum-of-american-art-contemporain\/\" target=\"_blank\" rel=\"noopener noreferrer\">Whitney Museum of American Art<\/a>\u00a0<\/strong> pour les envies de culture. Le prix moyen des ventes dans ce<strong> quartier<\/strong> est de 1,2 millions de dollars environ, mais certains<strong> townhouses<\/strong> valent, beaucoup, beaucoup plus cher.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-89215\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2020\/05\/quartiers-manhattant-article-_1_.jpg\" alt=\"quartiers-manhattant-article-_1_\" width=\"750\" height=\"350\" \/><\/p>\n<h2>Soho \u2013 Nolita- Greenwich Village<\/h2>\n<p>Branch\u00e9, c\u2019est l\u2019adjectif qui colle \u00e0 la peau de Soho et de ses environs. De son pass\u00e9 boh\u00e8me de \u00ab coin des artistes \u00bb,<strong> Soho<\/strong> (<a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/journee-decouverte-art-musee-visite-soho\/\" target=\"_blank\" rel=\"noopener noreferrer\">SOuth of HOuston Street pour ceux qui l\u2019ignorent<\/a>) a h\u00e9rit\u00e9 des boutiques de cr\u00e9ateurs qui se succ\u00e8dent le long des rues ombrag\u00e9es et notamment de Bleeker Street, bien connue des fashionistas. Les coffee-shops douillets et les restaurants branch\u00e9s aussi occupent chaque (centi)m\u00e8tre de trottoirs qui valent cher, tr\u00e8s cher. Les lofts contemporains et les studios d\u2019artistes tr\u00e8s pris\u00e9s sont venus fleurir dans les anciens grands b\u00e2timents de fonte et de briques jadis d\u00e9sert\u00e9s. Ce renouveau architectural avec notamment les r\u00e9novations apport\u00e9es au Puck Building, donne un r\u00e9sultat remarquable, \u00e0 tel point que Soho figure sur le Registre National des Sites Historiques. A quelques buildings de l\u00e0, la magnifique <strong>New York University<\/strong> tr\u00f4ne \u00e0<strong> Greenwich Village<\/strong>. Elle accueille chaque ann\u00e9e 50 000 \u00e9tudiants et sa biblioth\u00e8que poss\u00e8de 12 millions de livres.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-89218\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2020\/05\/QUArtier-manhattant-article-4.jpg\" alt=\"QUArtier-manhattant-article-4\" width=\"750\" height=\"350\" \/><\/p>\n<h2>Tribeca<\/h2>\n<p>Il \u00e9tait une fois, il y a fort bien longtemps, un coin de <strong>Manhattan<\/strong> habit\u00e9 uniquement par des manufactures et des usines alimentaires. <strong>Tribeca,<\/strong> comme sa voisine du haut Soho, a fait depuis enti\u00e8rement peau neuve et d\u00e8s lors, les splendides lofts d\u2019architectes et appartements aux grandes fen\u00eatres, et les nouveaux condominiums de luxe vers<strong> Battery Park,<\/strong> avec vue sur la baie de <strong>New York<\/strong> ont remplac\u00e9 les tristes fabriques d\u2019autrefois. Une faune des plus gratin\u00e9es habite d\u00e9sormais les lieux : vous pourrez ainsi croiser Meryl Streep lors de la promenade de Bichon, ou Jay-Z pendant votre jogging matinal, et m\u00eame, si vous \u00eates du genre sociable, pousser la chansonnette avec Taylor Swift ou d\u00e9battre sur le r\u00e9chauffement climatique avec Leonardo di Caprio.<br \/>\nLes enfants sont, eux aussi, les bienvenus \u00e0 <strong>Tribeca<\/strong>, la preuve en est avec Blue School, la maternelle la plus prestigieuse de<strong> New York<\/strong>, install\u00e9e \u00e0 quelques p\u00e2t\u00e9s de buildings. Contre 40 000$ par an (le prix d\u2019une <a href=\"https:\/\/frenchdistrict.com\/articles\/top-5-meilleures-universites-americaines-histoire\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ivy League<\/a>), des enseignants bard\u00e9s de dipl\u00f4mes forment votre enfant de 3,5 ans \u00e0 devenir un futur leader de ce monde\u2026<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-89223\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2020\/05\/lesplus-beaux-quartiers-manhattan-new-york.jpg\" alt=\"lesplus-beaux-quartiers-manhattan-new-york\" width=\"750\" height=\"350\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Vous souhaitez investir dans un des plus beaux quartiers de Manhattan ?<br \/>\nContactez Barnes New York?<\/h2>\n<a name=\"contactfd\" style=\"display: block;position: relative;top: -150px;visibility: hidden;\"><\/a><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_6' ><div id='gf_6' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_6' id='gform_6'  action='\/californie-nord\/wp-json\/wp\/v2\/posts\/144394#gf_6' data-formid='6' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_6' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_6_7\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_7'>LinkedIn<\/label><div class='ginput_container'><input name='input_7' id='input_6_7' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_6_7'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_6_1\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_1'>Votre nom:<\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_6_1' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_6_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_2'>Votre adresse Email:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_6_2' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_6_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_3'>Votre t\u00e9l\u00e9phone:<\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_6_3' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_6_4\" class=\"gfield gfield--type-textarea field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_4'>Votre message:<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_6_4' class='textarea medium'   maxlength='800'   aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_6_5\" class=\"gfield gfield--type-checkbox gfield--type-choice field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_6_5'><li class='gchoice gchoice_6_5_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.1' type='checkbox'  value='Je souhaite m&#039;abonner \u00e0 la newsletter French District Californie Nord et recevoir des bons plans' checked='checked' id='choice_6_5_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_6_5_1' id='label_6_5_1' class='gform-field-label gform-field-label--type-inline'>Je souhaite m'abonner \u00e0 la newsletter French District Californie Nord et recevoir des bons plans<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_6_6\" class=\"gfield gfield--type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text' for='input_6_6'><\/label><div id='input_6_6' class='ginput_container ginput_recaptcha' data-sitekey='6Ldt8T8pAAAAAGjed3W4for4vBHh05M38nSQGx0t'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_6' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Envoyer'  \/> <input type='hidden' name='gform_ajax' value='form_id=6&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=1fca562c281bf1e1ed9ba3caa16c30d8' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_6' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_6' id='gform_theme_6' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_6' id='gform_style_settings_6' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_6' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='6' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='2spHu5ujv+8qKfW+7UGcETxhkONol+BBEvNLYwftQBTHQPc8o72nbah7CzOlViOSq92obVYQHJ0k2p0dw3TqgGlz3BxsJPiJzomoRbGPBHQ6Yt0=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_6' value='WyJbXSIsIjYxMWFmYjlmMzI4ZTI4YmYzMThjYTg1MDIyODQ0YTljIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_6' id='gform_target_page_number_6' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_6' id='gform_source_page_number_6' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_6' id='gform_ajax_frame_6' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 6, 'https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_6').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_6');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_6').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_6').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_6').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_6').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_6').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_6').val();gformInitSpinner( 6, 'https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [6, current_page]);window['gf_submitting_6'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_6').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_6').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [6]);window['gf_submitting_6'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_6').text());}else{jQuery('#gform_6').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"6\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_6\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_6\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_6\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 6, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>Upper East Side Vivier culturel de Manhattan avec le Museum Mile et notamment l\u2019incontournable MET, l\u2019Upper East Side incarne le luxe discret et les traditions des grandes familles new-yorkaises. Ici, rien ne d\u00e9passe, tout est en ordre, vous dormirez sur vos deux oreilles. Le quartier est r\u00e9put\u00e9 pour ses superbes Brownstones, ses magasins haut de [&hellip;]<\/p>\n","protected":false},"author":8238,"featured_media":144566,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[208,1837],"tags":[1990,2129,2130,1724,2131,1973,1974,924,2132,2133,1153,2134,2135],"class_list":["post-144394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chut-secrets","category-immobilier-etats-unis","tag-agent-immobilier-new-york","tag-appatements-new-york","tag-brownstones","tag-ecoles-scolaires-enseignements-formations","tag-immobilier-manhattan","tag-immobilier-new-york","tag-investir-new-york","tag-ivy-league","tag-maisons-new-york","tag-marches","tag-musees","tag-quartiers","tag-townhouses"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25b7 Les plus beaux quartiers de Manhattan \u00e0 New York<\/title>\n<meta name=\"description\" content=\"Zoom sur les plus beaux endroits o\u00f9 poser ses valises pour vivre \u00e0 Manhattan, de l&#039;Upper West Side \u00e0 Tribeca en passant par Soho et Chelsea.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 Les plus beaux quartiers de Manhattan \u00e0 New York\" \/>\n<meta property=\"og:description\" content=\"Zoom sur les plus beaux endroits o\u00f9 poser ses valises pour vivre \u00e0 Manhattan, de l&#039;Upper West Side \u00e0 Tribeca en passant par Soho et Chelsea.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/\" \/>\n<meta property=\"og:site_name\" content=\"Californie Nord\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frenchdistrict\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-18T23:12:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-09T12:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2022\/06\/QUArtier-manhattant-article-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"laure\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:site\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"laure\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/\"},\"author\":{\"name\":\"laure\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/#\\\/schema\\\/person\\\/c290d2275f409e11be6d391a68ad4c1e\"},\"headline\":\"Les plus beaux quartiers de Manhattan\",\"datePublished\":\"2020-05-18T23:12:31+00:00\",\"dateModified\":\"2021-08-09T12:26:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/\"},\"wordCount\":1059,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/06\\\/QUArtier-manhattant-article-cover.jpg\",\"keywords\":[\"agent immobilier new york\",\"appatements new york\",\"brownstones\",\"ecoles\",\"immobilier manhattan\",\"immobilier new-york\",\"investir new york\",\"ivy league\",\"maisons new york\",\"march\u00e9s\",\"mus\u00e9es\",\"quartiers\",\"townhouses\"],\"articleSection\":[\"Coups de coeur\",\"Immobilier\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/\",\"name\":\"\u25b7 Les plus beaux quartiers de Manhattan \u00e0 New York\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/06\\\/QUArtier-manhattant-article-cover.jpg\",\"datePublished\":\"2020-05-18T23:12:31+00:00\",\"dateModified\":\"2021-08-09T12:26:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/#\\\/schema\\\/person\\\/c290d2275f409e11be6d391a68ad4c1e\"},\"description\":\"Zoom sur les plus beaux endroits o\u00f9 poser ses valises pour vivre \u00e0 Manhattan, de l'Upper West Side \u00e0 Tribeca en passant par Soho et Chelsea.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/06\\\/QUArtier-manhattant-article-cover.jpg\",\"contentUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2022\\\/06\\\/QUArtier-manhattant-article-cover.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"QUArtier-manhattant-article-cover\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/plus-beaux-quartiers-manhattan-new-york\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Californie Nord\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ecoles Priv\u00e9es\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/annuaire-pro\\\/ecoles-privees\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les plus beaux quartiers de Manhattan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/#website\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/\",\"name\":\"Californie Nord\",\"description\":\"Le meilleur de la &lt;span&gt;Californie du Nord&lt;\\\/span&gt; par ceux qui y vivent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/#\\\/schema\\\/person\\\/c290d2275f409e11be6d391a68ad4c1e\",\"name\":\"laure\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g\",\"caption\":\"laure\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 Les plus beaux quartiers de Manhattan \u00e0 New York","description":"Zoom sur les plus beaux endroits o\u00f9 poser ses valises pour vivre \u00e0 Manhattan, de l'Upper West Side \u00e0 Tribeca en passant par Soho et Chelsea.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/","og_locale":"fr_FR","og_type":"article","og_title":"\u25b7 Les plus beaux quartiers de Manhattan \u00e0 New York","og_description":"Zoom sur les plus beaux endroits o\u00f9 poser ses valises pour vivre \u00e0 Manhattan, de l'Upper West Side \u00e0 Tribeca en passant par Soho et Chelsea.","og_url":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/","og_site_name":"Californie Nord","article_publisher":"https:\/\/www.facebook.com\/frenchdistrict","article_published_time":"2020-05-18T23:12:31+00:00","article_modified_time":"2021-08-09T12:26:46+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2022\/06\/QUArtier-manhattant-article-cover.jpg","type":"image\/jpeg"}],"author":"laure","twitter_card":"summary_large_image","twitter_creator":"@frenchdistrict","twitter_site":"@frenchdistrict","twitter_misc":{"\u00c9crit par":"laure","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/#article","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/"},"author":{"name":"laure","@id":"https:\/\/frenchdistrict.com\/californie-nord\/#\/schema\/person\/c290d2275f409e11be6d391a68ad4c1e"},"headline":"Les plus beaux quartiers de Manhattan","datePublished":"2020-05-18T23:12:31+00:00","dateModified":"2021-08-09T12:26:46+00:00","mainEntityOfPage":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/"},"wordCount":1059,"commentCount":0,"image":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2022\/06\/QUArtier-manhattant-article-cover.jpg","keywords":["agent immobilier new york","appatements new york","brownstones","ecoles","immobilier manhattan","immobilier new-york","investir new york","ivy league","maisons new york","march\u00e9s","mus\u00e9es","quartiers","townhouses"],"articleSection":["Coups de coeur","Immobilier"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/","url":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/","name":"\u25b7 Les plus beaux quartiers de Manhattan \u00e0 New York","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/#primaryimage"},"image":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2022\/06\/QUArtier-manhattant-article-cover.jpg","datePublished":"2020-05-18T23:12:31+00:00","dateModified":"2021-08-09T12:26:46+00:00","author":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/#\/schema\/person\/c290d2275f409e11be6d391a68ad4c1e"},"description":"Zoom sur les plus beaux endroits o\u00f9 poser ses valises pour vivre \u00e0 Manhattan, de l'Upper West Side \u00e0 Tribeca en passant par Soho et Chelsea.","breadcrumb":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/#primaryimage","url":"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2022\/06\/QUArtier-manhattant-article-cover.jpg","contentUrl":"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2022\/06\/QUArtier-manhattant-article-cover.jpg","width":1600,"height":1067,"caption":"QUArtier-manhattant-article-cover"},{"@type":"BreadcrumbList","@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/plus-beaux-quartiers-manhattan-new-york\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Californie Nord","item":"https:\/\/frenchdistrict.com\/californie-nord\/"},{"@type":"ListItem","position":2,"name":"Ecoles Priv\u00e9es","item":"https:\/\/frenchdistrict.com\/californie-nord\/annuaire-pro\/ecoles-privees\/"},{"@type":"ListItem","position":3,"name":"Les plus beaux quartiers de Manhattan"}]},{"@type":"WebSite","@id":"https:\/\/frenchdistrict.com\/californie-nord\/#website","url":"https:\/\/frenchdistrict.com\/californie-nord\/","name":"Californie Nord","description":"Le meilleur de la &lt;span&gt;Californie du Nord&lt;\/span&gt; par ceux qui y vivent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchdistrict.com\/californie-nord\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/frenchdistrict.com\/californie-nord\/#\/schema\/person\/c290d2275f409e11be6d391a68ad4c1e","name":"laure","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g","caption":"laure"}}]}},"_links":{"self":[{"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/posts\/144394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/users\/8238"}],"replies":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/comments?post=144394"}],"version-history":[{"count":6,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/posts\/144394\/revisions"}],"predecessor-version":[{"id":144643,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/posts\/144394\/revisions\/144643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/media\/144566"}],"wp:attachment":[{"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/media?parent=144394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/categories?post=144394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/tags?post=144394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}