{"id":32154,"date":"2018-03-12T07:27:04","date_gmt":"2018-03-12T15:27:04","guid":{"rendered":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/"},"modified":"2020-12-02T11:12:15","modified_gmt":"2020-12-02T19:12:15","slug":"assurance-sante-etats-unis-expatries-etudiants-voyageurs","status":"publish","type":"post","link":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/","title":{"rendered":"Expatri\u00e9s, \u00e9tudiants ou voyageurs, l&#8217;assurance sant\u00e9 aux \u00c9tats-Unis est capitale !"},"content":{"rendered":"<h2>1) Comment choisir librement ses garanties et b\u00e9n\u00e9ficier d&#8217;un contrat sur mesure ?<\/h2>\n<p>Le co\u00fbt des <strong>frais de sant\u00e9<\/strong> aux USA est pr\u00e8s de 10 fois sup\u00e9rieur \u00e0 celui de la France, c&#8217;est m\u00eame l&#8217;un des plus \u00e9lev\u00e9s au monde ! La prime moyenne d&#8217;<strong>assurance sant\u00e9<\/strong> a augment\u00e9 de plus de 60 % depuis 2005 et de plus de 30 % depuis 2010. Fort de ce constat, c&#8217;est justement \u00e0 ce titre que vous devez \u00eatre vigilant sur l&#8217;\u00e9tendue de vos garanties et chercher un<strong> contrat d&#8217;assurance<\/strong> qui correspond \u00e0 vos attentes.<\/p>\n<p>Le principe est de trouver du sur mesure au prix du pr\u00eat \u00e0 porter ! Aujourd&#8217;hui cela est possible et facilement r\u00e9alisable aupr\u00e8s d&#8217;un assureur proposant des <strong>contrats d&#8217;assurances internationales<\/strong>. Par leur interm\u00e9diaire, vous pourrez choisir vos <strong>garanties<\/strong>, vos options compl\u00e9mentaires, vos <strong>franchises<\/strong> \u00e9ventuelles, vos plafonds de <strong>remboursements<\/strong> pour b\u00e9n\u00e9ficier d&#8217;un maximum de s\u00e9curit\u00e9 en fonction de votre situation personnelle. <strong>L&#8217;expatriation<\/strong>, surtout aux \u00c9tats-Unis, ne doit pas rimer avec une augmentation de la pr\u00e9carit\u00e9 sociale au pays de l&#8217;argent roi. Vous avez la possibilit\u00e9 de vous assurer en gardant les principes de base de vos remboursements et garanties dont vous b\u00e9n\u00e9ficiiez peut-\u00eatre en France avant de vous expatrier.<\/p>\n<h2>2) Comment \u00eatre prot\u00e9g\u00e9 en respectant une l\u00e9gislation en pleine \u00e9volution ?<\/h2>\n<h3>a) La probl\u00e9matique de l&#8217;Obamacare (Affordable Care Act)<\/h3>\n<p>Depuis 2014, tout r\u00e9sidant fiscal aux USA doit disposer d&#8217;une <strong>assurance sant\u00e9<\/strong> avec un contrat reprenant \u00e0 minima 10 garanties obligatoires appel\u00e9es <strong>MEC-Minimum Essential Coverage :<\/strong><\/p>\n<ul>\n<li>Les services d&#8217;<strong>urgence<\/strong>,<\/li>\n<li>l&#8217;<strong>hospitalisation<\/strong>,<\/li>\n<li>les <strong>services ambulatoires<\/strong>,<\/li>\n<li>les services <strong>p\u00e9diatriques<\/strong>,<\/li>\n<li>les analyses en <strong>laboratoire<\/strong>,<\/li>\n<li>les services de <strong>r\u00e9\u00e9ducation<\/strong>,<\/li>\n<li>les prescriptions m\u00e9dicales,<\/li>\n<li><strong>l&#8217;accouchement<\/strong> et prise en charge du nouveau-n\u00e9,<\/li>\n<li>la pr\u00e9vention et la prise en charge des <strong>maladies chroniques<\/strong>,<\/li>\n<li>la <strong>sant\u00e9 mentale<\/strong><\/li>\n<\/ul>\n<p>Pour ces garanties aucun plafond ne peut \u00eatre fix\u00e9 mais les contrats d&#8217;assurances am\u00e9ricaines peuvent augmenter les cotisations d&#8217;un mois sur l&#8217;autre \u00e0 contrario de ceux propos\u00e9s par les assurances internationales. Parall\u00e8lement, cette r\u00e9forme a eu un impact tr\u00e8s important sur les deux types de contrats d&#8217;assurance propos\u00e9s \u00e0 titre individuel (individual mandate) ou par l&#8217;interm\u00e9diaire de son employeur (corporate mandate). Le principe fondateur de cette r\u00e9forme \u00e9tant de permettre l&#8217;obtention d&#8217;une assurance aux plus d\u00e9munis, les expatri\u00e9s notamment fran\u00e7ais privil\u00e9gient depuis cette r\u00e9forme en tr\u00e8s grande majorit\u00e9 les contrats propos\u00e9s par des assureurs internationaux plut\u00f4t qu&#8217;am\u00e9ricains.<\/p>\n<h3>b) La Caisse des Fran\u00e7ais de l\u2019\u00c9tranger<\/h3>\n<p><strong>La Caisse des Fran\u00e7ais de l\u2019\u00c9tranger<\/strong> est la caisse de <strong>S\u00e9curit\u00e9 Sociale des Fran\u00e7ais<\/strong> r\u00e9sidents \u00e0 l&#8217;\u00e9tranger. Organisme priv\u00e9, proposant une couverture sociale dans le monde entier, elle est r\u00e9gie par le Code de la S\u00e9curit\u00e9 Sociale. M\u00eame si son adh\u00e9sion d\u00e8s le d\u00e9part de France est recommand\u00e9e, elle n&#8217;est pas obligatoire et cette derni\u00e8re est calcul\u00e9e en fonction de votre statut, vos ressources, votre \u00e2ge ainsi que la situation des personnes composant \u00e9ventuellement votre famille. Les couvertures maladie, maternit\u00e9, invalidit\u00e9, accidents du travail, maladies professionnelles, vieillesse sont propos\u00e9es aux choix et peuvent \u00eatre compl\u00e9t\u00e9es tout ou partie par une assurance avec des garanties venant en compl\u00e9ment de celles propos\u00e9es par la Caisse des Fran\u00e7ais de l\u2019\u00c9tranger.<\/p>\n<h3>c) La complexit\u00e9 des franchises de paiement<\/h3>\n<p>En France, nous b\u00e9n\u00e9ficions d&#8217;une<strong> couverture \u00e0 100 % avec un ticket mod\u00e9rateur<\/strong> (co-insurance ou cost sharing) tr\u00e8s peu \u00e9lev\u00e9 ce qui n&#8217;est pas le cas aux USA. Les franchises sont les montants qui resteront \u00e0 votre charge avant m\u00eame que l&#8217;assureur ne vous rembourse. Il existe les &#8220;co-payments&#8221; (pour les frais de laboratoires, examens m\u00e9dicaux&#8230;), les d\u00e9ductibles, les co-insurance qui restent toujours \u00e0 votre charge, montants au del\u00e0 desquels votre assureur vous remboursera \u00e0 100 %.<\/p>\n<p>Le montant restant \u00e0 votre charge (Maximum Out Of Pocket) est \u00e9galement variable en fonction des assureurs et peuvent atteindre 15.000 $\/an pour une famille. Selon l&#8217;\u00e9tat d&#8217;habitation aux USA, le co\u00fbt d&#8217;une assurance sant\u00e9 \u00e9tait en 2016 de 600 $\/mois pour un c\u00e9libataire et plus de 1.500 $\/mois pour une famille avec un restant \u00e0 charge moyen de plus de 5.000 $\/an. Tr\u00e8s souvent, afin de faire baisser le montant de leur cotisation, les assur\u00e9s font monter les franchises. Attention \u00e0 ce jeu dangereux qui, au final, peut vous co\u00fbter tr\u00e8s chers avant m\u00eame que votre assureur ne prenne le relais !<\/p>\n<h3>d) Le choix d&#8217;un contrat d&#8217;assurance am\u00e9ricaine ou internationale<\/h3>\n<p>Le choix d&#8217;un <strong>contrat d&#8217;assurance sant\u00e9 pour les expatri\u00e9s<\/strong> est tr\u00e8s important et permet de se rendre compte que la m\u00e9decine \u00e0 un co\u00fbt qui peut \u00eatre tr\u00e8s on\u00e9reux en dehors de nos fronti\u00e8res fran\u00e7aises. <a href=\"https:\/\/frenchdistrict.com\/adresse\/comparateur-courtier-assurance-sante-en-ligne-expatries-francais-usa\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Vous pouvez comparer des centaines d&#8217;offres gr\u00e2ces \u00e0 des comparateurs d&#8217;assurance sant\u00e9 aux \u00c9tats-Unis 100% en ligne.<\/strong><\/a><\/p>\n<p>Vous pouvez soit souscrire une <strong>assurance sant\u00e9 am\u00e9ricaine<\/strong>, soit une police internationale. Il est crucial afin de ne pas \u00eatre aussi limit\u00e9 dans le r\u00e9seau de m\u00e9decins \u00e0 consulter de bien comparer. Certaines assurances notamment les HMO Plans (<strong>Health Maintenance Organization<\/strong>) vous obligent \u00e0 consulter dans leur r\u00e9seau, aupr\u00e8s de leur m\u00e9decin r\u00e9f\u00e9rent PCP (<strong>Primary Care Physician<\/strong>) et ne vous rembourserons pas si vous d\u00e9rogez \u00e0 leur r\u00e8gle de consultation. Il convient de privil\u00e9gier plut\u00f4t les contrats PPO Plans (<strong>Preferred Provider Organization<\/strong>). Pour les m\u00eames soins, vous pouvez \u00eatre factur\u00e9 du simple au double. Si vous n&#8217;\u00eates pas bien assur\u00e9, si vous n&#8217;avez pas les moyens de payer et apr\u00e8s plusieurs milliers de dollars d\u00e9pens\u00e9s pour l&#8217;ambulance, aux USA les portes d&#8217;une hospitalisation peuvent rapidement se fermer.<\/p>\n<p>Alors que l&#8217;avenir de <strong>l&#8217;Obamacare<\/strong> s&#8217;assombrit de jour en jour (m\u00eame si les R\u00e9publicains n&#8217;ont pas pu se mettre d&#8217;accord sur son abolition), compte tenu de l&#8217;augmentation des primes par les assureurs am\u00e9ricains, il est fort probable que le <strong>syst\u00e8me d&#8217;assurance sant\u00e9 aux \u00c9tats-Unis<\/strong> va imploser et cette r\u00e9forme tant d\u00e9cri\u00e9e sera abolie avant la fin du mandat de M. Donald Trump !<\/p>\n<h2>Vous avez besoin d\u2019une assurance aux \u00c9tats-Unis?<br \/>\nContactez-nous!<\/h2>\n<a name=\"contactfd\" style=\"display: block;position: relative;top: -150px;visibility: hidden;\"><\/a><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_6' ><div id='gf_6' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_6' id='gform_6'  action='\/californie-nord\/wp-json\/wp\/v2\/posts\/32154#gf_6' data-formid='6' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_6' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_6_7\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_7'>Company<\/label><div class='ginput_container'><input name='input_7' id='input_6_7' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_6_7'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_6_1\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_1'>Votre nom:<\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_6_1' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_6_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_2'>Votre adresse Email:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_6_2' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_6_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_3'>Votre t\u00e9l\u00e9phone:<\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_6_3' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_6_4\" class=\"gfield gfield--type-textarea field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_4'>Votre message:<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_6_4' class='textarea medium'   maxlength='800'   aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_6_5\" class=\"gfield gfield--type-checkbox gfield--type-choice field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_6_5'><li class='gchoice gchoice_6_5_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.1' type='checkbox'  value='Je souhaite m&#039;abonner \u00e0 la newsletter French District Californie Nord et recevoir des bons plans' checked='checked' id='choice_6_5_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_6_5_1' id='label_6_5_1' class='gform-field-label gform-field-label--type-inline'>Je souhaite m'abonner \u00e0 la newsletter French District Californie Nord et recevoir des bons plans<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_6_6\" class=\"gfield gfield--type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text' for='input_6_6'><\/label><div id='input_6_6' class='ginput_container ginput_recaptcha' data-sitekey='6Ldt8T8pAAAAAGjed3W4for4vBHh05M38nSQGx0t'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_6' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Envoyer'  \/> <input type='hidden' name='gform_ajax' value='form_id=6&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=1fca562c281bf1e1ed9ba3caa16c30d8' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_6' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_6' id='gform_theme_6' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_6' id='gform_style_settings_6' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_6' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='6' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='VCjbf9TtHy9EhqzPWBceqJ0iZjkeWDSt2VmyTcqj6osH10OIWS6n8+TnHVNw8gE+z0sd1N4U36El7B67kKzac8\/LhgiKNiORwqE5nn4UjQ5GAFA=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_6' value='WyJbXSIsIjYxMWFmYjlmMzI4ZTI4YmYzMThjYTg1MDIyODQ0YTljIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_6' id='gform_target_page_number_6' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_6' id='gform_source_page_number_6' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_6' id='gform_ajax_frame_6' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 6, 'https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_6').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_6');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_6').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_6').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_6').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_6').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_6').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_6').val();gformInitSpinner( 6, 'https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [6, current_page]);window['gf_submitting_6'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_6').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_6').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [6]);window['gf_submitting_6'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_6').text());}else{jQuery('#gform_6').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"6\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_6\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_6\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_6\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 6, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>1) Comment choisir librement ses garanties et b\u00e9n\u00e9ficier d&#8217;un contrat sur mesure ? Le co\u00fbt des frais de sant\u00e9 aux USA est pr\u00e8s de 10 fois sup\u00e9rieur \u00e0 celui de la France, c&#8217;est m\u00eame l&#8217;un des plus \u00e9lev\u00e9s au monde ! La prime moyenne d&#8217;assurance sant\u00e9 a augment\u00e9 de plus de 60 % depuis 2005 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":103952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1841,774,1842],"tags":[1281,202,321,1330,234],"class_list":["post-32154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-assurance-etats-unis","category-monde-expatriation","category-sante-etats-unis","tag-assurance-sante","tag-etudiant","tag-special-nouveaux-arrivants","tag-securite-sociale","tag-voyage-tourisme-avions-agences"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;assurance sant\u00e9 aux \u00c9tats-Unis pour les expatri\u00e9s, \u00e9tudiants et voyageurs<\/title>\n<meta name=\"description\" content=\"Comment assurer sa sant\u00e9 dans le cadre d&#039;une expatriation, d&#039;\u00e9tudes ou d&#039;un voyage \u00e0 l&#039;\u00e9tranger ? Pour une s\u00e9curit\u00e9 maximale, vous devez \u00eatre certain d&#039;avoir un assureur qui vous propose de prendre en charge 100 % de vos frais m\u00e9dicaux partout dans le monde. French Expat company vous donne ses conseils.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;assurance sant\u00e9 aux \u00c9tats-Unis pour les expatri\u00e9s, \u00e9tudiants et voyageurs\" \/>\n<meta property=\"og:description\" content=\"Comment assurer sa sant\u00e9 dans le cadre d&#039;une expatriation, d&#039;\u00e9tudes ou d&#039;un voyage \u00e0 l&#039;\u00e9tranger ? Pour une s\u00e9curit\u00e9 maximale, vous devez \u00eatre certain d&#039;avoir un assureur qui vous propose de prendre en charge 100 % de vos frais m\u00e9dicaux partout dans le monde. French Expat company vous donne ses conseils.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Californie Nord\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frenchdistrict\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-12T15:27:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-02T19:12:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2020\/12\/assurance-sante-etats-unis-expatries-etudiants-voyageurs-2_8184529_1263495_6167411.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"alix\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:site\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"alix\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/\"},\"author\":{\"name\":\"alix\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/#\\\/schema\\\/person\\\/c6f42e2f256922989bb0a4df40eb74eb\"},\"headline\":\"Expatri\u00e9s, \u00e9tudiants ou voyageurs, l&#8217;assurance sant\u00e9 aux \u00c9tats-Unis est capitale !\",\"datePublished\":\"2018-03-12T15:27:04+00:00\",\"dateModified\":\"2020-12-02T19:12:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/\"},\"wordCount\":1086,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/12\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs-2_8184529_1263495_6167411.jpg\",\"keywords\":[\"Assurance sant\u00e9\",\"\u00e9tudiant\",\"expatriation\",\"s\u00e9curit\u00e9 sociale\",\"voyage\"],\"articleSection\":[\"Assurance\",\"Expatriation\",\"Sant\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/\",\"name\":\"L'assurance sant\u00e9 aux \u00c9tats-Unis pour les expatri\u00e9s, \u00e9tudiants et voyageurs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/12\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs-2_8184529_1263495_6167411.jpg\",\"datePublished\":\"2018-03-12T15:27:04+00:00\",\"dateModified\":\"2020-12-02T19:12:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/#\\\/schema\\\/person\\\/c6f42e2f256922989bb0a4df40eb74eb\"},\"description\":\"Comment assurer sa sant\u00e9 dans le cadre d'une expatriation, d'\u00e9tudes ou d'un voyage \u00e0 l'\u00e9tranger ? Pour une s\u00e9curit\u00e9 maximale, vous devez \u00eatre certain d'avoir un assureur qui vous propose de prendre en charge 100 % de vos frais m\u00e9dicaux partout dans le monde. French Expat company vous donne ses conseils.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/12\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs-2_8184529_1263495_6167411.jpg\",\"contentUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/12\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs-2_8184529_1263495_6167411.jpg\",\"width\":\"670\",\"height\":\"463\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/articles\\\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Californie Nord\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pratique\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/pratique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Assurance\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/pratique\\\/assurance-etats-unis\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Expatri\u00e9s, \u00e9tudiants ou voyageurs, l&#8217;assurance sant\u00e9 aux \u00c9tats-Unis est capitale !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/#website\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/\",\"name\":\"Californie Nord\",\"description\":\"Le meilleur de la &lt;span&gt;Californie du Nord&lt;\\\/span&gt; par ceux qui y vivent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-nord\\\/#\\\/schema\\\/person\\\/c6f42e2f256922989bb0a4df40eb74eb\",\"name\":\"alix\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed4ae6bf4315242728864c05b2fe8317caf14717783557659a64a08063f9c279?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed4ae6bf4315242728864c05b2fe8317caf14717783557659a64a08063f9c279?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed4ae6bf4315242728864c05b2fe8317caf14717783557659a64a08063f9c279?s=96&d=mm&r=g\",\"caption\":\"alix\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'assurance sant\u00e9 aux \u00c9tats-Unis pour les expatri\u00e9s, \u00e9tudiants et voyageurs","description":"Comment assurer sa sant\u00e9 dans le cadre d'une expatriation, d'\u00e9tudes ou d'un voyage \u00e0 l'\u00e9tranger ? Pour une s\u00e9curit\u00e9 maximale, vous devez \u00eatre certain d'avoir un assureur qui vous propose de prendre en charge 100 % de vos frais m\u00e9dicaux partout dans le monde. French Expat company vous donne ses conseils.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/","og_locale":"fr_FR","og_type":"article","og_title":"L'assurance sant\u00e9 aux \u00c9tats-Unis pour les expatri\u00e9s, \u00e9tudiants et voyageurs","og_description":"Comment assurer sa sant\u00e9 dans le cadre d'une expatriation, d'\u00e9tudes ou d'un voyage \u00e0 l'\u00e9tranger ? Pour une s\u00e9curit\u00e9 maximale, vous devez \u00eatre certain d'avoir un assureur qui vous propose de prendre en charge 100 % de vos frais m\u00e9dicaux partout dans le monde. French Expat company vous donne ses conseils.","og_url":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/","og_site_name":"Californie Nord","article_publisher":"https:\/\/www.facebook.com\/frenchdistrict","article_published_time":"2018-03-12T15:27:04+00:00","article_modified_time":"2020-12-02T19:12:15+00:00","og_image":[{"width":670,"height":463,"url":"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2020\/12\/assurance-sante-etats-unis-expatries-etudiants-voyageurs-2_8184529_1263495_6167411.jpg","type":"image\/jpeg"}],"author":"alix","twitter_card":"summary_large_image","twitter_creator":"@frenchdistrict","twitter_site":"@frenchdistrict","twitter_misc":{"\u00c9crit par":"alix","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/#article","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/"},"author":{"name":"alix","@id":"https:\/\/frenchdistrict.com\/californie-nord\/#\/schema\/person\/c6f42e2f256922989bb0a4df40eb74eb"},"headline":"Expatri\u00e9s, \u00e9tudiants ou voyageurs, l&#8217;assurance sant\u00e9 aux \u00c9tats-Unis est capitale !","datePublished":"2018-03-12T15:27:04+00:00","dateModified":"2020-12-02T19:12:15+00:00","mainEntityOfPage":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/"},"wordCount":1086,"commentCount":0,"image":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2020\/12\/assurance-sante-etats-unis-expatries-etudiants-voyageurs-2_8184529_1263495_6167411.jpg","keywords":["Assurance sant\u00e9","\u00e9tudiant","expatriation","s\u00e9curit\u00e9 sociale","voyage"],"articleSection":["Assurance","Expatriation","Sant\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/","url":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/","name":"L'assurance sant\u00e9 aux \u00c9tats-Unis pour les expatri\u00e9s, \u00e9tudiants et voyageurs","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/#primaryimage"},"image":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2020\/12\/assurance-sante-etats-unis-expatries-etudiants-voyageurs-2_8184529_1263495_6167411.jpg","datePublished":"2018-03-12T15:27:04+00:00","dateModified":"2020-12-02T19:12:15+00:00","author":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/#\/schema\/person\/c6f42e2f256922989bb0a4df40eb74eb"},"description":"Comment assurer sa sant\u00e9 dans le cadre d'une expatriation, d'\u00e9tudes ou d'un voyage \u00e0 l'\u00e9tranger ? Pour une s\u00e9curit\u00e9 maximale, vous devez \u00eatre certain d'avoir un assureur qui vous propose de prendre en charge 100 % de vos frais m\u00e9dicaux partout dans le monde. French Expat company vous donne ses conseils.","breadcrumb":{"@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/#primaryimage","url":"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2020\/12\/assurance-sante-etats-unis-expatries-etudiants-voyageurs-2_8184529_1263495_6167411.jpg","contentUrl":"https:\/\/frenchdistrict.com\/californie-nord\/wp-content\/uploads\/sites\/6\/2020\/12\/assurance-sante-etats-unis-expatries-etudiants-voyageurs-2_8184529_1263495_6167411.jpg","width":"670","height":"463"},{"@type":"BreadcrumbList","@id":"https:\/\/frenchdistrict.com\/californie-nord\/articles\/assurance-sante-etats-unis-expatries-etudiants-voyageurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Californie Nord","item":"https:\/\/frenchdistrict.com\/californie-nord\/"},{"@type":"ListItem","position":2,"name":"Pratique","item":"https:\/\/frenchdistrict.com\/californie-nord\/pratique\/"},{"@type":"ListItem","position":3,"name":"Assurance","item":"https:\/\/frenchdistrict.com\/californie-nord\/pratique\/assurance-etats-unis\/"},{"@type":"ListItem","position":4,"name":"Expatri\u00e9s, \u00e9tudiants ou voyageurs, l&#8217;assurance sant\u00e9 aux \u00c9tats-Unis est capitale !"}]},{"@type":"WebSite","@id":"https:\/\/frenchdistrict.com\/californie-nord\/#website","url":"https:\/\/frenchdistrict.com\/californie-nord\/","name":"Californie Nord","description":"Le meilleur de la &lt;span&gt;Californie du Nord&lt;\/span&gt; par ceux qui y vivent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchdistrict.com\/californie-nord\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/frenchdistrict.com\/californie-nord\/#\/schema\/person\/c6f42e2f256922989bb0a4df40eb74eb","name":"alix","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ed4ae6bf4315242728864c05b2fe8317caf14717783557659a64a08063f9c279?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed4ae6bf4315242728864c05b2fe8317caf14717783557659a64a08063f9c279?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed4ae6bf4315242728864c05b2fe8317caf14717783557659a64a08063f9c279?s=96&d=mm&r=g","caption":"alix"}}]}},"_links":{"self":[{"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/posts\/32154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/comments?post=32154"}],"version-history":[{"count":9,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/posts\/32154\/revisions"}],"predecessor-version":[{"id":103951,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/posts\/32154\/revisions\/103951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/media\/103952"}],"wp:attachment":[{"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/media?parent=32154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/categories?post=32154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-nord\/wp-json\/wp\/v2\/tags?post=32154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}