{"id":19200,"date":"2013-06-17T20:00:00","date_gmt":"2013-06-18T04:00:00","guid":{"rendered":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/"},"modified":"2025-01-31T06:01:35","modified_gmt":"2025-01-31T14:01:35","slug":"universite-americaine-college-fonctionnement-usa","status":"publish","type":"post","link":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/","title":{"rendered":"L&#8217;universit\u00e9 am\u00e9ricaine \u2013 comment \u00e7a marche\u00a0?"},"content":{"rendered":"<h2>Le syst\u00e8me \u00e9ducatif<\/h2>\n<h3>High School, College, University\u2026 Quelle diff\u00e9rence ?<\/h3>\n<p>A leur sortie de la <em>middle school<\/em> (4\u00e8me en France), les coll\u00e9giens entrent au lyc\u00e9e (<em>High School<\/em>) o\u00f9 ils \u00e9tudient 4 ans.<br \/>\nChaque \u00e9tudiant passe ensuite le SAT qui teste la lecture, les math\u00e9matiques, et l\u2019\u00e9crit, ou le ACT pour l\u2019anglais, les maths, la lecture et les sciences.<\/p>\n<p><strong>Lire aussi : <i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"http:\/\/frenchdistrict.com\/articles\/lycee-americain-high-school-ecole-etats-unis\/\">L&#8217;entr\u00e9e au lyc\u00e9e am\u00e9ricain<\/a><\/strong><\/p>\n<h3>Undergraduate, fais ce qu&#8217;il te pla\u00eet&#8230;<\/h3>\n<p>L\u2019\u00e9cole est obligatoire jusqu&#8217;au Lyc\u00e9e, et un \u00e9l\u00e8ve peut ensuite choisir de s\u2019inscrire au <strong><em>College<\/em><\/strong> comme <em>undergraduate<\/em> pendant 4 ans afin d\u2019obtenir un <em><strong>Bachelor Degree<\/strong><\/em> (BA pour Arts, BS pour Sciences).<\/p>\n\r\n\t<div class=\"sponsor__article sponsor__article--right\">\r\n\t\t<div class=\"inner\">\r\n\t\t\t<div class=\"sponsor__by\">Pr&eacute;sent&eacute; par...<\/div>\r\n\t\t\t<div>\r\n\t\t\t\t<a href=\"https:\/\/frenchdistrict.com\/presentez-entreprise\/\" target=\"_blank\">\r\n\t\t\t\t<div class=\"sponsor__illus\"><img decoding=\"async\" src=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2024\/05\/french-district-referencez-entreprise_9145233.png\" alt=\"French District\" \/><\/div>\r\n\t\t\t\t<div class=\"sponsor__content\">\r\n\t\t\t\t\t<p class=\"sponsor__title\">French District<\/p>\r\n\t\t\t\t\t<div class=\"sponsor__slogan\">French District : Le lien entre les entreprises et les expatri\u00e9s.<\/div>\r\n\t\t\t\t\t<div class=\"vce-button vce-button--small\" style=\"background-color: #444444;\"><i class=\"fa fa-hand-o-right\" aria-hidden=\"true\">&nbsp;<\/i>French District<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\t\t\r\n\t\t<\/div>\r\n\t<\/div>A la diff\u00e9rence de la France, un adolescent n\u2019a pas \u00e0 faire un choix quasi d\u00e9finitif quant \u00e0 son orientation professionnelle d\u00e8s le lyc\u00e9e ; le choix de mati\u00e8res en <em>undergraduate school<\/em> ne d\u00e9finit pas n\u00e9cessairement la voie emprunt\u00e9e plus tard. Un \u00e9tudiant peut donc \u00e9tudier l\u2019astronomie ou l\u2019anthropologie comme \u00ab\u00a0<em>major<\/em>\u00a0\u00bb en <strong><em>undergraduate school<\/em><\/strong> mais int\u00e9grer par la suite une \u00e9cole de droit. Chaque adolescent peut ainsi changer de major autant qu\u2019il le souhaite, afin de prendre le temps d\u2019explorer les potentiels de son soi-int\u00e9rieur.<\/p>\n<h3>Graduate, il faut choisir<\/h3>\n<p>A la <em>graduate school<\/em>, un \u00e9tudiant choisit la <strong><em>major<\/em><\/strong> qu&#8217;il va \u00e9tudier et peut obtenir un <strong>Master Degree<\/strong> apr\u00e8s 2 ans d\u2019\u00e9tudes, et m\u00eame ensuite un <strong>PhD<\/strong> (Doctorat) s\u2019il souhaite continuer.<br \/>\n<i class=\"fa fa-exclamation-triangle\" aria-hidden=\"true\"><\/i> Attention, il est toutefois possible d&#8217;int\u00e9grer les \u00e9coles de Droit, M\u00e9decine et Business directement apr\u00e8s l\u2019<em>undergraduate school<\/em>, sans faire un Master.<\/p>\n<p>Vient ensuite le moment tant attendu de la <strong>Graduation<\/strong> : le fameux jet\u00e9 du Mortarboard c\u00e9l\u00e8bre en effet l\u2019ach\u00e8vement de la scolarit\u00e9 am\u00e9ricaine&#8230; et un grand moment d&#8217;\u00e9motion et de f\u00eate.<\/p>\n<h3>Public vs Priv\u00e9<\/h3>\n<p>Une premi\u00e8re particularit\u00e9 am\u00e9ricaine est que le syst\u00e8me f\u00e9d\u00e9ral permet \u00e0 chaque Etat de d\u00e9cider de sa propre politique. Une <strong>\u00e9cole publique<\/strong> re\u00e7oit des fonds de la part du Gouvernement de l\u2019Etat dans lequel elle se situe, ce qui permet aux \u00e9tudiants de ce m\u00eame Etat de payer des <strong>frais de scolarit\u00e9<\/strong>, ou \u00ab\u00a0<em>tuition\u00a0\u00bb<\/em>, moins \u00e9lev\u00e9s que s\u2019ils allaient dans une \u00e9cole situ\u00e9e dans un autre Etat ou dans une institution priv\u00e9e.<\/p>\n<p>Les <strong>\u00e9coles priv\u00e9es<\/strong> \u2013 dont certaines sont religieuses &#8211; ne re\u00e7oivent pas d\u2019aide \u00e9tatique ; elles ne sont en revanche pas sujettes aux r\u00e9gulations gouvernementales de l\u2019Etat. La <em>tuition<\/em> de ces \u00e9coles l\u00e0 est cependant bien plus \u00e9lev\u00e9e \u2013 v\u00e9ritable investissement qui se chiffre en dizaine de milliers de dollars pour une seule ann\u00e9e.<\/p>\n<h2>Le budget<\/h2>\n<p><em>Comment financer ses \u00e9tudes sur le sol am\u00e9ricain ?<\/em><\/p>\n<h3>Bourses et subventions<\/h3>\n<p><strong>Lire aussi : <a href=\"https:\/\/frenchdistrict.com\/articles\/obtenir-bourses-etudes-americaines\/\"><i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> Les bourses d\u2019\u00e9tudes am\u00e9ricaines<\/a><\/strong><\/p>\n<p>Il y a trois principaux syst\u00e8mes d\u2019<strong>aide financi\u00e8re<\/strong>\u00a0:<\/p>\n<ul>\n<li>les bourses (scholarships)<\/li>\n<li>les subventions (grants)<\/li>\n<li>les emprunts (loans).<\/li>\n<\/ul>\n<p>Quelles en sont les diff\u00e9rences ? Que pr\u00e9f\u00e9rer ? Comment en b\u00e9n\u00e9ficier ? Analyse succincte de leur fonctionnement pour savoir quel syst\u00e8me choisir.<\/p>\n\r\n\t<div class=\"sponsor__article sponsor__article--right\">\r\n\t\t<div class=\"inner\">\r\n\t\t\t<div class=\"sponsor__by\">Pr&eacute;sent&eacute; par...<\/div>\r\n\t\t\t<div>\r\n\t\t\t\t<a href=\"https:\/\/frenchdistrict.com\/presentez-entreprise\/\" target=\"_blank\">\r\n\t\t\t\t<div class=\"sponsor__illus\"><img decoding=\"async\" src=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2024\/05\/french-district-referencez-entreprise_9145233.png\" alt=\"French District\" \/><\/div>\r\n\t\t\t\t<div class=\"sponsor__content\">\r\n\t\t\t\t\t<p class=\"sponsor__title\">French District<\/p>\r\n\t\t\t\t\t<div class=\"sponsor__slogan\">French District : Le lien entre les entreprises et les expatri\u00e9s.<\/div>\r\n\t\t\t\t\t<div class=\"vce-button vce-button--small\" style=\"background-color: #444444;\"><i class=\"fa fa-hand-o-right\" aria-hidden=\"true\">&nbsp;<\/i>French District<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\t\t\r\n\t\t<\/div>\r\n\t<\/div><strong>Les bourses et les subventions<\/strong> ne sont pas remboursables, contrairement aux emprunts. Leur diff\u00e9rence r\u00e9side dans la source dont provient l\u2019argent ; pour les <strong>bourses,<\/strong> c\u2019est de l\u2019\u00e9cole m\u00eame ou bien de donneurs priv\u00e9s (qui donnent g\u00e9n\u00e9ralement leur nom \u00e0 la bourse), et pour les <strong>subventions,<\/strong> c\u2019est de l\u2019Etat ou de la part d&#8217;institutions.<\/p>\n<p>Les bourses sont attribu\u00e9es suivant les besoins de l\u2019\u00e9l\u00e8ve, ses m\u00e9rites ou encore son appartenance \u00e0 une certaine cat\u00e9gorie d\u2019individus (m\u00e8res c\u00e9libataires, les membres d\u2019une minorit\u00e9 ethnique, les familles en extr\u00eame difficult\u00e9 financi\u00e8re).<\/p>\n<p>Chaque \u00e9cole g\u00e8re ses propres ressources, il y aura donc des bourses attribu\u00e9es pour les \u00e9l\u00e8ves en \u00e9cole d\u2019ing\u00e9nieur, de droit, de m\u00e9decine, d\u2019aviation\u2026<\/p>\n<p>Les \u00e9tablissements se fondent sur les <strong>r\u00e9sultats acad\u00e9miques<\/strong> de l\u2019\u00e9l\u00e8ve bien s\u00fbr, mais aussi sur son engagement aupr\u00e8s d\u2019associations, sa qualit\u00e9 de sportif de haut niveau ou ses habilit\u00e9s artistiques. Certaines \u00e9coles sont de v\u00e9ritables d\u00e9nicheuses de talents potentiels, ce qui cultive une ambiance comp\u00e9titive.<\/p>\n<p>Si l\u2019on ne vient pas vers vous, vous pouvez toujours en faire la demande \u2013 le plus t\u00f4t est le mieux \u2013 et les crit\u00e8res de qualification sont assez rigides. Il est conseill\u00e9 d\u2019aller v\u00e9rifier auparavant sur le site de l\u2019\u00e9tablissement s\u2019il offre bien des bourses.<\/p>\n<p>Les <strong>subventions<\/strong> sont quant \u00e0 elles octroy\u00e9es par l\u2019Etat ou des institutions. Tout \u00e9l\u00e8ve am\u00e9ricain doit d&#8217;abord compl\u00e9ter le formulaire <strong>FAFSA<\/strong> (<i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"https:\/\/studentaid.gov\/h\/apply-for-aid\/fafsa\" target=\"_blank\" rel=\"noopener noreferrer\">StudentAid.gov<\/a>) afin de d\u00e9terminer l\u2019aide financi\u00e8re dont il peut b\u00e9n\u00e9ficier. Le site FAFSA offre par ailleurs de nombreux renseignements sur toutes les possibilit\u00e9s d\u2019<strong>aides financi\u00e8res<\/strong>.<\/p>\n<p>Les subventions elles aussi sont attribu\u00e9es suivant les besoins, les m\u00e9rites ou l\u2019appartenance \u00e0 une minorit\u00e9. Une des plus renomm\u00e9es est la <strong>Pell Grant,<\/strong> accord\u00e9e par le Gouvernement :<br \/>\n<i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"https:\/\/studentaid.gov\/understand-aid\/types\/grants\/pell\" target=\"_blank\" rel=\"noopener noreferrer\">StudentAid.gov<\/a><\/p>\n<h3>Pr\u00eat<\/h3>\n<p>L&#8217;autre possibilit\u00e9 de financer ses \u00e9tudes est de contracter un <strong>pr\u00eat \u00e9tudiant.<\/strong> Les pr\u00eats \u00e9tatiques sont plus avantageux que ceux \u00e9manant de banques ou d\u2019institutions financi\u00e8res priv\u00e9es car ils sont plus facilement payables.<\/p>\n<p>Tout d\u2019abord, leur remboursement ne commence \u00e0 courir que six mois apr\u00e8s la graduation, ce qui laisse le temps \u00e0 l\u2019\u00e9tudiant de trouver un emploi (mais pas trop non plus). Ces pr\u00eats ont \u00e9galement un <strong>taux d\u2019int\u00e9r\u00eat fixe<\/strong> et diff\u00e9rentes modalit\u00e9s de paiement ; travailler pour le gouvernement pendant 10 ans et il sera \u00ab\u00a0<em>oubli\u00e9<\/em>\u00a0\u00bb, ou rembourser en affectant seulement 10% de son salaire\u2026<\/p>\n<p>Pour plus d\u2019informations, voici le site officiel : <i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"https:\/\/studentaid.gov\/understand-aid\/types\/loans\" target=\"_blank\" rel=\"noopener noreferrer\">StudentAid.gov<\/a>.<\/p>\n<p>L&#8217;\u00e9tudiant fra\u00eechement actif peut \u00e9galement souscrire \u00e0 un paiement mensuel de sa tuition, apr\u00e8s s\u2019\u00eatre renseign\u00e9 aupr\u00e8s de son \u00e9cole.<\/p>\n<p>Malheureusement pour les portefeuilles, le budget ne se limite pas \u00e0 la tuition mais comprend \u00e9galement les diff\u00e9rentes d\u00e9penses n\u00e9cessaires \u00e0 sa survie dans la jungle capitaliste du campus (assurances, livres, parking, argent de poche \u2026).<\/p>\n<i class=\"fa fa-exclamation-triangle\" aria-hidden=\"true\"><\/i> Attention, les <strong>universit\u00e9s priv\u00e9es<\/strong> incluent g\u00e9n\u00e9ralement automatiquement l\u2019assurance dans les d\u00e9penses n\u00e9cessaires, et il appartient \u00e0 l\u2019\u00e9tudiant de l\u2019annuler s&#8217;il dispose d\u00e9j\u00e0 d&#8217;une protection.<\/p>\n<p>Concernant les livres, il existe au sein de la plupart des universit\u00e9s des sites Internet afin de les acheter d\u2019occasion \u00e0 d\u2019anciens \u00e9l\u00e8ves ou tout simplement eBay ou Amazon. Fins de mois parfois difficiles\u00a0? Les <strong>campus<\/strong> proposent de nombreux jobs pour leurs \u00e9tudiants, dans presque tous les domaines.<\/p>\n<h2>Et pour les \u00e9tudiants \u00e9trangers<\/h2>\n\r\n\t<div class=\"sponsor__article sponsor__article--right\">\r\n\t\t<div class=\"inner\">\r\n\t\t\t<div class=\"sponsor__by\">Pr&eacute;sent&eacute; par...<\/div>\r\n\t\t\t<div>\r\n\t\t\t\t<a href=\"https:\/\/frenchdistrict.com\/presentez-entreprise\/\" target=\"_blank\">\r\n\t\t\t\t<div class=\"sponsor__illus\"><img decoding=\"async\" src=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2024\/05\/french-district-referencez-entreprise_9145233.png\" alt=\"French District\" \/><\/div>\r\n\t\t\t\t<div class=\"sponsor__content\">\r\n\t\t\t\t\t<p class=\"sponsor__title\">French District<\/p>\r\n\t\t\t\t\t<div class=\"sponsor__slogan\">French District : Le lien entre les entreprises et les expatri\u00e9s.<\/div>\r\n\t\t\t\t\t<div class=\"vce-button vce-button--small\" style=\"background-color: #444444;\"><i class=\"fa fa-hand-o-right\" aria-hidden=\"true\">&nbsp;<\/i>French District<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\t\t\r\n\t\t<\/div>\r\n\t<\/div>Toutes ces informations concernent les <strong>\u00e9tudiants am\u00e9ricains<\/strong> (<i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"http:\/\/frenchdistrict.com\/articles\/vie-etudiant-etudier-campus-universite-americain-informations\/\" rel=\"noopener\">la vie \u00e9tudiante am\u00e9ricaine<\/a>) ayant les visas n\u00e9cessaires pour \u00e9tudier sur le sol am\u00e9ricain. Pour les <strong>\u00e9tudiants \u00e9trangers<\/strong>, il est recommand\u00e9 d\u2019aller sur le site de la future universit\u00e9 afin d\u2019en \u00e9tudier les conditions. Un des programmes d\u2019aide financi\u00e8re les plus connus est Fulbright, voir plus d\u2019infos sur le site <i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"https:\/\/eca.state.gov\/fulbright\" target=\"_blank\" rel=\"noopener noreferrer\">Eca.State.gov\/Fulbright<\/a>.<\/p>\n<p><strong>Lire aussi : <a href=\"https:\/\/frenchdistrict.com\/articles\/obtenir-visa-f1-etudiant-etats-unis-etudier-universite-americaine\/\"><i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> \u00c9tudier aux \u00c9tats-Unis avec le visa F1<\/a><\/strong><\/p>\n<p>Ces demandes sont g\u00e9n\u00e9ralement \u00e0 effectuer chaque ann\u00e9e, notamment pour les subventions \u00e9tatiques car les revenus d\u2019une famille varient d\u2019une ann\u00e9e \u00e0 l\u2019autre.<\/p>\n<p><strong>Les inscriptions<\/strong>\u00a0: On ne ch\u00f4me pas ! L\u2019ann\u00e9e scolaire d\u00e9bute g\u00e9n\u00e9ralement en ao\u00fbt pour s\u2019achever en juin. Comment choisir son \u00e9cole ? On peut en v\u00e9rifier le classement sur le site <i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"https:\/\/www.timeshighereducation.com\/world-university-rankings\/latest\/world-ranking\" target=\"_blank\" rel=\"noopener noreferrer\">TimesHigherEducation.com<\/a> ou faire une recherche par \u00e9cole sur le site USNews (classement \u00e9coles de droit : <i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"https:\/\/www.usnews.com\/best-graduate-schools\/top-law-schools\" target=\"_blank\" rel=\"noopener noreferrer\">UsNews.com\/best-graduate-schools<\/a>, ou pour une recherche <i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"https:\/\/www.usnews.com\/rankings\" target=\"_blank\" rel=\"noopener noreferrer\">UsNews.com\/Rankings<\/a>).<\/p>\n<p><strong>Lire aussi : <i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"http:\/\/frenchdistrict.com\/articles\/top-5-meilleures-universites-americaines-histoire\/\">Le top 5 des universit\u00e9s am\u00e9ricaines<\/a><\/strong><\/p>\n<p>Avoir fait une <em>undergraduate school<\/em> dans un Etat et venir \u00e0 l\u2019universit\u00e9 dans un autre ne pose aucun probl\u00e8me ; il faut cependant s\u2019assurer auparavant de bien remplir les conditions n\u00e9cessaires \u00e0 son inscription (notamment en terme de cr\u00e9dits).<\/p>\n<p>Attention toutefois concernant les futurs \u00e9tudiants toujours \u00e0 l\u2019\u00e9tranger et qui ne souhaitent venir aux <strong>\u00c9tats-Unis<\/strong> qu\u2019\u00e0 partir de l\u2019universit\u00e9. Ils doivent fournir une transcription de tous leurs dipl\u00f4mes et de toutes leurs notes, le tout effectu\u00e9 par un traducteur asserment\u00e9 et agr\u00e9e par le gouvernement am\u00e9ricain (en g\u00e9n\u00e9ral la liste de ces interpr\u00e8tes se trouvent sur le site de l\u2019ambassade des <strong>\u00c9tats-Unis<\/strong>, vous pouvez voir aussi notre article d\u00e9di\u00e9 \u00e0 <i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"http:\/\/frenchdistrict.com\/articles\/reconnaissance-equivalence-diplomes\/\" rel=\"noopener\">l&#8217;\u00e9quivalence des dipl\u00f4mes aux \u00c9tats-Unis<\/a>). Il est conseill\u00e9 de pr\u00e9voir quelques mois de pr\u00e9paration afin d\u2019avoir tous ses papiers en ordre.<\/p>\n<h3>Vous souhaitez des conseils pour entrer dans les universit\u00e9s am\u00e9ricaines? Contactez nous.<\/h3>\n<p><span style=\"font-weight: 400;\"><a name=\"contactfd\" style=\"display: block;position: relative;top: -150px;visibility: hidden;\"><\/a><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_6' ><div id='gf_6' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_6' id='gform_6'  action='\/californie-sud\/wp-json\/wp\/v2\/posts\/19200#gf_6' data-formid='6' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_6' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_6_7\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_7'>URL<\/label><div class='ginput_container'><input name='input_7' id='input_6_7' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_6_7'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_6_1\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_1'>Votre nom:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_6_1' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_6_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_2'>Votre adresse Email:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_6_2' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_6_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_3'>Votre t\u00e9l\u00e9phone:<\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_6_3' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_6_4\" class=\"gfield gfield--type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_4'>Votre message:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_6_4' class='textarea medium'   maxlength='800'  aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_6_5\" class=\"gfield gfield--type-checkbox gfield--type-choice field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_6_5'><li class='gchoice gchoice_6_5_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.1' type='checkbox'  value='Je souhaite m&#039;abonner \u00e0 la newsletter French District Californie Sud et recevoir des bons plans' checked='checked' id='choice_6_5_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_6_5_1' id='label_6_5_1' class='gform-field-label gform-field-label--type-inline'>Je souhaite m'abonner \u00e0 la newsletter French District Californie Sud et recevoir des bons plans<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_6_6\" class=\"gfield gfield--type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text' for='input_6_6'><\/label><div id='input_6_6' class='ginput_container ginput_recaptcha' data-sitekey='6Ldt8T8pAAAAAGjed3W4for4vBHh05M38nSQGx0t'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_6' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Envoyer'  \/> <input type='hidden' name='gform_ajax' value='form_id=6&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=1fca562c281bf1e1ed9ba3caa16c30d8' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_6' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_6' id='gform_theme_6' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_6' id='gform_style_settings_6' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_6' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='6' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='6obB8hUzu\/fGWhtH3MBQYRjscjxON2BMgx3xJDSGtr9Onx5heJbHs99JjXmuUpp5q28AcSCLKXXNPr\/I3TUfBL3aFtOixGMRKDkTRdcTXUNMGAg=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_6' value='WyJbXSIsIjYxMWFmYjlmMzI4ZTI4YmYzMThjYTg1MDIyODQ0YTljIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_6' id='gform_target_page_number_6' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_6' id='gform_source_page_number_6' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_6' id='gform_ajax_frame_6' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 6, 'https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_6').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_6');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_6').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_6').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_6').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_6').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_6').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_6').val();gformInitSpinner( 6, 'https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [6, current_page]);window['gf_submitting_6'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_6').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_6').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [6]);window['gf_submitting_6'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_6').text());}else{jQuery('#gform_6').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"6\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_6\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_6\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_6\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 6, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le syst\u00e8me \u00e9ducatif High School, College, University\u2026 Quelle diff\u00e9rence ? A leur sortie de la middle school (4\u00e8me en France), les coll\u00e9giens entrent au lyc\u00e9e (High School) o\u00f9 ils \u00e9tudient 4 ans. Chaque \u00e9tudiant passe ensuite le SAT qui teste la lecture, les math\u00e9matiques, et l\u2019\u00e9crit, ou le ACT pour l\u2019anglais, les maths, la lecture [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":170849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1957,284],"tags":[286,287,822,992,386,788],"class_list":["post-19200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education-etats-unis","category-nouveaux-arrivants","tag-ecole","tag-etudiant","tag-etudier","tag-financement","tag-rentree-scolaire","tag-universite"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Universit\u00e9 aux Etats-Unis - Tout savoir sur l&#039;universit\u00e9 am\u00e9ricaine<\/title>\n<meta name=\"description\" content=\"L\u2019enseignement sup\u00e9rieur am\u00e9ricain fait r\u00eaver, mais il s\u2019organise. Il existe des diff\u00e9rences importantes entre le Public et le Priv\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Universit\u00e9 aux Etats-Unis - Tout savoir sur l&#039;universit\u00e9 am\u00e9ricaine\" \/>\n<meta property=\"og:description\" content=\"L\u2019enseignement sup\u00e9rieur am\u00e9ricain fait r\u00eaver, mais il s\u2019organise. Il existe des diff\u00e9rences importantes entre le Public et le Priv\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"Californie Sud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frenchdistrict\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-18T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-31T14:01:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/07\/universite-americaine-college-fonctionnement-usa-une.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tZaFNBo4R9Yh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:site\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"tZaFNBo4R9Yh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/\",\"url\":\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/\",\"name\":\"Universit\u00e9 aux Etats-Unis - Tout savoir sur l'universit\u00e9 am\u00e9ricaine\",\"isPartOf\":{\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2025\/01\/universite-americaine-college-fonctionnement-usa-une_7615306.jpg\",\"datePublished\":\"2013-06-18T04:00:00+00:00\",\"dateModified\":\"2025-01-31T14:01:35+00:00\",\"author\":{\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"description\":\"L\u2019enseignement sup\u00e9rieur am\u00e9ricain fait r\u00eaver, mais il s\u2019organise. Il existe des diff\u00e9rences importantes entre le Public et le Priv\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/#primaryimage\",\"url\":\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2025\/01\/universite-americaine-college-fonctionnement-usa-une_7615306.jpg\",\"contentUrl\":\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2025\/01\/universite-americaine-college-fonctionnement-usa-une_7615306.jpg\",\"width\":\"1600\",\"height\":\"1067\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Californie Sud\",\"item\":\"https:\/\/frenchdistrict.com\/californie-sud\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Standard\",\"item\":\"https:\/\/frenchdistrict.com\/californie-sud\/listing_type\/standard\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L&#8217;universit\u00e9 am\u00e9ricaine \u2013 comment \u00e7a marche\u00a0?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/#website\",\"url\":\"https:\/\/frenchdistrict.com\/californie-sud\/\",\"name\":\"Californie Sud\",\"description\":\"Le meilleur de la &lt;span&gt;Californie du Sud&lt;\/span&gt; par ceux qui y vivent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/frenchdistrict.com\/californie-sud\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010\",\"name\":\"tZaFNBo4R9Yh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/frenchdistrict.com\/californie-sud\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"caption\":\"tZaFNBo4R9Yh\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Universit\u00e9 aux Etats-Unis - Tout savoir sur l'universit\u00e9 am\u00e9ricaine","description":"L\u2019enseignement sup\u00e9rieur am\u00e9ricain fait r\u00eaver, mais il s\u2019organise. Il existe des diff\u00e9rences importantes entre le Public et le Priv\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/","og_locale":"fr_FR","og_type":"article","og_title":"Universit\u00e9 aux Etats-Unis - Tout savoir sur l'universit\u00e9 am\u00e9ricaine","og_description":"L\u2019enseignement sup\u00e9rieur am\u00e9ricain fait r\u00eaver, mais il s\u2019organise. Il existe des diff\u00e9rences importantes entre le Public et le Priv\u00e9.","og_url":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/","og_site_name":"Californie Sud","article_publisher":"https:\/\/www.facebook.com\/frenchdistrict","article_published_time":"2013-06-18T04:00:00+00:00","article_modified_time":"2025-01-31T14:01:35+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/07\/universite-americaine-college-fonctionnement-usa-une.jpg","type":"image\/jpeg"}],"author":"tZaFNBo4R9Yh","twitter_card":"summary_large_image","twitter_creator":"@frenchdistrict","twitter_site":"@frenchdistrict","twitter_misc":{"\u00c9crit par":"tZaFNBo4R9Yh","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/","url":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/","name":"Universit\u00e9 aux Etats-Unis - Tout savoir sur l'universit\u00e9 am\u00e9ricaine","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/#primaryimage"},"image":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2025\/01\/universite-americaine-college-fonctionnement-usa-une_7615306.jpg","datePublished":"2013-06-18T04:00:00+00:00","dateModified":"2025-01-31T14:01:35+00:00","author":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"description":"L\u2019enseignement sup\u00e9rieur am\u00e9ricain fait r\u00eaver, mais il s\u2019organise. Il existe des diff\u00e9rences importantes entre le Public et le Priv\u00e9.","breadcrumb":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/#primaryimage","url":"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2025\/01\/universite-americaine-college-fonctionnement-usa-une_7615306.jpg","contentUrl":"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2025\/01\/universite-americaine-college-fonctionnement-usa-une_7615306.jpg","width":"1600","height":"1067"},{"@type":"BreadcrumbList","@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/universite-americaine-college-fonctionnement-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Californie Sud","item":"https:\/\/frenchdistrict.com\/californie-sud\/"},{"@type":"ListItem","position":2,"name":"Standard","item":"https:\/\/frenchdistrict.com\/californie-sud\/listing_type\/standard\/"},{"@type":"ListItem","position":3,"name":"L&#8217;universit\u00e9 am\u00e9ricaine \u2013 comment \u00e7a marche\u00a0?"}]},{"@type":"WebSite","@id":"https:\/\/frenchdistrict.com\/californie-sud\/#website","url":"https:\/\/frenchdistrict.com\/californie-sud\/","name":"Californie Sud","description":"Le meilleur de la &lt;span&gt;Californie du Sud&lt;\/span&gt; par ceux qui y vivent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchdistrict.com\/californie-sud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/frenchdistrict.com\/californie-sud\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010","name":"tZaFNBo4R9Yh","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/californie-sud\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","caption":"tZaFNBo4R9Yh"}}]}},"_links":{"self":[{"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/posts\/19200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/comments?post=19200"}],"version-history":[{"count":9,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/posts\/19200\/revisions"}],"predecessor-version":[{"id":170848,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/posts\/19200\/revisions\/170848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/media\/170849"}],"wp:attachment":[{"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/media?parent=19200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/categories?post=19200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/tags?post=19200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}