{"id":83860,"date":"2020-05-04T15:16:48","date_gmt":"2020-05-04T22:16:48","guid":{"rendered":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/\/"},"modified":"2023-08-30T04:14:33","modified_gmt":"2023-08-30T11:14:33","slug":"quartiers-immobilier-haut-de-gamme-los-angeles","status":"publish","type":"post","link":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/","title":{"rendered":"O\u00f9 sont les plus belles propri\u00e9t\u00e9s de Los Angeles ?"},"content":{"rendered":"<h2>La vie des stars : au c\u0153ur des quartiers branch\u00e9s \u00e0 Los Angeles<\/h2>\n<p>Elles sont des dizaines d\u00e9j\u00e0 bien connues, des centaines en devenir, des milliers qui ne le savent m\u00eame pas : les <strong>c\u00e9l\u00e9brit\u00e9s<\/strong>. Elles ont, depuis presque 100 ans, \u00e9lu domicile \u00e0<strong> Los Angeles<\/strong>, et restent particuli\u00e8rement friandes de certains <strong>quartiers branch\u00e9s \u00e0 LA<\/strong>.<\/p>\n<p>D&#8217;abord, l\u2019un des plus connus et<strong> <a href=\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/visiter-beverly-hills-rues-los-angeles-tourisme\/\" target=\"_blank\" rel=\"noopener noreferrer\">symbole incontestable du luxe dans le monde entier : Beverly Hills<\/a><\/strong>. L\u00e0,<strong> les plus belles villas haut de gamme<\/strong>, avec suffisamment de chambres pour loger une \u00e9quipe de foot, sont list\u00e9es au prix du salaire annuel d\u2019un joueur de ballon rond (pas de D2 \u00e9videmment). C&#8217;est-\u00e0-dire entre <strong>25 et 30 millions de dollars<\/strong> pour ceux qui ne lisent pas l\u2019\u00c9quipe. Le march\u00e9 immobilier haut de gammer \u00e0 Beverly Hills est aussi compos\u00e9 de <strong>villas<\/strong> plus &#8220;modestes&#8221;, \u00e0 vendre pour<strong> 2,5 \u00e0 4 millions de dollars.<\/strong> Mais, ne vous plaignez pas de ne pas avoir de piscine.<\/p>\n<p>A vol de jet, <strong>Sunset Strip<\/strong> est r\u00e9put\u00e9 pour avoir la plus grande concentration de <strong>c\u00e9l\u00e9brit\u00e9s<\/strong> au m\u00e8tre carr\u00e9. On y trouve des <strong>maisons<\/strong> sobres, avec parfois une vue infinie sur la ville, pour <strong>1 million de dollars<\/strong> environ. Elles se situent dans les petites rues perpendiculaires car, sur le<strong> strip<\/strong>, il n\u2019y a gu\u00e8re que des bars, clubs, boutiques, restaurants et h\u00f4tels. Ces <strong>maisons<\/strong> sont souvent destin\u00e9es \u00e0 accueillir un couple et un enfant &#8211; ou un couple qui travaille beaucoup et tient \u00e0 son bureau.<\/p>\n<i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> Lire aussi <strong>: <a href=\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/los-angeles-sunset-strip-visite-incontournables-hollywood\/\" target=\"_blank\" rel=\"noopener noreferrer\">Les incontournables du Sunset Strip\u00a0<\/a><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-83890\" src=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-2.jpg\" alt=\"immobilier-haut-de-gamme-los-angeles (2)\" width=\"750\" height=\"350\" srcset=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-2.jpg 750w, https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-2-300x140.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2>Vue mer : les villas les pieds dans l\u2019eau \u00e0 Los Angeles<\/h2>\n<p>Totalement \u00e0 l\u2019ouest, sur l\u2019Oc\u00e9an Pacifique, les villes et quartiers c\u00f4tiers sont synonymes de <strong>villas haut de gamme, <\/strong>modernes ou de style toscan. G\u00e9n\u00e9ralement, elles sont plant\u00e9es sur des lots de sable, avec un <a href=\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/el-matador-state-beach-malibu-plage-cote-ouest-los-angeles\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>acc\u00e8s direct aux plages<\/strong><\/a>. Ces petits <strong>bijoux immobliers haut de gamme<\/strong> sont \u00e0 vendre \u00e0 <strong>Malibu<\/strong> pour <strong>6 \u00e0\u2026 30 millions de dollars<\/strong>. Et, <strong>les plus ch\u00e8res propri\u00e9t\u00e9s \u00e0 Malibu<\/strong> ont la panoplie de l\u2019opulence : salle de cin\u00e9, gym, bureau, chemin\u00e9es et cuisine de Chef.<\/p>\n<p>Juste pour votre information, <b>le<\/b>\u00a0<strong>march\u00e9 immobilier haut de gamme de Malibu <\/strong>est\u00a0ax\u00e9 sur les <strong>r\u00e9sidences de luxe<\/strong> (on parle de 10 millions de dollars et plus). Il en propose en moyenne entre 40 et 45 \u00e0 la vente r\u00e9guli\u00e8rement. Le<strong> prix moyen des maisons<\/strong> <strong>haut de gamme \u00e0 Malibu <\/strong>est de<strong> 3.3 millions de dollars<\/strong>. Par ailleurs, en F\u00e9vrier 2020, une \u201c<strong><em>mega mansion<\/em><\/strong>\u201d de plus de 1 000 m2 habitables avec <strong>plage priv\u00e9e<\/strong> a \u00e9t\u00e9 mise en vente \u00e0 115 millions de dollars.<\/p>\n<p>En outre, au sud, <strong><a href=\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/ocean-frontwalk-venice-santa-monica-plage-sable-photos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Santa Monica a des allures de ville de vacances.<\/a><\/strong> Ses rues commer\u00e7antes, ses bureaux modernes et sa plage \u00e0 2 p\u00e2t\u00e9s (de sable) donnent tout le charme au <a href=\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/journee-visiter-decouvrir-santa-monica\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>centre-ville<\/strong> <strong>de Santa Monica<\/strong><\/a>. L\u00e0, les<strong> maisons<\/strong> <strong>de 2 chambres \u00e0 Santa Monica<\/strong>\u00a0sont \u00e0 vendre pour 1 \u00e0 2 millions de dollars, avec la certitude de vous y plaire. Les prix sont identiques chez sa voisine <strong>Venice.<\/strong> Sauf si vous souhaitez vivre pr\u00e8s des <a href=\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/canaux-venice-italien-los-angeles\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>canaux de Venice<\/strong><\/a>, auquel cas les prix pour un bien immobilier haut de gamme grimpent de pr\u00e8s du double.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-83891\" src=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-5.jpg\" alt=\"immobilier-haut-de-gamme-los-angeles (5)\" width=\"750\" height=\"350\" srcset=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-5.jpg 750w, https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-5-300x140.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2>Entre mer et montagne : les propri\u00e9t\u00e9s haut de gamme perch\u00e9es de Los Angeles<\/h2>\n<p>Si vous n\u2019avez pas vraiment le pied marin et d\u00e9j\u00e0 suffisamment d\u2019autographes pour tapisser vos murs, direction les hauteurs!\u00a0 L\u00e0, la vie s\u2019\u00e9coule dans des <strong>quartiers r\u00e9sidentiels tranquilles<\/strong> avec vue \u00e0 couper le souffle sur la ville et\/ou sur l\u2019oc\u00e9an. Par exemple, <strong>Pacific Palisades<\/strong> est le <strong>quartier favori des familles<\/strong> en raison de son excellent syst\u00e8me \u00e9ducatif. Il est compos\u00e9 de <strong>maisons r\u00e9sidentielles<\/strong> plus modestes (entre 800,000 et 2 millions de dollars) et d\u2019imposantes <strong>villas<\/strong> situ\u00e9es dans les collines.<\/p>\n<p>Enfin, plus loin, \u00e0 <strong>Bel Air<\/strong>, quartier o\u00f9 les revenus familiaux sont parmi les plus \u00e9lev\u00e9s de la r\u00e9gion angeline, l\u2019ambiance est \u00e9galement familiale. Vous partagerez votre quotidien avec moins de 10,000 personnes. L\u00e0 encore, la diff\u00e9rence entre les <strong>maisons modestes et les<\/strong> <strong>villas haut-de-gamme<\/strong> est flagrante. En effet, les prix des <strong>villas haut de gamme <\/strong>s\u2019envolent vers les 20 millions de dollars. Mais, il s&#8217;agit de propri\u00e9t\u00e9s ultra \u00e9quip\u00e9es.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-83889\" src=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-4.jpg\" alt=\"immobilier-haut-de-gamme-los-angeles (4)\" width=\"750\" height=\"350\" srcset=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-4.jpg 750w, https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-4-300x140.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h3>Vous souhaitez investir dans l&#8217;immobilier haut de gamme \u00e0 Los Angeles?<br \/>\n\u00c9crivez-nous!<\/h3>\n<p><span style=\"font-weight: 400;\"><a name=\"contactfd\" style=\"display: block;position: relative;top: -150px;visibility: hidden;\"><\/a><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_6' ><div id='gf_6' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_6' id='gform_6'  action='\/californie-sud\/wp-json\/wp\/v2\/posts\/83860#gf_6' data-formid='6' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_6' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_6_7\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_7'>Company<\/label><div class='ginput_container'><input name='input_7' id='input_6_7' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_6_7'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_6_1\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_1'>Votre nom:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_6_1' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_6_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_2'>Votre adresse Email:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_6_2' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_6_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_3'>Votre t\u00e9l\u00e9phone:<\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_6_3' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_6_4\" class=\"gfield gfield--type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_4'>Votre message:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_6_4' class='textarea medium'   maxlength='800'  aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_6_5\" class=\"gfield gfield--type-checkbox gfield--type-choice field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_6_5'><li class='gchoice gchoice_6_5_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.1' type='checkbox'  value='Je souhaite m&#039;abonner \u00e0 la newsletter French District Californie Sud et recevoir des bons plans' checked='checked' id='choice_6_5_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_6_5_1' id='label_6_5_1' class='gform-field-label gform-field-label--type-inline'>Je souhaite m'abonner \u00e0 la newsletter French District Californie Sud et recevoir des bons plans<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_6_6\" class=\"gfield gfield--type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text' for='input_6_6'><\/label><div id='input_6_6' class='ginput_container ginput_recaptcha' data-sitekey='6Ldt8T8pAAAAAGjed3W4for4vBHh05M38nSQGx0t'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_6' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Envoyer'  \/> <input type='hidden' name='gform_ajax' value='form_id=6&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=1fca562c281bf1e1ed9ba3caa16c30d8' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_6' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_6' id='gform_theme_6' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_6' id='gform_style_settings_6' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_6' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='6' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='osTFXkFXTc4JKahcdca5omFyvyrOtBuwps1P9Oom0gZH9A4vwPf+ZcNJe9T7FZWds9wjYcRQFXngqcdYAFx8wJbIIZhdRghBwbuIsNvfZulaBs0=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_6' value='WyJbXSIsIjYxMWFmYjlmMzI4ZTI4YmYzMThjYTg1MDIyODQ0YTljIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_6' id='gform_target_page_number_6' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_6' id='gform_source_page_number_6' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_6' id='gform_ajax_frame_6' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 6, 'https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_6').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_6');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_6').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_6').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_6').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_6').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_6').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_6').val();gformInitSpinner( 6, 'https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [6, current_page]);window['gf_submitting_6'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_6').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_6').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [6]);window['gf_submitting_6'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_6').text());}else{jQuery('#gform_6').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"6\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_6\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_6\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_6\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 6, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vie des stars : au c\u0153ur des quartiers branch\u00e9s \u00e0 Los Angeles Elles sont des dizaines d\u00e9j\u00e0 bien connues, des centaines en devenir, des milliers qui ne le savent m\u00eame pas : les c\u00e9l\u00e9brit\u00e9s. Elles ont, depuis presque 100 ans, \u00e9lu domicile \u00e0 Los Angeles, et restent particuli\u00e8rement friandes de certains quartiers branch\u00e9s \u00e0 [&hellip;]<\/p>\n","protected":false},"author":8238,"featured_media":83888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[262,930,1959],"tags":[748,1936,1443,1938,1937,1940,1939],"class_list":["post-83860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chut-secrets","category-monde-expatriation","category-immobilier-etats-unis","tag-celebrites","tag-maisons","tag-marche-immobilier","tag-ocean-pacifique","tag-proprietes","tag-villas","tag-vue-mer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u25b7 O\u00f9 se situe l&#039;immobilier haut de gamme \u00e0 Los Angeles ?<\/title>\n<meta name=\"description\" content=\"On vous emm\u00e8ne faire le tour des quartiers de Los Angeles o\u00f9 investir dans l&#039;immobilier haut de gamme. Vous \u00eates plut\u00f4t maison moderne ou villa d&#039;exception?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u25b7 O\u00f9 se situe l&#039;immobilier haut de gamme \u00e0 Los Angeles ?\" \/>\n<meta property=\"og:description\" content=\"On vous emm\u00e8ne faire le tour des quartiers de Los Angeles o\u00f9 investir dans l&#039;immobilier haut de gamme. Vous \u00eates plut\u00f4t maison moderne ou villa d&#039;exception?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/\" \/>\n<meta property=\"og:site_name\" content=\"Californie Sud\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frenchdistrict\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-04T22:16:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-30T11:14:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"laure\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:site\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"laure\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/\"},\"author\":{\"name\":\"laure\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/#\\\/schema\\\/person\\\/c290d2275f409e11be6d391a68ad4c1e\"},\"headline\":\"O\u00f9 sont les plus belles propri\u00e9t\u00e9s de Los Angeles ?\",\"datePublished\":\"2020-05-04T22:16:48+00:00\",\"dateModified\":\"2023-08-30T11:14:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/\"},\"wordCount\":733,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2020\\\/05\\\/immobilier-haut-de-gamme-los-angeles-1.jpg\",\"keywords\":[\"c\u00e9l\u00e9brit\u00e9s\",\"maisons\",\"march\u00e9 immobilier\",\"ocean pacifique\",\"proprietes\",\"villas\",\"vue mer\"],\"articleSection\":[\"Coups de coeur\",\"Expatriation\",\"Immobilier\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/\",\"name\":\"\u25b7 O\u00f9 se situe l'immobilier haut de gamme \u00e0 Los Angeles ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2020\\\/05\\\/immobilier-haut-de-gamme-los-angeles-1.jpg\",\"datePublished\":\"2020-05-04T22:16:48+00:00\",\"dateModified\":\"2023-08-30T11:14:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/#\\\/schema\\\/person\\\/c290d2275f409e11be6d391a68ad4c1e\"},\"description\":\"On vous emm\u00e8ne faire le tour des quartiers de Los Angeles o\u00f9 investir dans l'immobilier haut de gamme. Vous \u00eates plut\u00f4t maison moderne ou villa d'exception?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2020\\\/05\\\/immobilier-haut-de-gamme-los-angeles-1.jpg\",\"contentUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2020\\\/05\\\/immobilier-haut-de-gamme-los-angeles-1.jpg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/articles\\\/quartiers-immobilier-haut-de-gamme-los-angeles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Californie Sud\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coups de coeur\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/chut-secrets\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"O\u00f9 sont les plus belles propri\u00e9t\u00e9s de Los Angeles ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/#website\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/\",\"name\":\"Californie Sud\",\"description\":\"Le meilleur de la &lt;span&gt;Californie du Sud&lt;\\\/span&gt; par ceux qui y vivent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/californie-sud\\\/#\\\/schema\\\/person\\\/c290d2275f409e11be6d391a68ad4c1e\",\"name\":\"laure\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g\",\"caption\":\"laure\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 O\u00f9 se situe l'immobilier haut de gamme \u00e0 Los Angeles ?","description":"On vous emm\u00e8ne faire le tour des quartiers de Los Angeles o\u00f9 investir dans l'immobilier haut de gamme. Vous \u00eates plut\u00f4t maison moderne ou villa d'exception?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/","og_locale":"fr_FR","og_type":"article","og_title":"\u25b7 O\u00f9 se situe l'immobilier haut de gamme \u00e0 Los Angeles ?","og_description":"On vous emm\u00e8ne faire le tour des quartiers de Los Angeles o\u00f9 investir dans l'immobilier haut de gamme. Vous \u00eates plut\u00f4t maison moderne ou villa d'exception?","og_url":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/","og_site_name":"Californie Sud","article_publisher":"https:\/\/www.facebook.com\/frenchdistrict","article_published_time":"2020-05-04T22:16:48+00:00","article_modified_time":"2023-08-30T11:14:33+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-1.jpg","type":"image\/jpeg"}],"author":"laure","twitter_card":"summary_large_image","twitter_creator":"@frenchdistrict","twitter_site":"@frenchdistrict","twitter_misc":{"\u00c9crit par":"laure","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/#article","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/"},"author":{"name":"laure","@id":"https:\/\/frenchdistrict.com\/californie-sud\/#\/schema\/person\/c290d2275f409e11be6d391a68ad4c1e"},"headline":"O\u00f9 sont les plus belles propri\u00e9t\u00e9s de Los Angeles ?","datePublished":"2020-05-04T22:16:48+00:00","dateModified":"2023-08-30T11:14:33+00:00","mainEntityOfPage":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/"},"wordCount":733,"commentCount":0,"image":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-1.jpg","keywords":["c\u00e9l\u00e9brit\u00e9s","maisons","march\u00e9 immobilier","ocean pacifique","proprietes","villas","vue mer"],"articleSection":["Coups de coeur","Expatriation","Immobilier"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/","url":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/","name":"\u25b7 O\u00f9 se situe l'immobilier haut de gamme \u00e0 Los Angeles ?","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/#primaryimage"},"image":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-1.jpg","datePublished":"2020-05-04T22:16:48+00:00","dateModified":"2023-08-30T11:14:33+00:00","author":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/#\/schema\/person\/c290d2275f409e11be6d391a68ad4c1e"},"description":"On vous emm\u00e8ne faire le tour des quartiers de Los Angeles o\u00f9 investir dans l'immobilier haut de gamme. Vous \u00eates plut\u00f4t maison moderne ou villa d'exception?","breadcrumb":{"@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/#primaryimage","url":"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-1.jpg","contentUrl":"https:\/\/frenchdistrict.com\/californie-sud\/wp-content\/uploads\/sites\/5\/2020\/05\/immobilier-haut-de-gamme-los-angeles-1.jpg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/frenchdistrict.com\/californie-sud\/articles\/quartiers-immobilier-haut-de-gamme-los-angeles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Californie Sud","item":"https:\/\/frenchdistrict.com\/californie-sud\/"},{"@type":"ListItem","position":2,"name":"Coups de coeur","item":"https:\/\/frenchdistrict.com\/californie-sud\/chut-secrets\/"},{"@type":"ListItem","position":3,"name":"O\u00f9 sont les plus belles propri\u00e9t\u00e9s de Los Angeles ?"}]},{"@type":"WebSite","@id":"https:\/\/frenchdistrict.com\/californie-sud\/#website","url":"https:\/\/frenchdistrict.com\/californie-sud\/","name":"Californie Sud","description":"Le meilleur de la &lt;span&gt;Californie du Sud&lt;\/span&gt; par ceux qui y vivent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchdistrict.com\/californie-sud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/frenchdistrict.com\/californie-sud\/#\/schema\/person\/c290d2275f409e11be6d391a68ad4c1e","name":"laure","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/85d71d3d13d3adf6dc6c7c76dd4dcb3c7a344b72d7b137c089c3df43167374c2?s=96&d=mm&r=g","caption":"laure"}}]}},"_links":{"self":[{"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/posts\/83860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/users\/8238"}],"replies":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/comments?post=83860"}],"version-history":[{"count":12,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/posts\/83860\/revisions"}],"predecessor-version":[{"id":158702,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/posts\/83860\/revisions\/158702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/media\/83888"}],"wp:attachment":[{"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/media?parent=83860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/categories?post=83860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchdistrict.com\/californie-sud\/wp-json\/wp\/v2\/tags?post=83860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}