{"id":61608,"date":"2013-07-19T00:00:00","date_gmt":"2013-07-19T04:00:00","guid":{"rendered":"https:\/\/frenchdistrict.com\/floride\/articles\/trousse-medicaments-pharmacie-avoir-etats-unis\/"},"modified":"2025-03-24T10:08:48","modified_gmt":"2025-03-24T14:08:48","slug":"medicaments-etats-unis-equivalent-france-pharmacies","status":"publish","type":"post","link":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/","title":{"rendered":"La trousse de m\u00e9dicaments \u00e0 avoir aux \u00c9tats-Unis"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-172071\" src=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription-224x300.jpg\" alt=\"medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription\" width=\"224\" height=\"300\" srcset=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription-224x300.jpg 224w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription-763x1024.jpg 763w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription-768x1031.jpg 768w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription-1145x1536.jpg 1145w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription-1526x2048.jpg 1526w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription-810x1087.jpg 810w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription-1140x1530.jpg 1140w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription-600x805.jpg 600w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/medicaments-etats-unis-equivalent-france-pharmacies-ordonnance-prescription.jpg 1702w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/p>\n<h2>Petit lexique de la pharmacie made in US<\/h2>\n<p>Aux \u00c9tats-Unis, on distingue les<strong> m\u00e9dicaments<\/strong> en vente libre (<em>Over the counter ou OTC<\/em>) et ceux uniquement d\u00e9livr\u00e9s sur <strong>ordonnance m\u00e9dicale<\/strong> (<em>Prescription ou Rx<\/em>).<\/p>\n<p>Si vous avez un doute sur un produit, si vous n&#8217;arrivez pas \u00e0 choisir (ou \u00e0 traduire) pour construire <strong>votre trousse de m\u00e9dicaments<\/strong>, vous pouvez toujours interroger les blouses blanches qui oeuvrent\u00a0derri\u00e8re le comptoir du fond <a href=\"https:\/\/frenchdistrict.com\/articles\/pharmacies-etats-unis-medicaments-ordonnance-drugstore\/\">de votre CVS ou Walgreens<\/a>. C&#8217;est l\u00e0 aussi que vous devez vous orienter pour la d\u00e9livrance d&#8217;une ordonnance m\u00e9dicale : cherchez le\u00a0<em>Pharmacist Manager<\/em>, le responsable de la pr\u00e9paration de votre traitement, d\u00e9livr\u00e9 pour le nombre strict de jours demand\u00e9s et remis dans un flacon \u00e9tiquet\u00e9 \u00e0 votre nom.<\/p>\n<p><strong>Lire aussi : <a href=\"https:\/\/frenchdistrict.com\/articles\/systeme-sante-americain-securite-sociale-assurances-medicales\/\"><i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> L\u2019assurance sant\u00e9 aux \u00c9tats-Unis<\/a><\/strong><\/p>\n<h3>Bon \u00e0 savoir<\/h3>\n<ul>\n<li>De nombreux <strong>m\u00e9dicaments<\/strong> prescrits sur ordonnance en France sont ici en vente libre (et inversement).<\/li>\n<li>Les dosages et les concentrations ne sont pas les m\u00eames, notamment pour les cr\u00e8mes \u00e0 base de <strong>cortisone<\/strong>.<\/li>\n<li>Les <strong>prix des m\u00e9dicaments<\/strong> et notamment des <strong>antibiotiques<\/strong> sont souvent plus \u00e9lev\u00e9s aux USA qu&#8217;en France (<em>mais \u00e7a, vous le saviez d\u00e9j\u00e0<\/em>).<\/li>\n<\/ul>\n<h2>Les m\u00e9dicaments en vente libre en France sans \u00e9quivalent am\u00e9ricain<\/h2>\n<ul>\n<li>Vous risquez de chercher longtemps du\u00a0<em>TOPLEXIL<\/em>\u00a0contre les toux s\u00e8ches et irritatives dans les rayons des <strong><em>drugstores<\/em> am\u00e9ricains<\/strong> : l&#8217;oxom\u00e9mazine, sa substance active, est interdite aux Etats-Unis. Malheureusement pour vous, les traitements am\u00e9ricains efficaces contre la toux s\u00e8che sont tous sur prescription. A d\u00e9faut, il vous reste les pastilles au miel&#8230;<\/li>\n<li>Pour enrayer un d\u00e9but d&#8217;angine ou un mal \u00e0 la gorge, les suppositoires de\u00a0<em>BIQUINOL<\/em>\u00a0(<em>succinate de bismuth<\/em>) sont efficaces, mais n&#8217;ont pas d&#8217;\u00e9quivalent en vente libre aux Etats-Unis. L\u00e0 encore, \u00e0 moins d&#8217;une ordonnance pour <strong>obtenir des m\u00e9dicaments<\/strong>, il ne vous reste que les pastilles pour adoucir votre voix d&#8217;homme des cavernes et votre gorge en combustion.<\/li>\n<li><em>L&#8217;OTIPAX<\/em>\u00a0qui est un analg\u00e9sique et anesth\u00e9sique local contre les douleurs auriculaires n&#8217;a pas son \u00e9quivalent ici. Il ne fera pas partie de votre <strong>trousse de m\u00e9dicament aux \u00c9tats-Unis<\/strong>, \u00e0 moins de le ramener de France.<\/li>\n<li>Le <strong>traitement des cystites<\/strong> co\u00fbte tr\u00e8s cher aux Etats-Unis&#8230; pr\u00e9voyez toujours dans votre <strong>pharmacie d&#8217;urgence<\/strong> une dose unique de<em>\u00a0MONURIL<\/em>\u00a0(<em>fosfomycine<\/em>), qui co\u00fbte environ 9 euros en France.<\/li>\n<li>Cherche <strong>collutoire<\/strong> d\u00e9sesp\u00e9r\u00e9ment&#8230; Ces m\u00e9dicaments en sprays pour soulager les maux de gorges l\u00e9gers, tels que\u00a0<em>ANGISPRAY<\/em>\u00a0(<em>hex\u00e9tidine<\/em>),\u00a0<em>HEXASPRAY<\/em>\u00a0(<em>biclotymol<\/em>) sont introuvables dans les <em>drugstores<\/em>.<\/li>\n<li>Pour traiter efficacement les poux, les produits fran\u00e7ais sont remarquables. Cependant, le dim\u00e9ticone contenu dans les traitements est pr\u00e9sent en plus faible quantit\u00e9 dans les produits am\u00e9ricains et le\u00a0<em>PRIODERM<\/em>\u00a0\u00e0 base de malathion n&#8217;est pas commercialis\u00e9 aux USA.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-172072\" src=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new-1024x682.jpg\" alt=\"trousse-medicaments-pharmacie-avoir-etats-unis-une-new\" width=\"810\" height=\"539\" srcset=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new-1024x682.jpg 1024w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new-300x200.jpg 300w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new-768x512.jpg 768w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new-810x540.jpg 810w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new-1140x760.jpg 1140w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9091343_7924967_2701773_9099431_9299314.jpg 1600w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/p>\n<h2>Quelques \u00e9quivalents de m\u00e9dicaments fran\u00e7ais<\/h2>\n<h3>Pour la fi\u00e8vre, les douleurs<\/h3>\n<h4>1 &#8211; Doliprane<\/h4>\n<p><em>TYLENOL<\/em>\u00a0: \u00e9quivalent du <strong>Doliprane<\/strong> et autres <strong>m\u00e9dicaments<\/strong> \u00e0 bases de <strong>Parac\u00e9tamol<\/strong>. Les am\u00e9ricains nomme cette mol\u00e9cule : l\u2019acetaminophen. On ne retrouve en revanche pas ces m\u00e9dicaments sous formes effervescentes aux USA. C&#8217;est un v\u00e9ritable pilier de la culture pharmaceutique aux \u00c9tats-Unis. On le trouve partout, des stations-service aux \u00e9piceries !<\/p>\n<h4>2 &#8211; Spasfon<\/h4>\n<p>Il n&#8217;y a malheureusement pas d&#8217;\u00e9quivalent aux Etats-Unis, seul le <strong>Tylenol<\/strong> pourra vous aider \u00e0 r\u00e9duire la douleur.<\/p>\n<h4>3 &#8211; Aspegic<\/h4>\n<p>Son \u00e9quivalent am\u00e9ricain est le <strong>Bayer<\/strong>. On le retrouve sous forme de comprim\u00e9s \u00e0 avaler. Il permet de diminuer les sympt\u00f4mes de fi\u00e8vre et de douleurs.<\/p>\n<h4>4 &#8211; Nurofen<\/h4>\n<p>Les m\u00e9dicaments \u00e0 base d&#8217;ibuprof\u00e8ne (ibuprofen) se vendent libre service dans les pharmacies de type CVS. La marque la plus connue est <strong>Advil ou Motrin<\/strong>.<\/p>\n<h4>5 &#8211; Smecta<\/h4>\n<p>Il n&#8217;existe pas d&#8217;\u00e9quivalent direct avec le Smecta contre la diarrh\u00e9e. Le m\u00e9dicament qui s&#8217;en rapproche le plus est pansement digestif silicon\u00e9, fabriqu\u00e9s et vendus par les marques <strong>Gas-X<\/strong> ou <strong>Phazyme.<\/strong><\/p>\n<h4>6 &#8211; Imodium<\/h4>\n<p>Vous pouvez retrouver ce m\u00e9dicament anti-diarrh\u00e9ique sous le m\u00eame nom dans la plupart des pharmacies de type CVS.<\/p>\n<h4>7 &#8211; Toplexil<\/h4>\n<p>Ce m\u00e9dicament antitussif antihistaminique n&#8217;a pas d&#8217;\u00e9quivalent aux USA, cependant vous pouvez trouver un d\u00e9riv\u00e9 morphinique, <strong>Delsym.<\/strong><\/p>\n<h4>8 &#8211; Mucomyst<\/h4>\n<p>Tres utile en cas de toux, son \u00e9quivalent am\u00e9ricain est le <strong>Mucinex<\/strong>.<\/p>\n<h4>9 &#8211; Humex<\/h4>\n<p>Il existe de nombreux \u00e9quivalents am\u00e9ricains pour Humex, les plus connus : <strong>DayQuil<\/strong> et <strong>NyQuil<\/strong> ou encore<strong>Sudafed<\/strong>.<\/p>\n<h4>10 &#8211; Arnica<\/h4>\n<p>Il est assez difficile de trouver des <strong>m\u00e9dicaments hom\u00e9opathiques aux Etats-Unis<\/strong>, cependant vous pouvez facilement trouver les m\u00e9dicaments du laboratoire Boiron dans les pharmacies de type CVS.<\/p>\n<h3>De l&#8217;eau et du sel \u00e0 prix d&#8217;or<\/h3>\n<p>Le <strong>s\u00e9rum physiologique<\/strong> est bien vendu aux \u00c9tats-Unis, notamment sous la marque <em>Simply Saline<\/em>, mais au prix moyen de <i class=\"fa fa-money\" aria-hidden=\"true\"><\/i> 10$ le flacon&#8230;<\/p>\n<h3>Autres\u00a0sympt\u00f4mes<\/h3>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><strong>Pour la toux :\u00a0<\/strong><em>ROBITUSSIN<\/em>\u00a0(Expectorant efficace pour traiter les toux grasses) et\u00a0<em>ROBITUSSIN D M<\/em>\u00a0(le m\u00eame avec un antitussif, pour les toux s\u00e8ches), il est moins efficace cependant que le Toplexil au bon go\u00fbt de caramel made in France.<\/li>\n<li><strong>Pour les maux d&#8217;estomac et les br\u00fblures gastriques<\/strong>\u00a0:\u00a0<em>PEPTOBISMOL<\/em><\/li>\n<li><strong>Pour les vomissements, diarrh\u00e9es du nourrisson :<\/strong>\u00a0<em>PEDIALYTE<\/em>, un solut\u00e9 tr\u00e8s efficace pour r\u00e9hydrater.<\/li>\n<li><strong>Pour les douleurs musculaires ou articulaires :<\/strong>\u00a0la cr\u00e8me am\u00e9ricaine MYOFLEX fait des miracles.<\/li>\n<li><strong>Pour les d\u00e9mangeaisons,\u00a0piq\u00fbres\u00a0d&#8217;insectes :<\/strong>\u00a0les lotions, cr\u00e8mes, sprays et comprim\u00e9s\u00a0<em>BENADRYL<\/em>, et le large choix de cr\u00e8mes \u00e0 la cortisone disponibles en vente libre.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li>Enfin, pour les adeptes des <strong>sp\u00e9cialit\u00e9s th\u00e9rapeutiques naturelles<\/strong>, et ils sont nombreux, <a href=\"https:\/\/frenchdistrict.com\/floride\/adresse\/homeogum-medication-naturelle-homeopathie-phytotherapie-plantes\/\" target=\"_blank\" rel=\"noopener noreferrer\">HOMEOGUM<\/a>\u00a0allie <strong>l&#8217;hom\u00e9opathie<\/strong> et la <strong>phytoth\u00e9rapie<\/strong> en proposant des gommes \u00e0 mettre sous la langue pour traiter efficacement les principaux probl\u00e8mes de la vie courante (<strong>fatigue<\/strong> et manque de vitalit\u00e9, stress et anxi\u00e9t\u00e9, <strong>fonction thyro\u00efdienne<\/strong> et immunitaire). Tous les produits de la marque sont garantis vegan, sans perturbateurs endocriniens, sans pesticides et sans OGM.<\/li>\n<\/ul>\n<p><strong>Lire aussi : <a href=\"https:\/\/frenchdistrict.com\/floride\/articles\/moustiques-ete-floride-everglades-miami\/\"><i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> Un \u00e9t\u00e9 sans moustiques en Floride<\/a><\/strong><\/p>\n<h2>Vous \u00eates \u00e0 la recherche d&#8217;une assurance de sant\u00e9?<br \/>\nContactez-nous.<\/h2>\n<a name=\"contactfd\" style=\"display: block;position: relative;top: -150px;visibility: hidden;\"><\/a><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_11' ><div id='gf_11' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_11' id='gform_11'  action='\/floride\/wp-json\/wp\/v2\/posts\/61608#gf_11' data-formid='11' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_11' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_11_7\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_7'>Phone<\/label><div class='ginput_container'><input name='input_7' id='input_11_7' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_11_7'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_11_1\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_1'>Votre nom:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_11_1' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_11_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_2'>Votre adresse Email:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_11_2' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_11_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_3'>Votre t\u00e9l\u00e9phone:<\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_11_3' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_11_4\" class=\"gfield gfield--type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_4'>Votre message:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_11_4' class='textarea medium'   maxlength='800'  aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_11_5\" class=\"gfield gfield--type-checkbox gfield--type-choice field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_11_5'><li class='gchoice gchoice_11_5_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.1' type='checkbox'  value='Je souhaite m&#039;abonner \u00e0 la newsletter French District Floride et recevoir des bons plans' checked='checked' id='choice_11_5_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_11_5_1' id='label_11_5_1' class='gform-field-label gform-field-label--type-inline'>Je souhaite m'abonner \u00e0 la newsletter French District Floride et recevoir des bons plans<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_11_6\" class=\"gfield gfield--type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text' for='input_11_6'><\/label><div id='input_11_6' class='ginput_container ginput_recaptcha' data-sitekey='6Ldt8T8pAAAAAGjed3W4for4vBHh05M38nSQGx0t'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_11' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Envoyer'  \/> <input type='hidden' name='gform_ajax' value='form_id=11&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=0e33a01de5d1eec17cd82413e37789f5' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_11' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_11' id='gform_theme_11' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_11' id='gform_style_settings_11' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_11' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='11' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='DihT19NXqKm4D4WJdk98dujamPynQmrzNU1HHHFYY4ksU\/v3UJyRNo0JxoIgbaIeAgJk2vPHC5ldN3f5cclYdMjsQg8hrvvce1fywJyQeLhkGC0=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_11' value='WyJbXSIsIjYxMWFmYjlmMzI4ZTI4YmYzMThjYTg1MDIyODQ0YTljIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_11' id='gform_target_page_number_11' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_11' id='gform_source_page_number_11' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_11' id='gform_ajax_frame_11' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 11, 'https:\/\/frenchdistrict.com\/floride\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_11').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_11');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_11').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_11').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_11').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_11').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_11').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_11').val();gformInitSpinner( 11, 'https:\/\/frenchdistrict.com\/floride\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [11, current_page]);window['gf_submitting_11'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_11').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_11').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [11]);window['gf_submitting_11'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_11').text());}else{jQuery('#gform_11').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"11\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_11\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_11\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_11\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 11, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>Petit lexique de la pharmacie made in US Aux \u00c9tats-Unis, on distingue les m\u00e9dicaments en vente libre (Over the counter ou OTC) et ceux uniquement d\u00e9livr\u00e9s sur ordonnance m\u00e9dicale (Prescription ou Rx). Si vous avez un doute sur un produit, si vous n&#8217;arrivez pas \u00e0 choisir (ou \u00e0 traduire) pour construire votre trousse de m\u00e9dicaments, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":172072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3402,3257,3269],"tags":[951,468,2745,1780,487,2746],"class_list":["post-61608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expatriation-etats-unis","category-sante-etats-unis","category-sejour-vacances-etats-unis","tag-equivalence-france-usa","tag-speciale-famille-enfants","tag-maladie","tag-medicament","tag-medecins-sante-francais","tag-soin"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les m\u00e9dicaments aux Etats-Unis et leurs \u00e9quivalents avec la France<\/title>\n<meta name=\"description\" content=\"Quel est l&#039;\u00e9quivalent am\u00e9ricain de votre m\u00e9dicament, et surtout existe-il ? Certains m\u00e9dicaments en vente libre en France le sont-ils aux Etats-Unis ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les m\u00e9dicaments aux Etats-Unis et leurs \u00e9quivalents avec la France\" \/>\n<meta property=\"og:description\" content=\"Quel est l&#039;\u00e9quivalent am\u00e9ricain de votre m\u00e9dicament, et surtout existe-il ? Certains m\u00e9dicaments en vente libre en France le sont-ils aux Etats-Unis ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/\" \/>\n<meta property=\"og:site_name\" content=\"Floride\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frenchdistrict\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-19T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T14:08:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2021\/11\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9852238_9624835_6083409.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"French District\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:site\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"French District\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/\"},\"author\":{\"name\":\"French District\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"headline\":\"La trousse de m\u00e9dicaments \u00e0 avoir aux \u00c9tats-Unis\",\"datePublished\":\"2013-07-19T04:00:00+00:00\",\"dateModified\":\"2025-03-24T14:08:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/\"},\"wordCount\":1033,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/03\\\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9091343_7924967_2701773_9099431_9299314.jpg\",\"keywords\":[\"\u00e9quivalence france usa\",\"famille\",\"maladie\",\"m\u00e9dicament\",\"sant\u00e9\",\"soin\"],\"articleSection\":[\"Expatriation aux \u00c9tats-Unis\",\"Sant\u00e9\",\"S\u00e9jour \\\/ Vacances\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/\",\"name\":\"Les m\u00e9dicaments aux Etats-Unis et leurs \u00e9quivalents avec la France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/03\\\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9091343_7924967_2701773_9099431_9299314.jpg\",\"datePublished\":\"2013-07-19T04:00:00+00:00\",\"dateModified\":\"2025-03-24T14:08:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"description\":\"Quel est l'\u00e9quivalent am\u00e9ricain de votre m\u00e9dicament, et surtout existe-il ? Certains m\u00e9dicaments en vente libre en France le sont-ils aux Etats-Unis ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/03\\\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9091343_7924967_2701773_9099431_9299314.jpg\",\"contentUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/03\\\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9091343_7924967_2701773_9099431_9299314.jpg\",\"width\":\"1600\",\"height\":\"1066\",\"caption\":\"trousse-medicaments-pharmacie-avoir-etats-unis-une-new\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/medicaments-etats-unis-equivalent-france-pharmacies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Floride\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pratique\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/pratique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sant\u00e9\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/pratique\\\/sante-etats-unis\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"La trousse de m\u00e9dicaments \u00e0 avoir aux \u00c9tats-Unis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/#website\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/\",\"name\":\"Floride\",\"description\":\"Le meilleur de la &lt;span&gt;Floride&lt;\\\/span&gt; par ceux qui y vivent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\",\"name\":\"French District\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"caption\":\"French District\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les m\u00e9dicaments aux Etats-Unis et leurs \u00e9quivalents avec la France","description":"Quel est l'\u00e9quivalent am\u00e9ricain de votre m\u00e9dicament, et surtout existe-il ? Certains m\u00e9dicaments en vente libre en France le sont-ils aux Etats-Unis ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/","og_locale":"fr_FR","og_type":"article","og_title":"Les m\u00e9dicaments aux Etats-Unis et leurs \u00e9quivalents avec la France","og_description":"Quel est l'\u00e9quivalent am\u00e9ricain de votre m\u00e9dicament, et surtout existe-il ? Certains m\u00e9dicaments en vente libre en France le sont-ils aux Etats-Unis ?","og_url":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/","og_site_name":"Floride","article_publisher":"https:\/\/www.facebook.com\/frenchdistrict","article_published_time":"2013-07-19T04:00:00+00:00","article_modified_time":"2025-03-24T14:08:48+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2021\/11\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9852238_9624835_6083409.jpg","type":"image\/jpeg"}],"author":"French District","twitter_card":"summary_large_image","twitter_creator":"@frenchdistrict","twitter_site":"@frenchdistrict","twitter_misc":{"\u00c9crit par":"French District","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/#article","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/"},"author":{"name":"French District","@id":"https:\/\/frenchdistrict.com\/floride\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"headline":"La trousse de m\u00e9dicaments \u00e0 avoir aux \u00c9tats-Unis","datePublished":"2013-07-19T04:00:00+00:00","dateModified":"2025-03-24T14:08:48+00:00","mainEntityOfPage":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/"},"wordCount":1033,"commentCount":0,"image":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9091343_7924967_2701773_9099431_9299314.jpg","keywords":["\u00e9quivalence france usa","famille","maladie","m\u00e9dicament","sant\u00e9","soin"],"articleSection":["Expatriation aux \u00c9tats-Unis","Sant\u00e9","S\u00e9jour \/ Vacances"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/","url":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/","name":"Les m\u00e9dicaments aux Etats-Unis et leurs \u00e9quivalents avec la France","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/floride\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/#primaryimage"},"image":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9091343_7924967_2701773_9099431_9299314.jpg","datePublished":"2013-07-19T04:00:00+00:00","dateModified":"2025-03-24T14:08:48+00:00","author":{"@id":"https:\/\/frenchdistrict.com\/floride\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"description":"Quel est l'\u00e9quivalent am\u00e9ricain de votre m\u00e9dicament, et surtout existe-il ? Certains m\u00e9dicaments en vente libre en France le sont-ils aux Etats-Unis ?","breadcrumb":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/#primaryimage","url":"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9091343_7924967_2701773_9099431_9299314.jpg","contentUrl":"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/03\/trousse-medicaments-pharmacie-avoir-etats-unis-une-new_9091343_7924967_2701773_9099431_9299314.jpg","width":"1600","height":"1066","caption":"trousse-medicaments-pharmacie-avoir-etats-unis-une-new"},{"@type":"BreadcrumbList","@id":"https:\/\/frenchdistrict.com\/floride\/articles\/medicaments-etats-unis-equivalent-france-pharmacies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Floride","item":"https:\/\/frenchdistrict.com\/floride\/"},{"@type":"ListItem","position":2,"name":"Pratique","item":"https:\/\/frenchdistrict.com\/floride\/pratique\/"},{"@type":"ListItem","position":3,"name":"Sant\u00e9","item":"https:\/\/frenchdistrict.com\/floride\/pratique\/sante-etats-unis\/"},{"@type":"ListItem","position":4,"name":"La trousse de m\u00e9dicaments \u00e0 avoir aux \u00c9tats-Unis"}]},{"@type":"WebSite","@id":"https:\/\/frenchdistrict.com\/floride\/#website","url":"https:\/\/frenchdistrict.com\/floride\/","name":"Floride","description":"Le meilleur de la &lt;span&gt;Floride&lt;\/span&gt; par ceux qui y vivent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchdistrict.com\/floride\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/frenchdistrict.com\/floride\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010","name":"French District","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","caption":"French District"}}]}},"_links":{"self":[{"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/posts\/61608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/comments?post=61608"}],"version-history":[{"count":18,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/posts\/61608\/revisions"}],"predecessor-version":[{"id":172077,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/posts\/61608\/revisions\/172077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/media\/172072"}],"wp:attachment":[{"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/media?parent=61608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/categories?post=61608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/tags?post=61608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}