{"id":95700,"date":"2016-12-01T00:00:00","date_gmt":"2016-12-01T05:00:00","guid":{"rendered":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/"},"modified":"2025-07-21T11:53:00","modified_gmt":"2025-07-21T15:53:00","slug":"les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous","status":"publish","type":"post","link":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/","title":{"rendered":"Les 10 faux pas \u00e0 \u00e9viter lors d\u2019un premier rendez-vous"},"content":{"rendered":"<p>Pour tout savoir sur les dates aux Etats-Unis, cliquez ici ici et <i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"http:\/\/frenchdistrict.com\/articles\/date-dating-rendez-vous-amoureux-relation-homme-femme-amour-etats-unis\/\" target=\"_blank\" rel=\"noopener noreferrer\">lisez notre article \u00e0 ce sujet<\/a>.<\/p>\n<h2>Avant le grand moment<\/h2>\n<h3>1 &#8211; Vivons mieux, vivons discrets<\/h3>\n\r\n\t<div class=\"sponsor__article sponsor__article--right\">\r\n\t\t<div class=\"inner\">\r\n\t\t\t<div class=\"sponsor__by\">Pr&eacute;sent&eacute; par...<\/div>\r\n\t\t\t<div>\r\n\t\t\t\t<a href=\"https:\/\/www.gymglish.com\/partner\/french-district\/124\/iframe\" target=\"_blank\">\r\n\t\t\t\t<div class=\"sponsor__illus\"><img decoding=\"async\" src=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2015\/04\/gymglish-apprendre-anglais-en-ligne-facile-10-380x260.png\" alt=\"Gymglish &#8211; Apprendre l&#8217;anglais en ligne\" \/><\/div>\r\n\t\t\t\t<div class=\"sponsor__content\">\r\n\t\t\t\t\t<p class=\"sponsor__title\">Gymglish &#8211; Apprendre l&#8217;anglais en ligne<\/p>\r\n\t\t\t\t\t<div class=\"sponsor__slogan\">Le\u00e7ons d'anglais personnalis\u00e9es en ligne<\/div>\r\n\t\t\t\t\t<div class=\"vce-button vce-button--small\" style=\"background-color: #ff4242;\"><i class=\"fa fa-hand-o-right\" aria-hidden=\"true\">&nbsp;<\/i>Gymglish &#8211; Apprendre l&#8217;anglais en ligne<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\t\t\r\n\t\t<\/div>\r\n\t<\/div>\u00ab\u00a0Grand-Tante Amy ?\u00a0Oui, la s\u0153ur du cousin de la grand-m\u00e8re de ton demi-fr\u00e8re, c\u2019est \u00e7a\u00a0?\u00a0\u00bb. Rien de pire pour votre <strong>rendez-vous galant<\/strong> que de se sentir \u00e9pi\u00e9. Bien s\u00fbr, vous aurez envie de prouver que vous connaissez son arbre g\u00e9n\u00e9alogique sur 3 g\u00e9n\u00e9rations (merci Facebook), mais c\u2019est l\u00e9g\u00e8rement angoissant. Notre soci\u00e9t\u00e9 actuelle nous pousse \u00e0 suivre voire espionner tout le monde, et si, vraiment, \u00e7a vous d\u00e9mange, contentez-vous de le faire\u2026 sans le d\u00e9voiler.<\/p>\n<h3>2 &#8211; Y\u2019a un temps pour tout, surtout pour \u00eatre \u00e0 l\u2019heure<\/h3>\n<p>Personne n\u2019appr\u00e9cie les gens en retard, encore moins quand c\u2019est pour attendre devant chez vous et voir tous vos voisins d\u00e9filer avec leurs chiens ou devant un restaurant bond\u00e9 sous l\u2019\u0153il empli de piti\u00e9 des clients d\u00e9j\u00e0 install\u00e9s. <strong>Pour un premier rendez-vous, on est \u00e0 l\u2019heure<\/strong> et on fait un effort pour ne pas lui dire \u00ab\u00a0j\u2019arrive ! \u00bb alors que vous savez toujours pas quel pantalon enfiler.<\/p>\n<p><a href=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-173626\" src=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard-1024x683.jpg\" alt=\"les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard\" width=\"810\" height=\"540\" srcset=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard-1024x683.jpg 1024w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard-300x200.jpg 300w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard-768x512.jpg 768w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard-1536x1024.jpg 1536w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard-810x540.jpg 810w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard-1140x760.jpg 1140w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard-600x400.jpg 600w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-retard.jpg 1920w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n<h3>3 &#8211; Je suis s\u00fbr d\u2019\u00eatre s\u00fbr de moi<\/h3>\n<p>Les premi\u00e8res <strong><em>dates<\/em> aux Etats-Unis<\/strong> sont parfois synonymes de caf\u00e9 en terrasse ou de cin\u00e9ma intime. Mais elles peuvent l\u2019\u00eatre de sortie roller en bord de mer, concert de cornemuse, ou d\u00e9gustation d\u2019hu\u00eetres chaudes. N\u2019h\u00e9sitez alors pas, une fois que vous en avez connaissance, \u00e0 vous interposer et pr\u00e9ciser que les escargots, tr\u00e8s peu pour vous.<\/p>\n<h2>Pendant le rendez-vous<\/h2>\n<h3>4 &#8211; Moi, Princesse<\/h3>\n<p>Ce n\u2019est pas que les Am\u00e9ricains ne soient pas galants. Simplement, il est d\u00e9plac\u00e9 aux Etats-Unis de s\u2019imaginer que votre chevalier va payer l\u2019addition, seul, une fois qu\u2019elle est d\u00e9pos\u00e9e sur la table. Ne pensez pas que vous serez invit\u00e9e, m\u00eame si ce sera g\u00e9n\u00e9ralement le cas, et pr\u00e9parez-vous \u00e0 payer la moiti\u00e9, m\u00eame si \u00e7a ne vous fera qu\u2019\u00e0 moiti\u00e9 plaisir.<\/p>\n<div id=\"attachment_173625\" style=\"width: 820px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-173625\" class=\"size-large wp-image-173625\" src=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition-1024x683.jpg\" alt=\"les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition\" width=\"810\" height=\"540\" srcset=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition-1024x683.jpg 1024w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition-300x200.jpg 300w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition-768x512.jpg 768w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition-1536x1024.jpg 1536w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition-810x540.jpg 810w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition-1140x760.jpg 1140w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition-600x400.jpg 600w, https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-partager-addition.jpg 1920w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><p id=\"caption-attachment-173625\" class=\"wp-caption-text\"><span style=\"font-size: 12px; font-style: italic;\">Cr\u00e9dit photo : <a style=\"color: #3d5185; text-decoration: none;\" href=\"https:\/\/www.flickr.com\/photos\/criminalintent\/4012655664\" target=\"_blank\" rel=\"noopener\">Lars Plougmann<\/a> (<a style=\"color: #3d5185; text-decoration: none;\" href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/2.0\/\" target=\"_blank\" rel=\"noopener\">CC BY-SA 2.0<\/a>)<\/span><\/p><\/div>\n<h3>5 &#8211; Moi je, moi je<\/h3>\n<p>Que ce soit entre amis, en famille, en entretien d\u2019embauche ou, justement, en\u00a0rendez-vous, il n\u2019est jamais tellement recommand\u00e9 de d\u00e9biter votre autobiographie, souvent devant les yeux \u00e9bahis et les oreilles fatigu\u00e9es de votre interlocuteur\/interlocutrice. Sachez <strong>poser des questions<\/strong>, <strong>\u00e9couter les r\u00e9ponses<\/strong>, et, surtout, appr\u00e9cier les petits silences.<\/p>\n<h3>\r\n\t<div class=\"sponsor__article sponsor__article--right\">\r\n\t\t<div class=\"inner\">\r\n\t\t\t<div class=\"sponsor__by\">Pr&eacute;sent&eacute; par...<\/div>\r\n\t\t\t<div>\r\n\t\t\t\t<a href=\"https:\/\/www.gymglish.com\/partner\/french-district\/124\/iframe\" target=\"_blank\">\r\n\t\t\t\t<div class=\"sponsor__illus\"><img decoding=\"async\" src=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2015\/04\/gymglish-apprendre-anglais-en-ligne-facile-10-380x260.png\" alt=\"Gymglish &#8211; Apprendre l&#8217;anglais en ligne\" \/><\/div>\r\n\t\t\t\t<div class=\"sponsor__content\">\r\n\t\t\t\t\t<p class=\"sponsor__title\">Gymglish &#8211; Apprendre l&#8217;anglais en ligne<\/p>\r\n\t\t\t\t\t<div class=\"sponsor__slogan\">Le\u00e7ons d'anglais personnalis\u00e9es en ligne<\/div>\r\n\t\t\t\t\t<div class=\"vce-button vce-button--small\" style=\"background-color: #ff4242;\"><i class=\"fa fa-hand-o-right\" aria-hidden=\"true\">&nbsp;<\/i>Gymglish &#8211; Apprendre l&#8217;anglais en ligne<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\t\t\r\n\t\t<\/div>\r\n\t<\/div>6 &#8211; Parlons mieux, parlons peu<\/h3>\n<p>Dans le m\u00eame genre, <strong>ne d\u00e9voilez pas toutes les informations<\/strong> secr\u00e8tes sur votre caract\u00e8re de cochon, votre tendance \u00e0 ronfler ou votre forte addiction aux telenovelas colombiennes. Bien que les Am\u00e9ricains soient g\u00e9n\u00e9ralement tr\u00e8s friands des effusions de sympathie et des d\u00e9monstrations flagrantes d\u2019affection, <strong>restez discret et r\u00e9serv\u00e9<\/strong>, tout le monde vous en sera reconnaissant \u2013 surtout votre ego lorsque votre conqu\u00eate ne vous aura pas rappel\u00e9 apr\u00e8s ce rendez-vous.<\/p>\n<h2>Apr\u00e8s la rencontre<\/h2>\n<h3>7 &#8211; Vivons mieux, vivons \u00e0 la d\u00e9rob\u00e9e<\/h3>\n<p>L\u00e0 encore, on rejoint le premier point. Essayez de vous contenir et de ne pas vous ruer sur Facebook, Twitter, Instagram, TikTok, voire LinkedIn ou encore Pinterest pour en savoir plus sur la vie, la famille, le travail, les recettes pr\u00e9f\u00e9r\u00e9es et le pr\u00e9nom du coiffeur de votre conqu\u00eate.<\/p>\n<h3>8 &#8211; Tout vient \u00e0 point \u00e0 qui sait attendre<\/h3>\n<p>Le syst\u00e8me de <a href=\"https:\/\/frenchdistrict.com\/articles\/date-dating-rendez-vous-amoureux-relation-homme-femme-amour-etats-unis\/\">&#8220;<strong><em>date&#8221;<\/em> \u00e0 l\u2019am\u00e9ricaine<\/strong><\/a> est bien particulier, et para\u00eet bien compliqu\u00e9 lorsqu\u2019on n\u2019est pas du pays. M\u00eame si le 1er rendez-vous s\u2019est excessivement bien pass\u00e9, <strong>le 2\u00e8me rendez-vous n\u2019est pas automatique<\/strong>. De m\u00eame, s\u2019il a lieu, il ne sera souvent enclench\u00e9 que quelques jours apr\u00e8s le 1er. Rien d\u2019\u00e9tonnant alors \u00e0 ce que vous ayez des nouvelles de votre rendez-vous galant apr\u00e8s 3 ou 4 jours de silence, pesant.<\/p>\n<h3>9 &#8211; Toi + moi = nous ?<\/h3>\n<p>Toujours une notion m\u00e9connue des non-am\u00e9ricains, <strong>le premier rendez-vous aux Etats-Unis n\u2019est pas synonyme de couple, de relation stable et de mariage<\/strong>. D\u00e9tendez-vous. Aux Etats-Unis, on peut multiplier les <strong><em>dates,<\/em><\/strong> les cumuler et les renouveler, avec une ou plusieurs personnes diff\u00e9rentes. Apr\u00e8s votre premier rendez-vous n\u2019imaginez pas que vous \u00eates l\u2019Unique\u00a0; ce n\u2019est qu\u2019apr\u00e8s plusieurs dates que le choix s\u2019impose \u00e0 vous\u00a0; devenez-vous exclusif\u00a0? Continuez-vous les rendez-vous\u00a0? Arr\u00eatez-vous tout\u00a0? \u00c0 vous de d\u00e9cider\u2026<\/p>\n<h2>10 &#8211; Et si \u00e7a ne fonctionne pas&#8230;<\/h2>\n<p><em>There are plenty of fish in the sea<\/em> comme\u00a0on dit ici&#8230;<\/p>\n<h3>Vous souhaitez b\u00e9n\u00e9ficier de conseils avis\u00e9s par un coach ou un expert ?<br \/>\n\u00c9crivez-nous !<\/h3>\n<a name=\"contactfd\" style=\"display: block;position: relative;top: -150px;visibility: hidden;\"><\/a><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_11' ><div id='gf_11' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_11' id='gform_11'  action='\/floride\/wp-json\/wp\/v2\/posts\/95700#gf_11' data-formid='11' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_11' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_11_7\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_7'>Email<\/label><div class='ginput_container'><input name='input_7' id='input_11_7' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_11_7'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_11_1\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_1'>Votre nom:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_11_1' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_11_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_2'>Votre adresse Email:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_11_2' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_11_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_3'>Votre t\u00e9l\u00e9phone:<\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_11_3' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_11_4\" class=\"gfield gfield--type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_11_4'>Votre message:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_11_4' class='textarea medium'   maxlength='800'  aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_11_5\" class=\"gfield gfield--type-checkbox gfield--type-choice field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_11_5'><li class='gchoice gchoice_11_5_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.1' type='checkbox'  value='Je souhaite m&#039;abonner \u00e0 la newsletter French District Floride et recevoir des bons plans' checked='checked' id='choice_11_5_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_11_5_1' id='label_11_5_1' class='gform-field-label gform-field-label--type-inline'>Je souhaite m'abonner \u00e0 la newsletter French District Floride et recevoir des bons plans<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_11_6\" class=\"gfield gfield--type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text' for='input_11_6'><\/label><div id='input_11_6' class='ginput_container ginput_recaptcha' data-sitekey='6Ldt8T8pAAAAAGjed3W4for4vBHh05M38nSQGx0t'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_11' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Envoyer'  \/> <input type='hidden' name='gform_ajax' value='form_id=11&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=0e33a01de5d1eec17cd82413e37789f5' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_11' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_11' id='gform_theme_11' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_11' id='gform_style_settings_11' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_11' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='11' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='mCAF7+\/HN9SSlmdpfDSY2oNKxsswxvtLF4loz1aWoIR\/dRnZtXfIQx9MpBii\/zCpcjem3sI945J19oJYvOIxKr36wRGr4qOxGhcOjXhLAfaqbTk=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_11' value='WyJbXSIsIjYxMWFmYjlmMzI4ZTI4YmYzMThjYTg1MDIyODQ0YTljIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_11' id='gform_target_page_number_11' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_11' id='gform_source_page_number_11' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_11' id='gform_ajax_frame_11' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 11, 'https:\/\/frenchdistrict.com\/floride\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_11').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_11');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_11').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_11').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_11').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_11').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_11').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_11').val();gformInitSpinner( 11, 'https:\/\/frenchdistrict.com\/floride\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [11, current_page]);window['gf_submitting_11'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_11').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_11').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [11]);window['gf_submitting_11'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_11').text());}else{jQuery('#gform_11').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"11\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_11\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_11\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_11\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 11, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>Pour tout savoir sur les dates aux Etats-Unis, cliquez ici ici et lisez notre article \u00e0 ce sujet. Avant le grand moment 1 &#8211; Vivons mieux, vivons discrets \u00ab\u00a0Grand-Tante Amy ?\u00a0Oui, la s\u0153ur du cousin de la grand-m\u00e8re de ton demi-fr\u00e8re, c\u2019est \u00e7a\u00a0?\u00a0\u00bb. Rien de pire pour votre rendez-vous galant que de se sentir \u00e9pi\u00e9. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":173627,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[411],"tags":[2071,1159,1636,1686,1687,581,1688],"class_list":["post-95700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insolite","tag-americains","tag-amour","tag-conseils","tag-couple","tag-date","tag-etats-unis","tag-rendez-vous"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 choses \u00e0 \u00e9viter lors d&#039;une first date aux Etats-Unis<\/title>\n<meta name=\"description\" content=\"Quelles sont les autres clefs pour que votre rendez-vous se transforme en second, voire en deuxi\u00e8me ? Quelques r\u00e9ponses pour \u00e9viter de terminer c\u00e9libataire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 choses \u00e0 \u00e9viter lors d&#039;une first date aux Etats-Unis\" \/>\n<meta property=\"og:description\" content=\"Quelles sont les autres clefs pour que votre rendez-vous se transforme en second, voire en deuxi\u00e8me ? Quelques r\u00e9ponses pour \u00e9viter de terminer c\u00e9libataire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/\" \/>\n<meta property=\"og:site_name\" content=\"Floride\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frenchdistrict\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-01T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-21T15:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2024\/12\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-une-1_1566203.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1095\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tZaFNBo4R9Yh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:site\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"tZaFNBo4R9Yh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/\"},\"author\":{\"name\":\"tZaFNBo4R9Yh\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"headline\":\"Les 10 faux pas \u00e0 \u00e9viter lors d\u2019un premier rendez-vous\",\"datePublished\":\"2016-12-01T05:00:00+00:00\",\"dateModified\":\"2025-07-21T15:53:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/\"},\"wordCount\":811,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous.jpg\",\"keywords\":[\"americains\",\"amour\",\"conseils\",\"couple\",\"date\",\"Etats-Unis\",\"rendez-vous\"],\"articleSection\":[\"A contre-courant\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/\",\"name\":\"10 choses \u00e0 \u00e9viter lors d'une first date aux Etats-Unis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous.jpg\",\"datePublished\":\"2016-12-01T05:00:00+00:00\",\"dateModified\":\"2025-07-21T15:53:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"description\":\"Quelles sont les autres clefs pour que votre rendez-vous se transforme en second, voire en deuxi\u00e8me ? Quelques r\u00e9ponses pour \u00e9viter de terminer c\u00e9libataire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous.jpg\",\"contentUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/07\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous.jpg\",\"width\":1920,\"height\":1278,\"caption\":\"les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/articles\\\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Floride\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A contre-courant\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/insolite\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les 10 faux pas \u00e0 \u00e9viter lors d\u2019un premier rendez-vous\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/#website\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/\",\"name\":\"Floride\",\"description\":\"Le meilleur de la &lt;span&gt;Floride&lt;\\\/span&gt; par ceux qui y vivent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/floride\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\",\"name\":\"tZaFNBo4R9Yh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"caption\":\"tZaFNBo4R9Yh\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 choses \u00e0 \u00e9viter lors d'une first date aux Etats-Unis","description":"Quelles sont les autres clefs pour que votre rendez-vous se transforme en second, voire en deuxi\u00e8me ? Quelques r\u00e9ponses pour \u00e9viter de terminer c\u00e9libataire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/","og_locale":"fr_FR","og_type":"article","og_title":"10 choses \u00e0 \u00e9viter lors d'une first date aux Etats-Unis","og_description":"Quelles sont les autres clefs pour que votre rendez-vous se transforme en second, voire en deuxi\u00e8me ? Quelques r\u00e9ponses pour \u00e9viter de terminer c\u00e9libataire.","og_url":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/","og_site_name":"Floride","article_publisher":"https:\/\/www.facebook.com\/frenchdistrict","article_published_time":"2016-12-01T05:00:00+00:00","article_modified_time":"2025-07-21T15:53:00+00:00","og_image":[{"width":1600,"height":1095,"url":"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2024\/12\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous-une-1_1566203.jpg","type":"image\/jpeg"}],"author":"tZaFNBo4R9Yh","twitter_card":"summary_large_image","twitter_creator":"@frenchdistrict","twitter_site":"@frenchdistrict","twitter_misc":{"\u00c9crit par":"tZaFNBo4R9Yh","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/#article","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/"},"author":{"name":"tZaFNBo4R9Yh","@id":"https:\/\/frenchdistrict.com\/floride\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"headline":"Les 10 faux pas \u00e0 \u00e9viter lors d\u2019un premier rendez-vous","datePublished":"2016-12-01T05:00:00+00:00","dateModified":"2025-07-21T15:53:00+00:00","mainEntityOfPage":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/"},"wordCount":811,"commentCount":0,"image":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous.jpg","keywords":["americains","amour","conseils","couple","date","Etats-Unis","rendez-vous"],"articleSection":["A contre-courant"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/","url":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/","name":"10 choses \u00e0 \u00e9viter lors d'une first date aux Etats-Unis","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/floride\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/#primaryimage"},"image":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous.jpg","datePublished":"2016-12-01T05:00:00+00:00","dateModified":"2025-07-21T15:53:00+00:00","author":{"@id":"https:\/\/frenchdistrict.com\/floride\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"description":"Quelles sont les autres clefs pour que votre rendez-vous se transforme en second, voire en deuxi\u00e8me ? Quelques r\u00e9ponses pour \u00e9viter de terminer c\u00e9libataire.","breadcrumb":{"@id":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/#primaryimage","url":"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous.jpg","contentUrl":"https:\/\/frenchdistrict.com\/floride\/wp-content\/uploads\/sites\/2\/2025\/07\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous.jpg","width":1920,"height":1278,"caption":"les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous"},{"@type":"BreadcrumbList","@id":"https:\/\/frenchdistrict.com\/floride\/articles\/les-10-faux-pas-a-eviter-lors-dun-premier-rendez-vous\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Floride","item":"https:\/\/frenchdistrict.com\/floride\/"},{"@type":"ListItem","position":2,"name":"A contre-courant","item":"https:\/\/frenchdistrict.com\/floride\/insolite\/"},{"@type":"ListItem","position":3,"name":"Les 10 faux pas \u00e0 \u00e9viter lors d\u2019un premier rendez-vous"}]},{"@type":"WebSite","@id":"https:\/\/frenchdistrict.com\/floride\/#website","url":"https:\/\/frenchdistrict.com\/floride\/","name":"Floride","description":"Le meilleur de la &lt;span&gt;Floride&lt;\/span&gt; par ceux qui y vivent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchdistrict.com\/floride\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/frenchdistrict.com\/floride\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010","name":"tZaFNBo4R9Yh","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","caption":"tZaFNBo4R9Yh"}}]}},"_links":{"self":[{"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/posts\/95700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/comments?post=95700"}],"version-history":[{"count":11,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/posts\/95700\/revisions"}],"predecessor-version":[{"id":173635,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/posts\/95700\/revisions\/173635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/media\/173627"}],"wp:attachment":[{"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/media?parent=95700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/categories?post=95700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchdistrict.com\/floride\/wp-json\/wp\/v2\/tags?post=95700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}