{"id":5044,"date":"2013-09-17T21:00:00","date_gmt":"2013-09-18T04:00:00","guid":{"rendered":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/"},"modified":"2020-11-13T11:58:38","modified_gmt":"2020-11-13T18:58:38","slug":"dui-alcool-volant-danger-conduite-ivresse-etats-unis","status":"publish","type":"post","link":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/","title":{"rendered":"Le DUI, l\u2019alcool et le volant aux \u00c9tats-Unis"},"content":{"rendered":"<h2>Le DUI : Conduire en \u00e9tat d&#8217;\u00e9bri\u00e9t\u00e9<\/h2>\n<h3>Driver Under the Influence \u2013 oui, mais de quoi ?<\/h3>\n<p><strong>L&#8217;alcool et le volant aux Etats-Unis<\/strong> est un sujet pris tr\u00e8s au s\u00e9rieux. Le \u00ab\u00a0<em>DUI<\/em>\u00a0\u00bb (prononcer \u00ab\u00a0<em>di-you-aye<\/em>\u00a0\u00bb) : \u00ab\u00a0<strong><em>Driving Under the Influence<\/em><\/strong>\u00a0\u00bb signifie <strong>conduire<\/strong> en \u00e9tat d\u2019\u00e9bri\u00e9t\u00e9, et\/ou sous l\u2019influence de drogues.<\/p>\n<p>Le <strong>DUI<\/strong> \u2013 ou DWI \u00ab\u00a0<em>Driving While Intoxicated<\/em>\u00a0\u00bb &#8211; se r\u00e9f\u00e8re \u00e0 l\u2019infraction que constitue la <strong>conduite en \u00e9tat d\u2019ivresse, ou\/et sous l\u2019influence de drogues.<\/strong> Les lois varient selon les \u00e9tats \u2013 attention donc si vous allez faire la f\u00eate de l\u2019autre c\u00f4t\u00e9 de la fronti\u00e8re \u2013 mais restent globalement similaires.<\/p>\n<p>Tous les \u00e9tats des Etats-Unis se sont entendus pour d\u00e9finir que le <strong>taux d\u2019alcool\u00e9mie<\/strong> maximum est de 0.08%. Le \u00ab\u00a0<em>BAC<\/em>\u00a0\u00bb, \u00ab\u00a0<em>Blood Alcool Content<\/em>\u00a0\u00bb se r\u00e9f\u00e8re alors au pourcentage d\u2019alcool contenu dans le sang ; 0,08% signifie qu\u2019une personne a\u00a08g d\u2019alcool dans 10L de sang.<\/p>\n<p>Sachez que le BAC en <strong>France<\/strong> s\u2019\u00e9l\u00e8ve \u00e0 0,05%, et au Canada, cela va de la z\u00e9ro tol\u00e9rance pour les nouveaux conducteurs, \u00e0 0,05%.<\/p>\n<h3>Une arrestation si vous en donnez des raisons<\/h3>\n\r\n\t<div class=\"sponsor__article sponsor__article--left\">\r\n\t\t<div class=\"inner\">\r\n\t\t\t<div class=\"sponsor__by\">Pr&eacute;sent&eacute; par...<\/div>\r\n\t\t\t<div>\r\n\t\t\t\t<a href=\"https:\/\/frenchdistrict.com\/presentez-entreprise\/\" target=\"_blank\">\r\n\t\t\t\t<div class=\"sponsor__illus\"><img decoding=\"async\" src=\"https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/uploads\/sites\/11\/2024\/05\/french-district-referencez-entreprise.png\" alt=\"French District\" \/><\/div>\r\n\t\t\t\t<div class=\"sponsor__content\">\r\n\t\t\t\t\t<p class=\"sponsor__title\">French District<\/p>\r\n\t\t\t\t\t<div class=\"sponsor__slogan\">French District : Le lien entre les entreprises et les expatri\u00e9s.<\/div>\r\n\t\t\t\t\t<div class=\"vce-button vce-button--small\" style=\"background-color: #444444;\"><i class=\"fa fa-hand-o-right\" aria-hidden=\"true\">&nbsp;<\/i>French District<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\t\t\r\n\t\t<\/div>\r\n\t<\/div>Pour vous arr\u00eater, la police doit avoir des raisons de penser que vous <strong>conduisez en \u00e9tat d\u2019ivresse<\/strong>, ou <strong>sous l\u2019emprise de drogues<\/strong> \u2013 zigzags, vitesse excessive, comportement suspect\u2026<\/p>\n<p>Afin de justifier leur d\u00e9cision, les policiers vont donc vous demander de r\u00e9aliser quelques exercices acrobatiques : vous tenir sur une jambe \u2013 d\u00e9j\u00e0 que vous n\u2019arrivez pas \u00e0 le faire au yoga \u2013 marcher sur une ligne droite imaginaire, voire r\u00e9citer l\u2019alphabet (sans chanter).<\/p>\n<p>Ils peuvent aussi vous commander de suivre un objet ou vous flanquer leur lampe torche dans les yeux afin de d\u00e9tecter un possible \u00ab\u00a0<em>Horizontal Gaze Nystagamus<\/em>\u00a0\u00bb (qui signifie que vos yeux s\u2019agitent un peu trop, ou pr\u00e9sentent un mouvement saccad\u00e9 en suivant un objet \u00e0 moins de 45\u00b0).<\/p>\n<p>Sachez que dans certains Etats, des <em><strong>checkpoints<\/strong><\/em> sont parfois install\u00e9s, et\u00a0les policiers se r\u00e9servent le droit de s\u00e9lectionner les conducteurs qui devront les suivre et se soumettre \u00e0 un<strong> test d&#8217;alcool\u00e9mie<\/strong>.<\/p>\n<h2>Trop de verres tu boiras, le taxi tu pr\u00e9f\u00e8reras<\/h2>\n<h3>Les mesures pr\u00e9ventives<\/h3>\n<h3>S\u00e9same\u2026 Souffle une fois !<\/h3>\n<p>Tous les \u00e9tats ont \u00e9dict\u00e9 des lois instaurant un syst\u00e8me de verrou sur les v\u00e9hicules de conducteurs pr\u00e9c\u00e9demment condamn\u00e9s pour <strong>conduite en \u00e9tat d\u2019ivresse<\/strong>, qui ne peuvent alors se servir de leur v\u00e9hicule qu\u2019apr\u00e8s avoir souffl\u00e9 dans un <strong>alcotest<\/strong> qui d\u00e9bloque leur voiture. Dans 19 \u00e9tats, ces verrous sont obligatoires, m\u00eame pour les d\u00e9linquants dont c\u2019est la premi\u00e8re infraction.<\/p>\n<h4>Boire au volant \u2013 mais de l\u2019eau uniquement<\/h4>\n<p>La plupart des Etats ont \u00e9dict\u00e9 des lois dites \u00ab\u00a0<em>Open Container Laws<\/em>\u00a0\u00bb, concernant la pr\u00e9sence de r\u00e9cipients ouverts dans les voitures de r\u00e9cidivistes de la descente sans fond.<\/p>\n<p>43 \u00e9tats et Washington D.C. interdisent donc le conducteur, le passager, ou les 2, de poss\u00e9der un r\u00e9cipient ouvert qui contiendrait de <strong>l\u2019alcool<\/strong> ; on entend donc toute bouteille, cannette ou petite flasque qui ne serait plus ferm\u00e9e herm\u00e9tiquement (plus de bouchon, plus de languette, plus de capsule) et qui serait entam\u00e9e.<\/p>\n<h3>Les sanctions de la conduite en \u00e9tat d\u2019ivresse<\/h3>\n<h4>Celui qui boit trop d&#8217;alcool finit \u00e0 pied<\/h4>\n\r\n\t<div class=\"sponsor__article sponsor__article--left\">\r\n\t\t<div class=\"inner\">\r\n\t\t\t<div class=\"sponsor__by\">Pr&eacute;sent&eacute; par...<\/div>\r\n\t\t\t<div>\r\n\t\t\t\t<a href=\"https:\/\/frenchdistrict.com\/presentez-entreprise\/\" target=\"_blank\">\r\n\t\t\t\t<div class=\"sponsor__illus\"><img decoding=\"async\" src=\"https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/uploads\/sites\/11\/2024\/05\/french-district-referencez-entreprise.png\" alt=\"French District\" \/><\/div>\r\n\t\t\t\t<div class=\"sponsor__content\">\r\n\t\t\t\t\t<p class=\"sponsor__title\">French District<\/p>\r\n\t\t\t\t\t<div class=\"sponsor__slogan\">French District : Le lien entre les entreprises et les expatri\u00e9s.<\/div>\r\n\t\t\t\t\t<div class=\"vce-button vce-button--small\" style=\"background-color: #444444;\"><i class=\"fa fa-hand-o-right\" aria-hidden=\"true\">&nbsp;<\/i>French District<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\t\t\r\n\t\t<\/div>\r\n\t<\/div>Dans la plupart des Etats, le <strong>conducteur ivre<\/strong> se voit <strong>retirer son permis de conduire<\/strong>, et il reste souvent suspendu 1 an pour les premi\u00e8res infractions, 3 ans pour la deuxi\u00e8me, et 5 ans pour la troisi\u00e8me. Dans certains \u00e9tats, le permis peut m\u00eame \u00eatre r\u00e9voqu\u00e9 de fa\u00e7on permanente.<\/p>\n<p>De m\u00eame, les v\u00e9hicules conduits sont g\u00e9n\u00e9ralement saisis ou du moins immobilis\u00e9s (avec la pose d\u2019un sabot par exemple), et parfois m\u00eame les plaques d\u2019immatriculation sont confisqu\u00e9es.<\/p>\n<h4>Evitez de payer votre tourn\u00e9e<\/h4>\n<p>Bien entendu, le <strong>conducteur alcoolis\u00e9<\/strong>\u00a0doit payer une amende \u2013 pouvant aller de centaines \u00e0 des milliers de dollars \u2013 sans compter tous les frais qui s\u2019en suivent : r\u00e9cup\u00e9rer votre voiture \u00e0 la fourri\u00e8re, des co\u00fbts d\u2019assurance auto bien plus \u00e9lev\u00e9s ensuite, l\u2019installation du syst\u00e8me de verrou-alcotest sur les v\u00e9hicules, les frais d\u2019avocats\u2026 et les tubes d\u2019aspirine qui vous aideront \u00e0 vous remettre de la soir\u00e9e et \u00e0 soulager vos maux de t\u00eate apr\u00e8s tant de complications.<\/p>\n<h4>Apr\u00e8s trop de bi\u00e8res, on finit au service communautaire<\/h4>\n<p>Une sanction suppl\u00e9mentaire \u00e0 l\u2019amende et au retrait de votre permis reste souvent le service communautaire obligatoire. Non seulement les portes de certaines professions vous seront ferm\u00e9es \u00e0 jamais (chauffeur dans la fonction publique par exemple), mais vous pourrez aussi perdre votre emploi si jamais l\u2019une des conditions d\u2019emploi est d\u2019avoir un casier judiciaire vierge. Vous devrez s\u00fbrement assister \u00e0 des <strong>classes sur les dangers de l\u2019alcool<\/strong> ou vous inscrire \u00e0 des cours de conduite.<\/p>\n<h4>Voir gris en cellule<\/h4>\n<p>De plus en plus d\u2019\u00e9tat imposent une peine de prison aux <strong>conducteurs qui se font arr\u00eater en \u00e9tat d\u2019ivresse<\/strong>, m\u00eame si c\u2019est leur premi\u00e8re infraction. Cela se r\u00e9sume g\u00e9n\u00e9ralement \u00e0 1 ou 2 jours que l\u2019on peut effectuer sur un week-end (\u00e7a reporte vos plans de fins de semaine \u00e0 la mer \u2013 dommage l\u2019eau vous aurait fait du bien). Pour les r\u00e9cidivistes, voire ceux qui ont commis des circonstances aggravantes, cela peut rapidement monter.<\/p>\n<h2>Vous \u00eates \u00e0 la recherche d&#8217;un avocat?<br \/>\nContactez Paul A. McKenna.<\/h2>\n<a name=\"contactfd\" style=\"display: block;position: relative;top: -150px;visibility: hidden;\"><\/a><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_5' ><div id='gf_5' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_5' id='gform_5'  action='\/las-vegas\/wp-json\/wp\/v2\/posts\/5044#gf_5' data-formid='5' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_5' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_5_7\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_7'>Instagram<\/label><div class='ginput_container'><input name='input_7' id='input_5_7' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_5_7'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_5_1\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_1'>Votre nom:<\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_5_1' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_5_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_2'>Votre adresse Email:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_5_2' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_5_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_3'>Votre t\u00e9l\u00e9phone:<\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_5_3' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_5_4\" class=\"gfield gfield--type-textarea field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_4'>Votre message:<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_5_4' class='textarea medium'   maxlength='800'   aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_5_5\" class=\"gfield gfield--type-checkbox gfield--type-choice field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_5_5'><li class='gchoice gchoice_5_5_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.1' type='checkbox'  value='Je souhaite m&#039;abonner \u00e0 la newsletter French District Las Vegas et recevoir des bons plans' checked='checked' id='choice_5_5_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_5_5_1' id='label_5_5_1' class='gform-field-label gform-field-label--type-inline'>Je souhaite m'abonner \u00e0 la newsletter French District Las Vegas et recevoir des bons plans<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_5_6\" class=\"gfield gfield--type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text' for='input_5_6'><\/label><div id='input_5_6' class='ginput_container ginput_recaptcha' data-sitekey='6Ldt8T8pAAAAAGjed3W4for4vBHh05M38nSQGx0t'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_5' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Envoyer'  \/> <input type='hidden' name='gform_ajax' value='form_id=5&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=7944630d7cf46f6bac9915fce8c5979a' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_5' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_5' id='gform_theme_5' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_5' id='gform_style_settings_5' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_5' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='5' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='X68M4zXbl1QvGvoHxA4hXI4mC3EWcMsHBo5q7U9FjXLXtNeo435XsNQTtk\/KMONvQGHpyNFWGKWwS\/qXtp7QCC6btw6FSpJNsuIEYx6pcvnMQ0E=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_5' value='WyJbXSIsIjYxMWFmYjlmMzI4ZTI4YmYzMThjYTg1MDIyODQ0YTljIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_5' id='gform_target_page_number_5' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_5' id='gform_source_page_number_5' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_5' id='gform_ajax_frame_5' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 5, 'https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_5').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_5');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_5').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_5').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_5').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_5').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_5').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_5').val();gformInitSpinner( 5, 'https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [5, current_page]);window['gf_submitting_5'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_5').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_5').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [5]);window['gf_submitting_5'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_5').text());}else{jQuery('#gform_5').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"5\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_5\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_5\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_5\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 5, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>Le DUI : Conduire en \u00e9tat d&#8217;\u00e9bri\u00e9t\u00e9 Driver Under the Influence \u2013 oui, mais de quoi ? L&#8217;alcool et le volant aux Etats-Unis est un sujet pris tr\u00e8s au s\u00e9rieux. Le \u00ab\u00a0DUI\u00a0\u00bb (prononcer \u00ab\u00a0di-you-aye\u00a0\u00bb) : \u00ab\u00a0Driving Under the Influence\u00a0\u00bb signifie conduire en \u00e9tat d\u2019\u00e9bri\u00e9t\u00e9, et\/ou sous l\u2019influence de drogues. Le DUI \u2013 ou DWI \u00ab\u00a0Driving [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":86223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[345,1420,96,1418],"tags":[501,1019,442,1020,98,337,267,414],"class_list":["post-5044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-monde-expatriation","category-sejour-vacances-etats-unis","category-nouveaux-arrivants","category-transport-etats-unis","tag-alcool","tag-alcotest","tag-decouvrir","tag-drogue","tag-legislation","tag-police","tag-vie-quotidienne","tag-voiture"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;alcool au volant aux Etats-Unis - DUI aux Etats-Unis<\/title>\n<meta name=\"description\" content=\"Taux limite d\u2019alcool\u00e9mie, arrestation et cons\u00e9quences de la conduite en \u00e9tat d\u2019ivresse : avant de boire et de conduire, voici quelques infos sur le DUI.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;alcool au volant aux Etats-Unis - DUI aux Etats-Unis\" \/>\n<meta property=\"og:description\" content=\"Taux limite d\u2019alcool\u00e9mie, arrestation et cons\u00e9quences de la conduite en \u00e9tat d\u2019ivresse : avant de boire et de conduire, voici quelques infos sur le DUI.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/\" \/>\n<meta property=\"og:site_name\" content=\"Las Vegas Nevada Arizona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frenchdistrict\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-18T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-13T18:58:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/uploads\/sites\/11\/2021\/05\/dui-alcool-volant-danger-conduite-ivresse-etats-unis-une_7399105.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1095\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tZaFNBo4R9Yh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:site\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"tZaFNBo4R9Yh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/\",\"url\":\"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/\",\"name\":\"L'alcool au volant aux Etats-Unis - DUI aux Etats-Unis\",\"isPartOf\":{\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/uploads\/sites\/11\/2021\/05\/dui-alcool-volant-danger-conduite-ivresse-etats-unis-une_7399105.jpg\",\"datePublished\":\"2013-09-18T04:00:00+00:00\",\"dateModified\":\"2020-11-13T18:58:38+00:00\",\"author\":{\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"description\":\"Taux limite d\u2019alcool\u00e9mie, arrestation et cons\u00e9quences de la conduite en \u00e9tat d\u2019ivresse : avant de boire et de conduire, voici quelques infos sur le DUI.\",\"breadcrumb\":{\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/#primaryimage\",\"url\":\"https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/uploads\/sites\/11\/2021\/05\/dui-alcool-volant-danger-conduite-ivresse-etats-unis-une_7399105.jpg\",\"contentUrl\":\"https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/uploads\/sites\/11\/2021\/05\/dui-alcool-volant-danger-conduite-ivresse-etats-unis-une_7399105.jpg\",\"width\":1600,\"height\":1095,\"caption\":\"dui-alcool-volant-danger-conduite-ivresse-etats-unis-une\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Las Vegas\",\"item\":\"https:\/\/frenchdistrict.com\/las-vegas\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Standard\",\"item\":\"https:\/\/frenchdistrict.com\/las-vegas\/listing_type\/standard\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le DUI, l\u2019alcool et le volant aux \u00c9tats-Unis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/#website\",\"url\":\"https:\/\/frenchdistrict.com\/las-vegas\/\",\"name\":\"Las Vegas Nevada Arizona\",\"description\":\"Le meilleur du &lt;span&gt;Nevada&lt;\/span&gt; et de l&#039;&lt;span&gt;Arizona&lt;\/span&gt; par ceux qui y vivent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/frenchdistrict.com\/las-vegas\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010\",\"name\":\"tZaFNBo4R9Yh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/frenchdistrict.com\/las-vegas\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"caption\":\"tZaFNBo4R9Yh\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'alcool au volant aux Etats-Unis - DUI aux Etats-Unis","description":"Taux limite d\u2019alcool\u00e9mie, arrestation et cons\u00e9quences de la conduite en \u00e9tat d\u2019ivresse : avant de boire et de conduire, voici quelques infos sur le DUI.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/","og_locale":"fr_FR","og_type":"article","og_title":"L'alcool au volant aux Etats-Unis - DUI aux Etats-Unis","og_description":"Taux limite d\u2019alcool\u00e9mie, arrestation et cons\u00e9quences de la conduite en \u00e9tat d\u2019ivresse : avant de boire et de conduire, voici quelques infos sur le DUI.","og_url":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/","og_site_name":"Las Vegas Nevada Arizona","article_publisher":"https:\/\/www.facebook.com\/frenchdistrict","article_published_time":"2013-09-18T04:00:00+00:00","article_modified_time":"2020-11-13T18:58:38+00:00","og_image":[{"width":1600,"height":1095,"url":"https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/uploads\/sites\/11\/2021\/05\/dui-alcool-volant-danger-conduite-ivresse-etats-unis-une_7399105.jpg","type":"image\/jpeg"}],"author":"tZaFNBo4R9Yh","twitter_card":"summary_large_image","twitter_creator":"@frenchdistrict","twitter_site":"@frenchdistrict","twitter_misc":{"\u00c9crit par":"tZaFNBo4R9Yh","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/","url":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/","name":"L'alcool au volant aux Etats-Unis - DUI aux Etats-Unis","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/las-vegas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/#primaryimage"},"image":{"@id":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/uploads\/sites\/11\/2021\/05\/dui-alcool-volant-danger-conduite-ivresse-etats-unis-une_7399105.jpg","datePublished":"2013-09-18T04:00:00+00:00","dateModified":"2020-11-13T18:58:38+00:00","author":{"@id":"https:\/\/frenchdistrict.com\/las-vegas\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"description":"Taux limite d\u2019alcool\u00e9mie, arrestation et cons\u00e9quences de la conduite en \u00e9tat d\u2019ivresse : avant de boire et de conduire, voici quelques infos sur le DUI.","breadcrumb":{"@id":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/#primaryimage","url":"https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/uploads\/sites\/11\/2021\/05\/dui-alcool-volant-danger-conduite-ivresse-etats-unis-une_7399105.jpg","contentUrl":"https:\/\/frenchdistrict.com\/las-vegas\/wp-content\/uploads\/sites\/11\/2021\/05\/dui-alcool-volant-danger-conduite-ivresse-etats-unis-une_7399105.jpg","width":1600,"height":1095,"caption":"dui-alcool-volant-danger-conduite-ivresse-etats-unis-une"},{"@type":"BreadcrumbList","@id":"https:\/\/frenchdistrict.com\/las-vegas\/articles\/dui-alcool-volant-danger-conduite-ivresse-etats-unis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Las Vegas","item":"https:\/\/frenchdistrict.com\/las-vegas\/"},{"@type":"ListItem","position":2,"name":"Standard","item":"https:\/\/frenchdistrict.com\/las-vegas\/listing_type\/standard\/"},{"@type":"ListItem","position":3,"name":"Le DUI, l\u2019alcool et le volant aux \u00c9tats-Unis"}]},{"@type":"WebSite","@id":"https:\/\/frenchdistrict.com\/las-vegas\/#website","url":"https:\/\/frenchdistrict.com\/las-vegas\/","name":"Las Vegas Nevada Arizona","description":"Le meilleur du &lt;span&gt;Nevada&lt;\/span&gt; et de l&#039;&lt;span&gt;Arizona&lt;\/span&gt; par ceux qui y vivent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchdistrict.com\/las-vegas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/frenchdistrict.com\/las-vegas\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010","name":"tZaFNBo4R9Yh","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/las-vegas\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","caption":"tZaFNBo4R9Yh"}}]}},"_links":{"self":[{"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/posts\/5044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/comments?post=5044"}],"version-history":[{"count":4,"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/posts\/5044\/revisions"}],"predecessor-version":[{"id":86222,"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/posts\/5044\/revisions\/86222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/media\/86223"}],"wp:attachment":[{"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/media?parent=5044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/categories?post=5044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchdistrict.com\/las-vegas\/wp-json\/wp\/v2\/tags?post=5044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}