{"id":27560,"date":"2013-10-28T00:00:00","date_gmt":"2013-10-28T04:00:00","guid":{"rendered":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/"},"modified":"2022-08-03T09:03:47","modified_gmt":"2022-08-03T13:03:47","slug":"faire-des-travaux-maison-etats-unis","status":"publish","type":"post","link":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/","title":{"rendered":"Vous souhaitez faire des travaux\u00a0?"},"content":{"rendered":"<p>Un <strong>architecte<\/strong> et un <strong>designer<\/strong> pour les plans de votre future maison, un <strong>ma\u00e7on<\/strong> pour sa construction, un <strong>plombier<\/strong> ou un <strong>\u00e9lectricien<\/strong>&#8230; Notre r\u00e9seau est compos\u00e9 de centaines de professionnels qui partagent l\u2019esprit French District. Afin de gagner du temps, si vous souhaitez faire des travaux chez vous, dans votre commerce ou dans vos bureaux, notre service va vous mettre en relation avec le professionnel dont vous avez besoin.<\/p>\n<p>Pour contacter notre service, utilisez le formulaire ci-dessous :<\/p>\n<script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_8' ><div id='gf_8' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_8' id='gform_8'  action='\/new-york\/wp-json\/wp\/v2\/posts\/27560#gf_8' data-formid='8' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_8' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_8_7\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_7'>URL<\/label><div class='ginput_container'><input name='input_7' id='input_8_7' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_8_7'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_8_1\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_1'>Votre nom:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_8_1' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_2'>Votre adresse Email:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_8_2' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_8_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_3'>Votre t\u00e9l\u00e9phone:<\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_8_3' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_8_4\" class=\"gfield gfield--type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_4'>Votre message:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_8_4' class='textarea medium'   maxlength='800'  aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_8_5\" class=\"gfield gfield--type-checkbox gfield--type-choice field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_8_5'><li class='gchoice gchoice_8_5_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.1' type='checkbox'  value='Je souhaite recevoir la newsletter French District de New York et recevoir des bons plans' checked='checked' id='choice_8_5_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_8_5_1' id='label_8_5_1' class='gform-field-label gform-field-label--type-inline'>Je souhaite recevoir la newsletter French District de New York et recevoir des bons plans<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_8_6\" class=\"gfield gfield--type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text' for='input_8_6'><\/label><div id='input_8_6' class='ginput_container ginput_recaptcha' data-sitekey='6Ldt8T8pAAAAAGjed3W4for4vBHh05M38nSQGx0t'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_8' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Envoyer'  \/> <input type='hidden' name='gform_ajax' value='form_id=8&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=633fb14af9ba6a764e981c647b8d866f' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_8' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_8' id='gform_theme_8' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_8' id='gform_style_settings_8' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_8' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='8' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='xrzfQMIPmECyAXKGZNbOAVXoHew4hNXc6iiVuw+Z4tZ7ihkVvzR1pRXi+ygEWCsal\/vfeQMaTLosJ45VYp2ql+OTDgtxGRT\/\/RyE\/qfCDZ+ycGk=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_8' value='WyJbXSIsIjYxMWFmYjlmMzI4ZTI4YmYzMThjYTg1MDIyODQ0YTljIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_8' id='gform_target_page_number_8' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_8' id='gform_source_page_number_8' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_8' id='gform_ajax_frame_8' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 8, 'https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_8').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_8');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_8').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_8').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_8').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_8').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_8').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_8').val();gformInitSpinner( 8, 'https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [8, current_page]);window['gf_submitting_8'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_8').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_8').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [8]);window['gf_submitting_8'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_8').text());}else{jQuery('#gform_8').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"8\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_8\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_8\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_8\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 8, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n<h2>Les services French District<\/h2>\n<style type=\"text\/css\">#soliloquy-container-141492 a.soliloquy-fc-title-link {font-size: 12px; font-weight:100;}#soliloquy-container-141492 h2,#soliloquy-container-141492.soliloquy-fc-slider .soliloquy-caption-inside .soliloquy-fc-title,#soliloquy-container-141492 .soliloquy-fc-slider .soliloquy-caption-inside .soliloquy-fc-title-link {margin-bottom:0;margin-top:0;}#soliloquy-container-141492.soliloquy-theme-base .soliloquy-caption-bottom .soliloquy-caption-inside {padding-bottom:10px; }<\/style><div class=\"soliloquy-outer-container soliloquy-carousel\" data-soliloquy-loaded=\"0\"><div aria-live=\"polite\" id=\"soliloquy-container-141492_1\" class=\"soliloquy-container soliloquy-transition-horizontal soliloquy-slide-horizontal soliloquy-arrows-active  soliloquy-theme-base no-js soliloquy-fc-slider\" style=\"max-width:960px;margin:0 auto 20px;\"><ul id=\"soliloquy-141492_1\" class=\"soliloquy-slider soliloquy-slides soliloquy-wrap soliloquy-clear\"><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-1 soliloquy-image-slide soliloquy-post-80106 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/transferer-argent-etranger-echanger-devises-meilleur-taux-new-york\/\" class=\"soliloquy-link\" title=\"Vous souhaitez transf\u00e9rer de l&#039;argent ou \u00e9changer des devises depuis ou vers \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-80106\" class=\"soliloquy-image soliloquy-image-1\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/12-services-transfert-argent-change-1-250x200_c.jpg\" alt=\"Vous souhaitez transf\u00e9rer de l&#039;argent ou \u00e9changer des devises depuis ou vers \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/transferer-argent-etranger-echanger-devises-meilleur-taux-new-york\/\" title=\"Vous souhaitez transf\u00e9rer de l&#039;argent ou \u00e9changer des devises depuis ou vers \u00e0 New York ?\">Vous souhaitez transf\u00e9rer de l'argent ou \u00e9changer des devises depuis ou vers \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-2 soliloquy-image-slide soliloquy-post-80101 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/medecin-dentiste-pediatre-gynecologue-opticien-francais-new-york\/\" class=\"soliloquy-link\" title=\"Vous cherchez un m\u00e9decin ou un dentiste \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-80101\" class=\"soliloquy-image soliloquy-image-2 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/12-services-expedier-produits-affaires-medecin-une-1-250x200_c.jpg\" alt=\"Vous cherchez un m\u00e9decin ou un dentiste \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/medecin-dentiste-pediatre-gynecologue-opticien-francais-new-york\/\" title=\"Vous cherchez un m\u00e9decin ou un dentiste \u00e0 New York ?\">Vous cherchez un m\u00e9decin ou un dentiste \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-3 soliloquy-image-slide soliloquy-post-80201 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/vente-produits-francais-new-york\/\" class=\"soliloquy-link\" title=\"Vous souhaitez acheter des produits fran\u00e7ais \u00e0 New York?\"><img decoding=\"async\" id=\"soliloquy-image-80201\" class=\"soliloquy-image soliloquy-image-3 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-produit-francais-alimentation-etats-unis-250x200_c.jpg\" alt=\"Vous souhaitez acheter des produits fran\u00e7ais \u00e0 New York?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/vente-produits-francais-new-york\/\" title=\"Vous souhaitez acheter des produits fran\u00e7ais \u00e0 New York?\">Vous souhaitez acheter des produits fran\u00e7ais \u00e0 New York?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-4 soliloquy-image-slide soliloquy-post-79577 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/avocat-francophone-francais-new-york\/\" class=\"soliloquy-link\" title=\"Vous recherchez un avocat qui parle francais \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-79577\" class=\"soliloquy-image soliloquy-image-4 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/avocat-francophone-francais-250x200_c.jpg\" alt=\"Vous recherchez un avocat qui parle francais \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/avocat-francophone-francais-new-york\/\" title=\"Vous recherchez un avocat qui parle francais \u00e0 New York ?\">Vous recherchez un avocat qui parle francais \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-5 soliloquy-image-slide soliloquy-post-79657 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/vous-souhaitez-organiser-ou-accueillir-un-evenement-a-new-york\/\" class=\"soliloquy-link\" title=\"Vous souhaitez organiser ou accueillir un \u00e9v\u00e9nement \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-79657\" class=\"soliloquy-image soliloquy-image-5 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/organiser-accueillir-evenement-250x200_c.jpg\" alt=\"Vous souhaitez organiser ou accueillir un \u00e9v\u00e9nement \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/vous-souhaitez-organiser-ou-accueillir-un-evenement-a-new-york\/\" title=\"Vous souhaitez organiser ou accueillir un \u00e9v\u00e9nement \u00e0 New York ?\">Vous souhaitez organiser ou accueillir un \u00e9v\u00e9nement \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-6 soliloquy-image-slide soliloquy-post-79783 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/location-vente-appartement-maison-new-york\/\" class=\"soliloquy-link\" title=\"Vous souhaitez louer un appartement ou une maison \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-79783\" class=\"soliloquy-image soliloquy-image-6 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-agent-immobiliere-etats-unis-demenager-1-250x200_c.jpg\" alt=\"Vous souhaitez louer un appartement ou une maison \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/location-vente-appartement-maison-new-york\/\" title=\"Vous souhaitez louer un appartement ou une maison \u00e0 New York ?\">Vous souhaitez louer un appartement ou une maison \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-7 soliloquy-image-slide soliloquy-post-79767 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/vous-souhaitez-acheter-un-appartement-ou-une-maison-a-new-york\/\" class=\"soliloquy-link\" title=\"Vous souhaitez acheter un appartement ou une maison \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-79767\" class=\"soliloquy-image soliloquy-image-7 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/acheter-appartement-maison-etats-unis-1-250x200_c.jpg\" alt=\"Vous souhaitez acheter un appartement ou une maison \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/vous-souhaitez-acheter-un-appartement-ou-une-maison-a-new-york\/\" title=\"Vous souhaitez acheter un appartement ou une maison \u00e0 New York ?\">Vous souhaitez acheter un appartement ou une maison \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-8 soliloquy-image-slide soliloquy-post-80205 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/recherche-professionnel-francais-new-york\/\" class=\"soliloquy-link\" title=\"Vous recherchez un professionnel \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-80205\" class=\"soliloquy-image soliloquy-image-8 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-professionnel-freelance-francais-francophone-etats-unis-250x200_c.jpg\" alt=\"Vous recherchez un professionnel \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/recherche-professionnel-francais-new-york\/\" title=\"Vous recherchez un professionnel \u00e0 New York ?\">Vous recherchez un professionnel \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-9 soliloquy-image-slide soliloquy-post-79859 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/investir-a-new-york\/\" class=\"soliloquy-link\" title=\"Vous voulez investir \u00e0 New York?\"><img decoding=\"async\" id=\"soliloquy-image-79859\" class=\"soliloquy-image soliloquy-image-9 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/12-services-investir-aux-etats-unis-250x200_c.jpg\" alt=\"Vous voulez investir \u00e0 New York?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/investir-a-new-york\/\" title=\"Vous voulez investir \u00e0 New York?\">Vous voulez investir \u00e0 New York?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-10 soliloquy-image-slide soliloquy-post-80198 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/recherche-comptable-francais-francophone-new-york\/\" class=\"soliloquy-link\" title=\"Vous recherchez un comptable \/ CPA \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-80198\" class=\"soliloquy-image soliloquy-image-10 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-comptable-francais-francophone-etats-unis-250x200_c.jpg\" alt=\"Vous recherchez un comptable \/ CPA \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/recherche-comptable-francais-francophone-new-york\/\" title=\"Vous recherchez un comptable \/ CPA \u00e0 New York ?\">Vous recherchez un comptable \/ CPA \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-11 soliloquy-image-slide soliloquy-post-79772 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/vous-avez-besoin-dune-assurance-a-new-york\/\" class=\"soliloquy-link\" title=\"Vous avez besoin d\u2019une assurance \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-79772\" class=\"soliloquy-image soliloquy-image-11 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-assurance-sante-famille-voiture-etats-unis-1-1-250x200_c.jpg\" alt=\"Vous avez besoin d\u2019une assurance \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/vous-avez-besoin-dune-assurance-a-new-york\/\" title=\"Vous avez besoin d\u2019une assurance \u00e0 New York ?\">Vous avez besoin d\u2019une assurance \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-12 soliloquy-image-slide soliloquy-post-80238 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/ecole-francaise-francophone-new-york\/\" class=\"soliloquy-link\" title=\"Vous recherchez une \u00e9cole \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-80238\" class=\"soliloquy-image soliloquy-image-12 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-ecole-francais-francophone-etats-unis-250x200_c.jpg\" alt=\"Vous recherchez une \u00e9cole \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/ecole-francaise-francophone-new-york\/\" title=\"Vous recherchez une \u00e9cole \u00e0 New York ?\">Vous recherchez une \u00e9cole \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-13 soliloquy-image-slide soliloquy-post-79662 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/vous-recherchez-un-restaurant-a-new-york\/\" class=\"soliloquy-link\" title=\"Vous recherchez un restaurant \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-79662\" class=\"soliloquy-image soliloquy-image-13 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/meilleurs-restaurants-etats-unis-recherche-1-250x200_c.jpg\" alt=\"Vous recherchez un restaurant \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/vous-recherchez-un-restaurant-a-new-york\/\" title=\"Vous recherchez un restaurant \u00e0 New York ?\">Vous recherchez un restaurant \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-14 soliloquy-image-slide soliloquy-post-79856 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/expedier-produits-affaires-demenager-new-york\/\" class=\"soliloquy-link\" title=\"Vous avez besoin d\u2019exp\u00e9dier des produits, des affaires, de d\u00e9m\u00e9nager \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-79856\" class=\"soliloquy-image soliloquy-image-14 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/12-services-expedier-produits-affaires-demenager-une-new-york-250x200_c.jpg\" alt=\"Vous avez besoin d\u2019exp\u00e9dier des produits, des affaires, de d\u00e9m\u00e9nager \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/expedier-produits-affaires-demenager-new-york\/\" title=\"Vous avez besoin d\u2019exp\u00e9dier des produits, des affaires, de d\u00e9m\u00e9nager \u00e0 New York ?\">Vous avez besoin d\u2019exp\u00e9dier des produits, des affaires, de d\u00e9m\u00e9nager \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-15 soliloquy-image-slide soliloquy-post-79951 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/service-entreprise-b2b-new-york\/\" class=\"soliloquy-link\" title=\"Vous avez besoin d\u2019un service pour votre entreprise \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-79951\" class=\"soliloquy-image soliloquy-image-15 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/service-entreprise-etats-unis-NEW-YORK-250x200_c.jpg\" alt=\"Vous avez besoin d\u2019un service pour votre entreprise \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/service-entreprise-b2b-new-york\/\" title=\"Vous avez besoin d\u2019un service pour votre entreprise \u00e0 New York ?\">Vous avez besoin d\u2019un service pour votre entreprise \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-16 soliloquy-image-slide soliloquy-post-80195 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/recherche-banque-new-york\/\" class=\"soliloquy-link\" title=\"Vous recherchez une banque \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-80195\" class=\"soliloquy-image soliloquy-image-16 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-banque-argent-etats-unis-250x200_c.jpg\" alt=\"Vous recherchez une banque \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/recherche-banque-new-york\/\" title=\"Vous recherchez une banque \u00e0 New York ?\">Vous recherchez une banque \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-17 soliloquy-image-slide soliloquy-post-79800 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/visa-conseil-avocat-expatriation-new-york\/\" class=\"soliloquy-link\" title=\"Vous avez besoin d\u2019un visa, d\u2019un conseil pour immigrer \u00e0 New York ?\"><img decoding=\"async\" id=\"soliloquy-image-79800\" class=\"soliloquy-image soliloquy-image-17 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/visa-e2-investisseur-employe-franchise-cdp-250x200_c.jpg\" alt=\"Vous avez besoin d\u2019un visa, d\u2019un conseil pour immigrer \u00e0 New York ?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/visa-conseil-avocat-expatriation-new-york\/\" title=\"Vous avez besoin d\u2019un visa, d\u2019un conseil pour immigrer \u00e0 New York ?\">Vous avez besoin d\u2019un visa, d\u2019un conseil pour immigrer \u00e0 New York ?<\/a><\/h2><\/div><\/div><\/div><\/li><li aria-hidden=\"true\" class=\"soliloquy-item soliloquy-item-18 soliloquy-image-slide soliloquy-post-27560 soliloquy-post soliloquy-type-post soliloquy-status-publish soliloquy-format-standard soliloquy-has-post-thumbnail soliloquy-hentry soliloquy-category-12-services-french-district soliloquy-tag-12-services soliloquy-tag-appartement soliloquy-tag-maison soliloquy-tag-travaux\" draggable=\"false\" style=\"list-style:none;\"><a href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/\" class=\"soliloquy-link\" title=\"Vous souhaitez faire des travaux\u00a0?\"><img decoding=\"async\" id=\"soliloquy-image-27560\" class=\"soliloquy-image soliloquy-image-18 soliloquy-preload\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/plugins\/soliloquy\/assets\/css\/images\/holder.gif\" data-soliloquy-src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2022\/08\/travaux-etats-unis_1690475_8024954_7208286-250x200_c.jpg\" alt=\"Vous souhaitez faire des travaux\u00a0?\" loading=\"lazy\" \/><\/a><div class=\"soliloquy-caption soliloquy-caption-bottom\"><div class=\"soliloquy-caption-inside\"><div class=\"soliloquy-fc-caption\"><h2 class=\"soliloquy-fc-title\"><a class=\"soliloquy-fc-title-link\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/\" title=\"Vous souhaitez faire des travaux\u00a0?\">Vous souhaitez faire des travaux\u00a0?<\/a><\/h2><\/div><\/div><\/div><\/li><\/ul><\/div><noscript><div class=\"soliloquy-no-js\" style=\"display:none;visibility:hidden;height:0;line-height:0;opacity:0;\"><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/12-services-transfert-argent-change-1.jpg\" alt=\"Vous souhaitez transf\u00e9rer de l&#039;argent ou \u00e9changer des devises depuis ou vers \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/12-services-expedier-produits-affaires-medecin-une-1.jpg\" alt=\"Vous cherchez un m\u00e9decin ou un dentiste \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-produit-francais-alimentation-etats-unis.jpg\" alt=\"Vous souhaitez acheter des produits fran\u00e7ais \u00e0 New York?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/avocat-francophone-francais.jpg\" alt=\"Vous recherchez un avocat qui parle francais \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/organiser-accueillir-evenement.jpg\" alt=\"Vous souhaitez organiser ou accueillir un \u00e9v\u00e9nement \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-agent-immobiliere-etats-unis-demenager-1.jpg\" alt=\"Vous souhaitez louer un appartement ou une maison \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/acheter-appartement-maison-etats-unis-1.jpg\" alt=\"Vous souhaitez acheter un appartement ou une maison \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-professionnel-freelance-francais-francophone-etats-unis.jpg\" alt=\"Vous recherchez un professionnel \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/12-services-investir-aux-etats-unis.jpg\" alt=\"Vous voulez investir \u00e0 New York?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-comptable-francais-francophone-etats-unis.jpg\" alt=\"Vous recherchez un comptable \/ CPA \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-assurance-sante-famille-voiture-etats-unis-1-1.jpg\" alt=\"Vous avez besoin d\u2019une assurance \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-ecole-francais-francophone-etats-unis.jpg\" alt=\"Vous recherchez une \u00e9cole \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/meilleurs-restaurants-etats-unis-recherche-1.jpg\" alt=\"Vous recherchez un restaurant \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/12-services-expedier-produits-affaires-demenager-une-new-york.jpg\" alt=\"Vous avez besoin d\u2019exp\u00e9dier des produits, des affaires, de d\u00e9m\u00e9nager \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/service-entreprise-etats-unis-NEW-YORK.jpg\" alt=\"Vous avez besoin d\u2019un service pour votre entreprise \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/recherche-banque-argent-etats-unis.jpg\" alt=\"Vous recherchez une banque \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/visa-e2-investisseur-employe-franchise-cdp.jpg\" alt=\"Vous avez besoin d\u2019un visa, d\u2019un conseil pour immigrer \u00e0 New York ?\" \/><img decoding=\"async\" class=\"soliloquy-image soliloquy-no-js-image skip-lazy\" src=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2022\/08\/travaux-etats-unis_1690475_8024954_7208286.jpg\" alt=\"Vous souhaitez faire des travaux\u00a0?\" \/><\/div><\/noscript><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un architecte et un designer pour les plans de votre future maison, un ma\u00e7on pour sa construction, un plombier ou un \u00e9lectricien&#8230; Notre r\u00e9seau est compos\u00e9 de centaines de professionnels qui partagent l\u2019esprit French District. Afin de gagner du temps, si vous souhaitez faire des travaux chez vous, dans votre commerce ou dans vos bureaux, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":141456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[969],"tags":[2228,1387,1432,973],"class_list":["post-27560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-12-services-french-district","tag-12-services","tag-appartement","tag-maison","tag-travaux"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vous souhaitez faire des travaux\u00a0? - New York<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vous souhaitez faire des travaux\u00a0? - New York\" \/>\n<meta property=\"og:description\" content=\"Un architecte et un designer pour les plans de votre future maison, un ma\u00e7on pour sa construction, un plombier ou un \u00e9lectricien&#8230; Notre r\u00e9seau est compos\u00e9 de centaines de professionnels qui partagent l\u2019esprit French District. Afin de gagner du temps, si vous souhaitez faire des travaux chez vous, dans votre commerce ou dans vos bureaux, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/\" \/>\n<meta property=\"og:site_name\" content=\"New York\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frenchdistrict\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-28T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-03T13:03:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/travaux-etats-unis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tZaFNBo4R9Yh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:site\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"tZaFNBo4R9Yh\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/\"},\"author\":{\"name\":\"tZaFNBo4R9Yh\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"headline\":\"Vous souhaitez faire des travaux\u00a0?\",\"datePublished\":\"2013-10-28T04:00:00+00:00\",\"dateModified\":\"2022-08-03T13:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/\"},\"wordCount\":94,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/travaux-etats-unis_1690475_8024954_7208286.jpg\",\"keywords\":[\"12 services\",\"appartement\",\"maison\",\"travaux\"],\"articleSection\":[\"Les 12 services French District\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/\",\"name\":\"Vous souhaitez faire des travaux\u00a0? - New York\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/travaux-etats-unis_1690475_8024954_7208286.jpg\",\"datePublished\":\"2013-10-28T04:00:00+00:00\",\"dateModified\":\"2022-08-03T13:03:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/travaux-etats-unis_1690475_8024954_7208286.jpg\",\"contentUrl\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/08\\\/travaux-etats-unis_1690475_8024954_7208286.jpg\",\"width\":1350,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/articles\\\/faire-des-travaux-maison-etats-unis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"New York\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les 12 services French District\",\"item\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/12-services-french-district\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vous souhaitez faire des travaux\u00a0?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/#website\",\"url\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/\",\"name\":\"New York\",\"description\":\"Le meilleur de  &lt;span&gt;New York&lt;\\\/span&gt; par ceux qui y vivent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/frenchdistrict.com\\\/new-york\\\/#\\\/schema\\\/person\\\/ca7493f7cf3c0f3dd252acaa99a10010\",\"name\":\"tZaFNBo4R9Yh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"caption\":\"tZaFNBo4R9Yh\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vous souhaitez faire des travaux\u00a0? - New York","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/","og_locale":"fr_FR","og_type":"article","og_title":"Vous souhaitez faire des travaux\u00a0? - New York","og_description":"Un architecte et un designer pour les plans de votre future maison, un ma\u00e7on pour sa construction, un plombier ou un \u00e9lectricien&#8230; Notre r\u00e9seau est compos\u00e9 de centaines de professionnels qui partagent l\u2019esprit French District. Afin de gagner du temps, si vous souhaitez faire des travaux chez vous, dans votre commerce ou dans vos bureaux, [&hellip;]","og_url":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/","og_site_name":"New York","article_publisher":"https:\/\/www.facebook.com\/frenchdistrict","article_published_time":"2013-10-28T04:00:00+00:00","article_modified_time":"2022-08-03T13:03:47+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2019\/12\/travaux-etats-unis.jpg","type":"image\/jpeg"}],"author":"tZaFNBo4R9Yh","twitter_card":"summary_large_image","twitter_creator":"@frenchdistrict","twitter_site":"@frenchdistrict","twitter_misc":{"\u00c9crit par":"tZaFNBo4R9Yh"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/#article","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/"},"author":{"name":"tZaFNBo4R9Yh","@id":"https:\/\/frenchdistrict.com\/new-york\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"headline":"Vous souhaitez faire des travaux\u00a0?","datePublished":"2013-10-28T04:00:00+00:00","dateModified":"2022-08-03T13:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/"},"wordCount":94,"commentCount":0,"image":{"@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2022\/08\/travaux-etats-unis_1690475_8024954_7208286.jpg","keywords":["12 services","appartement","maison","travaux"],"articleSection":["Les 12 services French District"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/","url":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/","name":"Vous souhaitez faire des travaux\u00a0? - New York","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/new-york\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/#primaryimage"},"image":{"@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2022\/08\/travaux-etats-unis_1690475_8024954_7208286.jpg","datePublished":"2013-10-28T04:00:00+00:00","dateModified":"2022-08-03T13:03:47+00:00","author":{"@id":"https:\/\/frenchdistrict.com\/new-york\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"breadcrumb":{"@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/#primaryimage","url":"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2022\/08\/travaux-etats-unis_1690475_8024954_7208286.jpg","contentUrl":"https:\/\/frenchdistrict.com\/new-york\/wp-content\/uploads\/sites\/3\/2022\/08\/travaux-etats-unis_1690475_8024954_7208286.jpg","width":1350,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/frenchdistrict.com\/new-york\/articles\/faire-des-travaux-maison-etats-unis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"New York","item":"https:\/\/frenchdistrict.com\/new-york\/"},{"@type":"ListItem","position":2,"name":"Les 12 services French District","item":"https:\/\/frenchdistrict.com\/new-york\/12-services-french-district\/"},{"@type":"ListItem","position":3,"name":"Vous souhaitez faire des travaux\u00a0?"}]},{"@type":"WebSite","@id":"https:\/\/frenchdistrict.com\/new-york\/#website","url":"https:\/\/frenchdistrict.com\/new-york\/","name":"New York","description":"Le meilleur de  &lt;span&gt;New York&lt;\/span&gt; par ceux qui y vivent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchdistrict.com\/new-york\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/frenchdistrict.com\/new-york\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010","name":"tZaFNBo4R9Yh","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","caption":"tZaFNBo4R9Yh"}}]}},"_links":{"self":[{"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/posts\/27560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/comments?post=27560"}],"version-history":[{"count":4,"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/posts\/27560\/revisions"}],"predecessor-version":[{"id":141455,"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/posts\/27560\/revisions\/141455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/media\/141456"}],"wp:attachment":[{"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/media?parent=27560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/categories?post=27560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchdistrict.com\/new-york\/wp-json\/wp\/v2\/tags?post=27560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}