{"id":17181,"date":"2014-04-01T23:00:00","date_gmt":"2014-04-02T04:00:00","guid":{"rendered":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/"},"modified":"2022-11-23T20:57:40","modified_gmt":"2022-11-24T01:57:40","slug":"louer-services-policier-police","status":"publish","type":"post","link":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/","title":{"rendered":"Louer les services d\u2019un policier"},"content":{"rendered":"<h2>Un policier peut en cacher un autre<\/h2>\n<p>Un <strong>policier<\/strong> \u00e0 la retraite, \u00e7a s\u2019emb\u00eate. Sans parler de ceux qui ont tellement d\u2019\u00e9nergie que leur semaine de labeur ne suffit pas ; ils ne peuvent se r\u00e9soudre \u00e0 rester inactifs.<\/p>\n\r\n\t<div class=\"sponsor__article sponsor__article--left\">\r\n\t\t<div class=\"inner\">\r\n\t\t\t<div class=\"sponsor__by\">Pr&eacute;sent&eacute; par...<\/div>\r\n\t\t\t<div>\r\n\t\t\t\t<a href=\"https:\/\/frenchdistrict.com\/presentez-entreprise\/\" target=\"_blank\">\r\n\t\t\t\t<div class=\"sponsor__illus\"><img decoding=\"async\" src=\"https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/uploads\/sites\/9\/2024\/05\/french-district-referencez-entreprise.png\" alt=\"French District\" \/><\/div>\r\n\t\t\t\t<div class=\"sponsor__content\">\r\n\t\t\t\t\t<p class=\"sponsor__title\">French District<\/p>\r\n\t\t\t\t\t<div class=\"sponsor__slogan\">French District : Le lien entre les entreprises et les expatri\u00e9s.<\/div>\r\n\t\t\t\t\t<div class=\"vce-button vce-button--small\" style=\"background-color: #444444;\"><i class=\"fa fa-hand-o-right\" aria-hidden=\"true\">&nbsp;<\/i>French District<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\t\t\r\n\t\t<\/div>\r\n\t<\/div>Retrait\u00e9s, mais aussi <strong>policiers<\/strong> de r\u00e9serve, anciens mainteneurs de l\u2019ordre ou encore policiers actifs, en dehors de leurs heures de travail, ils sont nombreux \u00e0 proposer leurs services de surveillance, de <strong>garde du corps<\/strong>, de s\u00e9curit\u00e9 rapproch\u00e9e\u2026<\/p>\n<p>Ils peuvent aussi \u00eatre appel\u00e9s pour jouer des gros bras que ce soit pour des raisons personnelles ou professionnelles \u2013 leurs services \u00e9tant fa\u00e7onnables \u00e0 votre commande et laiss\u00e9s \u00e0 votre pr\u00e9f\u00e9rence.<\/p>\n<h2>Allo, Police ? J\u2019ai besoin de vos services<\/h2>\n<h3>La Police \u00e0 ses frousses<\/h3>\n<p>Vous avez peur chez vous ? Plus rassurant que votre caniche, mais moins envahissant que votre voisin, louez les services d\u2019un <strong>policier<\/strong> pour votre confort personnel et votre s\u00e9curit\u00e9 individuelle.<\/p>\n<p>Ces <strong>agents<\/strong> restent alors \u00e0 votre disposition et peuvent aussi bien faire office de garde du corps pour votre propre <strong>surveillance,<\/strong> celle d\u2019un immeuble, ou d\u2019un complexe immobilier \u00e0 la demande d\u2019une association de propri\u00e9taires qui craint pour la s\u00e9curit\u00e9 de ses locataires.<\/p>\n<h3>Une police d\u2019assurance (tout risque)<\/h3>\n<p>Les <strong>policiers<\/strong> peuvent \u00e9galement se d\u00e9placer pour des \u00e9pisodes difficiles au bureau ou lors de congr\u00e8s, de s\u00e9minaires\u2026 Un employ\u00e9 qui refuse de faire ses cartons, une r\u00e9union de collaborateurs qui signent des arr\u00eats de mort plut\u00f4t que des protocoles, des proc\u00e8s en droit du travail qui tournent au vinaigre\u2026 On ne vous raconte pas de salade, tous ces gens \u00e9nerv\u00e9s peuvent finir dans le panier.<\/p>\n<h3>Mais que f\u00eate la Police ?<\/h3>\n<p>Vous pouvez aussi faire appel aux services de ces <strong>policiers<\/strong> pour vos \u00e9v\u00e9nements et soir\u00e9es personnelles ou particuli\u00e8res. Ils sont alors autant \u00e0 m\u00eame de d\u00e9voiler leur biscotos sur un tournage de film, de calmer les foules en d\u00e9lire les soirs de gala, ou de rabaisser le caquet des nerveux du ch\u00e9quier lors des soir\u00e9es de lev\u00e9es de fonds.<\/p>\n<p>Ils font \u00e9galement toujours leur petit effet aux mariages \u2013 attention, ceux ne sont pas des strip teaseurs ; les prendre pour des Chippendales serait du plus mauvais effet.<\/p>\n<i class=\"fa fa-link\" aria-hidden=\"true\"><\/i> <a href=\"https:\/\/www.offdutyofficers.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">offdutyofficers.com<\/a><\/p>\n<h2>Vous souhaitez savoir comment y avoir recours ?<br \/>\n\u00c9crivez-nous !<\/h2>\n<a name=\"contactfd\" style=\"display: block;position: relative;top: -150px;visibility: hidden;\"><\/a><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_6' ><div id='gf_6' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_6' id='gform_6'  action='\/washington-dc\/wp-json\/wp\/v2\/posts\/17181#gf_6' data-formid='6' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_6' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_6_7\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_7'>Phone<\/label><div class='ginput_container'><input name='input_7' id='input_6_7' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_6_7'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/li><li id=\"field_6_1\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_1'>Votre nom:<\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_6_1' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_6_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_2'>Votre adresse Email:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_6_2' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_6_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_3'>Votre t\u00e9l\u00e9phone:<\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_6_3' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_6_4\" class=\"gfield gfield--type-textarea field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_6_4'>Votre message:<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_6_4' class='textarea medium'   maxlength='800'   aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_6_5\" class=\"gfield gfield--type-checkbox gfield--type-choice field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text gfield_label_before_complex' ><\/label><div class='ginput_container ginput_container_checkbox'><ul class='gfield_checkbox' id='input_6_5'><li class='gchoice gchoice_6_5_1'>\n\t\t\t\t\t\t\t\t<input class='gfield-choice-input' name='input_5.1' type='checkbox'  value='Je souhaite m&#039;abonner \u00e0 la newsletter French District Washington DC et recevoir des bons plans' checked='checked' id='choice_6_5_1'   \/>\n\t\t\t\t\t\t\t\t<label for='choice_6_5_1' id='label_6_5_1' class='gform-field-label gform-field-label--type-inline'>Je souhaite m'abonner \u00e0 la newsletter French District Washington DC et recevoir des bons plans<\/label>\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/li><li id=\"field_6_6\" class=\"gfield gfield--type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label screen-reader-text' for='input_6_6'><\/label><div id='input_6_6' class='ginput_container ginput_recaptcha' data-sitekey='6Ldt8T8pAAAAAGjed3W4for4vBHh05M38nSQGx0t'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_6' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Envoyer'  \/> <input type='hidden' name='gform_ajax' value='form_id=6&amp;title=&amp;description=&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=1fca562c281bf1e1ed9ba3caa16c30d8' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_6' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_6' id='gform_theme_6' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_6' id='gform_style_settings_6' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_6' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='6' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='mUW\/8pC04986jfuj8aBeYcetG39itF4xk1TwCyImk5MDwQeMbm5+bDkdxQXOED\/NByFqK6Yck+67egBg6D2KG1O4G1pBVlo\/IeVwgguZtLQHwLc=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_6' value='WyJbXSIsIjYxMWFmYjlmMzI4ZTI4YmYzMThjYTg1MDIyODQ0YTljIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_6' id='gform_target_page_number_6' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_6' id='gform_source_page_number_6' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_6' id='gform_ajax_frame_6' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 6, 'https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_6').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_6');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_6').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_6').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_6').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_6').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_6').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_6').val();gformInitSpinner( 6, 'https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [6, current_page]);window['gf_submitting_6'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_6').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_6').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [6]);window['gf_submitting_6'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_6').text());}else{jQuery('#gform_6').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"6\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_6\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_6\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_6\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 6, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>Un policier peut en cacher un autre Un policier \u00e0 la retraite, \u00e7a s\u2019emb\u00eate. Sans parler de ceux qui ont tellement d\u2019\u00e9nergie que leur semaine de labeur ne suffit pas ; ils ne peuvent se r\u00e9soudre \u00e0 rester inactifs. Retrait\u00e9s, mais aussi policiers de r\u00e9serve, anciens mainteneurs de l\u2019ordre ou encore policiers actifs, en dehors [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":87402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[247],"tags":[622,531,635,306,941],"class_list":["post-17181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-insolite","tag-decouvrir","tag-police","tag-protection","tag-securite","tag-service"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Policier \u00e0 louer - Louer les services de la police - Protection, surveillance...<\/title>\n<meta name=\"description\" content=\"De la protection rapproch\u00e9e \u00e0 la surveillance lors d\u2019un \u00e9v\u00e9nement, les services des officiers de police am\u00e9ricains peuvent \u00eatre lou\u00e9s aux Etats-Unis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Louer les services d\u2019un policier aux Etats-Unis\" \/>\n<meta property=\"og:description\" content=\"De la protection rapproch\u00e9e \u00e0 la surveillance lors d\u2019un \u00e9v\u00e9nement, les services des officiers de police am\u00e9ricains peuvent \u00eatre lou\u00e9s aux Etats-Unis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/\" \/>\n<meta property=\"og:site_name\" content=\"Washington DC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frenchdistrict\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-02T04:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-24T01:57:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/uploads\/sites\/9\/2020\/07\/louer-services-policier-police-une3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tZaFNBo4R9Yh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:site\" content=\"@frenchdistrict\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"tZaFNBo4R9Yh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/\",\"url\":\"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/\",\"name\":\"Policier \u00e0 louer - Louer les services de la police - Protection, surveillance...\",\"isPartOf\":{\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/uploads\/sites\/9\/2022\/11\/louer-services-policier-police-une3_7365745.jpg\",\"datePublished\":\"2014-04-02T04:00:00+00:00\",\"dateModified\":\"2022-11-24T01:57:40+00:00\",\"author\":{\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010\"},\"description\":\"De la protection rapproch\u00e9e \u00e0 la surveillance lors d\u2019un \u00e9v\u00e9nement, les services des officiers de police am\u00e9ricains peuvent \u00eatre lou\u00e9s aux Etats-Unis.\",\"breadcrumb\":{\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/#primaryimage\",\"url\":\"https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/uploads\/sites\/9\/2022\/11\/louer-services-policier-police-une3_7365745.jpg\",\"contentUrl\":\"https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/uploads\/sites\/9\/2022\/11\/louer-services-policier-police-une3_7365745.jpg\",\"width\":1600,\"height\":1066,\"caption\":\"louer-services-policier-police-une3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Washington D.C.\",\"item\":\"https:\/\/frenchdistrict.com\/washington-dc\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"cupcake\",\"item\":\"https:\/\/frenchdistrict.com\/washington-dc\/tag\/cupcake\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Louer les services d\u2019un policier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/#website\",\"url\":\"https:\/\/frenchdistrict.com\/washington-dc\/\",\"name\":\"Washington DC\",\"description\":\"Le meilleur de la &lt;span&gt;Washington D.C.&lt;\/span&gt; par ceux qui y vivent\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/frenchdistrict.com\/washington-dc\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010\",\"name\":\"tZaFNBo4R9Yh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/frenchdistrict.com\/washington-dc\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g\",\"caption\":\"tZaFNBo4R9Yh\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Policier \u00e0 louer - Louer les services de la police - Protection, surveillance...","description":"De la protection rapproch\u00e9e \u00e0 la surveillance lors d\u2019un \u00e9v\u00e9nement, les services des officiers de police am\u00e9ricains peuvent \u00eatre lou\u00e9s aux Etats-Unis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/","og_locale":"fr_FR","og_type":"article","og_title":"Louer les services d\u2019un policier aux Etats-Unis","og_description":"De la protection rapproch\u00e9e \u00e0 la surveillance lors d\u2019un \u00e9v\u00e9nement, les services des officiers de police am\u00e9ricains peuvent \u00eatre lou\u00e9s aux Etats-Unis.","og_url":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/","og_site_name":"Washington DC","article_publisher":"https:\/\/www.facebook.com\/frenchdistrict","article_published_time":"2014-04-02T04:00:00+00:00","article_modified_time":"2022-11-24T01:57:40+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/uploads\/sites\/9\/2020\/07\/louer-services-policier-police-une3.jpg","type":"image\/jpeg"}],"author":"tZaFNBo4R9Yh","twitter_card":"summary_large_image","twitter_creator":"@frenchdistrict","twitter_site":"@frenchdistrict","twitter_misc":{"\u00c9crit par":"tZaFNBo4R9Yh","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/","url":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/","name":"Policier \u00e0 louer - Louer les services de la police - Protection, surveillance...","isPartOf":{"@id":"https:\/\/frenchdistrict.com\/washington-dc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/#primaryimage"},"image":{"@id":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/#primaryimage"},"thumbnailUrl":"https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/uploads\/sites\/9\/2022\/11\/louer-services-policier-police-une3_7365745.jpg","datePublished":"2014-04-02T04:00:00+00:00","dateModified":"2022-11-24T01:57:40+00:00","author":{"@id":"https:\/\/frenchdistrict.com\/washington-dc\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010"},"description":"De la protection rapproch\u00e9e \u00e0 la surveillance lors d\u2019un \u00e9v\u00e9nement, les services des officiers de police am\u00e9ricains peuvent \u00eatre lou\u00e9s aux Etats-Unis.","breadcrumb":{"@id":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/#primaryimage","url":"https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/uploads\/sites\/9\/2022\/11\/louer-services-policier-police-une3_7365745.jpg","contentUrl":"https:\/\/frenchdistrict.com\/washington-dc\/wp-content\/uploads\/sites\/9\/2022\/11\/louer-services-policier-police-une3_7365745.jpg","width":1600,"height":1066,"caption":"louer-services-policier-police-une3"},{"@type":"BreadcrumbList","@id":"https:\/\/frenchdistrict.com\/washington-dc\/articles\/louer-services-policier-police\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Washington D.C.","item":"https:\/\/frenchdistrict.com\/washington-dc\/"},{"@type":"ListItem","position":2,"name":"cupcake","item":"https:\/\/frenchdistrict.com\/washington-dc\/tag\/cupcake\/"},{"@type":"ListItem","position":3,"name":"Louer les services d\u2019un policier"}]},{"@type":"WebSite","@id":"https:\/\/frenchdistrict.com\/washington-dc\/#website","url":"https:\/\/frenchdistrict.com\/washington-dc\/","name":"Washington DC","description":"Le meilleur de la &lt;span&gt;Washington D.C.&lt;\/span&gt; par ceux qui y vivent","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frenchdistrict.com\/washington-dc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/frenchdistrict.com\/washington-dc\/#\/schema\/person\/ca7493f7cf3c0f3dd252acaa99a10010","name":"tZaFNBo4R9Yh","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frenchdistrict.com\/washington-dc\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5d139838ee2e960f5c78553852d2c0585ef569e33b9c3febd21e71f740396f1?s=96&d=mm&r=g","caption":"tZaFNBo4R9Yh"}}]}},"_links":{"self":[{"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/posts\/17181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/comments?post=17181"}],"version-history":[{"count":4,"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/posts\/17181\/revisions"}],"predecessor-version":[{"id":51156,"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/posts\/17181\/revisions\/51156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/media\/87402"}],"wp:attachment":[{"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/media?parent=17181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/categories?post=17181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/frenchdistrict.com\/washington-dc\/wp-json\/wp\/v2\/tags?post=17181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}